{"id":994717,"date":"2026-05-04T22:04:23","date_gmt":"2026-05-04T22:04:23","guid":{"rendered":"https:\/\/www.europesays.com\/de\/994717\/"},"modified":"2026-05-04T22:04:23","modified_gmt":"2026-05-04T22:04:23","slug":"berlin-experten-widersprechen-cdu-forderung-nach-einschraenkung-der-versammlungsfreiheit","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/994717\/","title":{"rendered":"Berlin: Experten widersprechen CDU-Forderung nach Einschr\u00e4nkung der Versammlungsfreiheit"},"content":{"rendered":"<p data-tts-first-paragraph=\"\" class=\"rich-text expressive-copy-lg-body my-6\">Im Innenausschuss des <a href=\"https:\/\/www.morgenpost.de\/berlin\/abgeordnetenhaus-von-berlin\/\" rel=\"nofollow noopener\" target=\"_blank\">Berliner Abgeordnetenhauses<\/a> wurde am Montag kontrovers \u00fcber das Versammlungsfreiheitsgesetz diskutiert. Hintergrund ist ein wissenschaftlicher Evaluationsbericht zu dem 2021 von Rot-Gr\u00fcn-Rot verabschiedeten Gesetz. Die Wissenschaftler kommen darin zu dem Schluss, dass sich das Gesetz in der Praxis im Wesentlichen bew\u00e4hrt habe. In einigen Punkten sehen sie aber Nachholbedarf.  <\/p>\n<p>    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/411901826_1777916488_v16_9_1200.jpeg\" class=\"relative z-10 block w-full object-cover aspect-[16\/9] md:aspect-[16\/9] lg:aspect-[16\/9]\" alt=\"Vorstellung Polizeiliche Kriminalstatistik in Berlin\" title=\"Innensenatorin Iris Spranger (SPD): \u201eDiesen Generalverdacht weise ich zur\u00fcck.\u201c\" loading=\"lazy\"\/><\/p>\n<p>\n      Innensenatorin Iris Spranger (SPD): \u201eDiesen Generalverdacht weise ich zur\u00fcck.\u201c<br \/>\n      \u00a9 DPA Images | Hannes P Albert\n    <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Innensenatorin <a href=\"https:\/\/www.morgenpost.de\/berlin\/iris-spranger\/\" data-category-full-path=\"https:\/\/www.morgenpost.de\/berlin\/\" data-paid-status=\"free\" data-article-publish-date=\"1639991095\" rel=\"nofollow noopener\" target=\"_blank\">Iris Spranger<\/a> (SPD) trat der ge\u00e4u\u00dferten Kritik entschieden entgegen. So konstruiere der im Bericht enthaltene Vorwurf, die Polizei r\u00e4ume der Gefahrenabwehr zu gro\u00dfen Stellenwert ein und vernachl\u00e4ssige damit den Schutz von Versammlungen, einen Gegensatz, der praktisch nicht zu halten sei. Vielmehr sei die Gew\u00e4hrleistung der Gefahrenabwehr Voraussetzung daf\u00fcr, dass Versammlungen durchgef\u00fchrt werden k\u00f6nnten, so Spranger. Die Senatorin wollte auch nicht gelten lassen, dass die Polizei sich von einem vorgefertigten Freund-Feind-Bild leiten lasse. \u201eDiesen Generalverdacht weise ich zur\u00fcck.\u201c <\/p>\n<p>  Berlin: \u201eUmfangreiche Verbotspraxis\u201c bei propal\u00e4stinensischen Demonstrationen? <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Der SPD-Abgeordnete Martin Matz wunderte sich insbesondere \u00fcber den Teil der Studie, in dem der Umgang mit pal\u00e4stinasolidarischen Protesten untersucht wird. Dass die Studie angesichts von zwei verbotenen Versammlungen seit 2023 von einer \u201eumfangreichen Verbotspraxis\u201c spricht, h\u00e4lt er f\u00fcr \u201eschleierhaft\u201c. <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Sprangers Staatssekret\u00e4r Christian Hochgrebe (SPD) hatte bereits vor der Ver\u00f6ffentlichung des Berichts dessen Wissenschaftlichkeit in Zweifel gezogen. Spranger folgte diesem Urteil am Montag. Es werde an einigen Stellen von Einzelaussagen auf allgemeine Defizite der Polizei geschlossen, sagte sie. Die Studie sei deshalb \u201enicht repr\u00e4sentativ\u201c. Verallgemeinerbare Schl\u00fcsse auf m\u00f6gliche Reformen seien nicht erkennbar. <\/p>\n<p>CDU will \u201e\u00f6ffentliche Ordnung\u201c in den Gesetzestext aufnehmen<\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Die CDU fordert an anderer Stelle durchaus eine grundlegende Reform des Gesetzes. Dabei handelt es sich allerdings nicht um Anpassungen im Sinne des Abbaus von H\u00fcrden bei der Wahrnehmung des Grundrechts. Sondern um dessen Einschr\u00e4nkung. Die Christdemokraten wollen die Kategorie der \u201e\u00f6ffentlichen Ordnung\u201c in den Gesetzestext aufnehmen, um in bestimmten Einzelf\u00e4llen Eingriffe in die Versammlungsfreiheit zu erm\u00f6glichen. Dabei gehe es nicht darum, Mindermeinungen auszuschlie\u00dfen, versicherte Burkhard Dregger (CDU) im Innenausschuss. Sondern um den Schutz der fundamentalen verfassungsm\u00e4\u00dfigen Prinzipien des friedlichen Zusammenlebens. <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">In seiner aktuellen Fassung erm\u00f6glicht das Gesetz nach Paragraf 14 \u00a0die Beschr\u00e4nkung der Versammlungsfreiheit, wenn durch die Versammlung die nationalsozialistische Gewaltherrschaft gebilligt, verherrlicht, gerechtfertigt, geleugnet oder verharmlost wird. Dregger forderte, dass dieser Tatbestand auf die aggressive Propagierung anderer totalit\u00e4rer Regime erweitert werde. Es m\u00fcsse \u201ealles, was uns das Bundesverfassungsgericht an Spielraum gelassen hat\u201c, genutzt werden, um Versammlungen dieser Art zu verhindern, so der CDU-Politiker. <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Als konkrete Beispiele nannte er Autokorsos von Putin-Anh\u00e4ngern am Jahrestag des \u00dcberfalls auf die Ukraine und eine islamistische, frauenfeindliche Demonstration am Gedenkort von Hatun S\u00fcr\u00fcc\u00fc, die 2005 einem sogenannten Ehrenmord zum Opfer fiel.    <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Auch Oliver T\u00f6lle, ehemaliger Justiziar der Berliner Polizei, empfiehlt, die Kategorie der \u00f6ffentlichen Ordnung in den Gesetzestext aufzunehmen. Ohne eine solche Generalklausel sei die Handlungsf\u00e4higkeit der Beh\u00f6rden nicht gew\u00e4hrleistet. T\u00f6lle nannte in diesem Kontext auch das von propal\u00e4stinensischen Demonstranten Anfang April am Alexanderplatz inszenierte H\u00e4ngen am Galgen. Mit diesem Protest hatten sich die Demonstranten gegen eine im israelischen Parlament beschlossene Gesetzesreform gerichtet, die prim\u00e4r f\u00fcr Pal\u00e4stinenser die Todesstrafe f\u00fcr bestimmte terroristische Straftaten erm\u00f6glicht. Nat\u00fcrlich d\u00fcrfe man gegen diese Gesetzesreform protestieren, sagte T\u00f6lle. \u201eAber vielleicht nicht in Formen, die der Allgemeinheit nicht mehr zuzumuten sind.\u201c Um so etwas zu verhindern, brauche es den Begriff der \u00f6ffentlichen Ordnung.   <\/p>\n<p>  Studienautoren: \u201eDemokratietheoretisch bedenkliche Verschiebung\u201c <\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Die Studienautoren empfehlen, Abstand von solchen \u00dcberlegungen zu nehmen. Die Wiedereinf\u00fchrung des Begriffs der \u00f6ffentlichen Ordnung w\u00fcrde Missbrauchsgefahren schaffen, sagen sie. Die CDU-Forderung sei Ausdruck einer \u201ezunehmenden Reizempfindlichkeit gegen\u00fcber provokativen Ausdrucksformen im \u00f6ffentlichen Raum\u201c.<\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Die Wissenschaftler nehmen eine \u201edemokratietheoretisch bedenkliche Verschiebung\u201c wahr: weg von der Absicherung pluralistischer Meinungs\u00e4u\u00dferungen, hin zu einer normativen Kontrolle symbolischer Provokationen. \u201eDer Staat begibt sich hierbei zunehmend in eine paternalistische Rolle, in der er die Gesellschaft vor \u201azumutbaren Zumutungen\u2018 zu sch\u00fctzen beansprucht\u201c, hei\u00dft es in der Studie.<\/p>\n<p>            Morgenpost der Chefredaktion<\/p>\n<p>Die ersten News des Tages \u2013 direkt von der Chefredaktion. Montag bis Samstag um 6:30 Uhr.<\/p>\n<p>            <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/1777901119_491_newsletter-envelope.png\" alt=\"Newsletter Illustration\" class=\"h-full w-full max-w-full object-cover md:max-w-[226px] lg:max-w-[234px]\" loading=\"lazy\"\/><\/p>\n<p>              Morgenpost der Chefredaktion<\/p>\n<p>Die ersten News des Tages \u2013 direkt von der Chefredaktion. Montag bis Samstag um 6:30 Uhr.<\/p>\n<p>              Mit meiner Anmeldung zum Newsletter stimme ich der<br \/>\n              <a href=\"https:\/\/www.morgenpost.de\/service\/newsletter-adconsent\" class=\"text-copy-accent underline decoration-solid underline-offset-1 hover:text-primary-700\" rel=\"nofollow noopener\" target=\"_blank\">Werbevereinbarung<\/a><br \/>\n              zu.<\/p>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Mit der Kategorie der \u201e\u00f6ffentlichen Ordnung\u201c w\u00fcrde au\u00dferdem die Gefahr bestehen, dass die Mehrheitsmeinung in den Stand einer \u201eQuasi-Norm\u201c gehoben werde, argumentiert Hartmut Aden, Professor an der Hochschule f\u00fcr Wirtschaft und Recht (HWR) und einer der Studienautoren. Das w\u00fcrde dem Zentralgedanken der Versammlungsfreiheit zuwiderlaufen. <\/p>\n<blockquote class=\"mx-auto my-10 flex flex-col items-center gap-y-4 text-center md:w-[80%]\">\n<p class=\"rich-text expressive-copy-xl text-copy-primary\">Der Staat begibt sich zunehmend in eine paternalistische Rolle.<\/p>\n<p>       Studienautoren\n    <\/p><\/blockquote>\n<p class=\"rich-text expressive-copy-lg-body my-6\">Zuvor hatte seine Kollegin Daniela Hunold, auch sie HWR-Professorin und Autorin der Studie, bereits der Kritik an der Wissenschaftlichkeit der Studie widersprochen. Die Studie basiere auf Interviews, Teilnehmerbeobachtungen realer Versammlungen und der Analyse von Fallakten der Versammlungsbeh\u00f6rde. Man habe sich dabei bewusst auf Konfliktf\u00e4lle konzentriert, weil Unklarheiten rund um gesetzliche Regelungen nur in solchen Reibungsf\u00e4llen sichtbar w\u00fcrden. Die Studie basiere dar\u00fcber hinaus nicht auf Einzelaussagen, sondern auf einer systematischen Inhaltsanalyse, die wiederkehrende Muster rekonstruiere, so die Professorin.   <\/p>\n","protected":false},"excerpt":{"rendered":"Im Innenausschuss des Berliner Abgeordnetenhauses wurde am Montag kontrovers \u00fcber das Versammlungsfreiheitsgesetz diskutiert. Hintergrund ist ein wissenschaftlicher Evaluationsbericht&hellip;\n","protected":false},"author":2,"featured_media":994718,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[296,29,30],"class_list":{"0":"post-994717","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-berlin","9":"tag-deutschland","10":"tag-germany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116518575897389582","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/994717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=994717"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/994717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/994718"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=994717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=994717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=994717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}