{"id":998005,"date":"2026-05-06T06:19:18","date_gmt":"2026-05-06T06:19:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/998005\/"},"modified":"2026-05-06T06:19:18","modified_gmt":"2026-05-06T06:19:18","slug":"er-scheiterte-offenbar-am-anforderungs-profil-deshalb-schlug-der-fc-bayern-muenchen-im-vergangenen-sommer-einen-angeblichen-wunschtransfer-aus","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/998005\/","title":{"rendered":"Er scheiterte offenbar am Anforderungs-Profil! Deshalb schlug der FC Bayern M\u00fcnchen im vergangenen Sommer einen angeblichen Wunschtransfer aus"},"content":{"rendered":"<dt>Wann wurde der FC Bayern M\u00fcnchen gegr\u00fcndet?<\/dt>\n<dd id=\"faq-accordion-answer-wann-wurde-der-fc-bayern-m\u00fcnchen-gegr\u00fcndet?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Der FC Bayern M\u00fcnchen wurde am 27. Februar 1900 im Schwabinger Caf\u00e9 Gisela gegr\u00fcndet. Gr\u00fcndungsmitglieder waren elf junge M\u00e4nner, angef\u00fchrt vom sp\u00e4teren ersten Pr\u00e4sidenten Franz John. Die Gr\u00fcndung bedeutete die Abspaltung vom MTV M\u00fcnchen.<\/p>\n<\/dd>\n<dt>Wer ist\/sind der\/die Besitzer des FC Bayern M\u00fcnchen?<\/dt>\n<dd id=\"faq-accordion-answer-wer-ist\/sind-der\/die-besitzer-des-fc-bayern-m\u00fcnchen?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>An der FC Bayern M\u00fcnchen AG, die sich insbesondere um die Fu\u00dfballabteilung k\u00fcmmert, h\u00e4lt der eigetragene Verein (eV) des FC Bayern M\u00fcnchen, also die rund 400.000 Mitglieder, mit 75 Prozent den Hauptanteil. Die restlichen 25 Prozent halten die Adidas AG, die Allianz SE und die Audi AG zu gleichen Anteilen (je 8,33 Prozent).<\/p>\n<\/dd>\n<dt>Wie wird das Stadion des FC Bayern M\u00fcnchen genannt?<\/dt>\n<dd id=\"faq-accordion-answer-wie-wird-das-stadion-des-fc-bayern-m\u00fcnchen-genannt?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Das Stadion des FC Bayern M\u00fcnchen befindet sich im Norden der bayerischen Landeshauptstadt (Schwabing-Freimann) und tr\u00e4gt den Namen Allianz Arena.<\/p>\n<\/dd>\n<dt>Wie viele Zuschauer passen in das Stadion des FC Bayern M\u00fcnchen?<\/dt>\n<dd id=\"faq-accordion-answer-wie-viele-zuschauer-passen-in-das-stadion-des-fc-bayern-m\u00fcnchen?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Das Stadion des FC Bayern M\u00fcnchen, die Allianz Arena, bietet bei nationalen Spielen 75.024 Pl\u00e4tze, bei internationalen Ansetzungen 70.000.<\/p>\n<\/dd>\n<dt>Wie viele Titel hat der FC Bayern M\u00fcnchen gewonnen?<\/dt>\n<dd id=\"faq-accordion-answer-wie-viele-titel-hat-der-fc-bayern-m\u00fcnchen-gewonnen?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Der FC Bayern M\u00fcnchen hat in seiner langen Historie eine Vielzahl von nationalen und internationalen Titeln gewonnen. Darunter z\u00e4hlen:<\/p>\n<ul>\n<li>33-mal deutscher Meister (22\/23, 21\/22, 20\/21,\u00a019\/20,\u00a018\/19,\u00a017\/18, 16\/17, 15\/16,\u00a014\/15,\u00a013\/14,\u00a012\/13,\u00a009\/10,\u00a007\/08,\u00a005\/06,\u00a004\/05,\u00a002\/03,\u00a000\/01,\u00a099\/00, 98\/99,\u00a096\/97,\u00a093\/94,\u00a089\/90, 88\/89, 86\/87, 85\/86,\u00a084\/85,\u00a080\/81,\u00a079\/80,\u00a073\/74,\u00a072\/73,\u00a071\/72,\u00a068\/69,\u00a031\/32)<\/li>\n<li>20-mal DFB-Pokal Sieger (19\/20,\u00a018\/19, 15\/16,\u00a013\/14,\u00a012\/13 ,\u00a009\/10,\u00a007\/08,\u00a005\/06,\u00a004\/05, 02\/03, 99\/00,\u00a097\/98, 85\/86,\u00a083\/84, 81\/82,\u00a070\/71,\u00a068\/69,\u00a066\/67,\u00a065\/66,\u00a056\/57)<\/li>\n<li>3-mal Champions League Sieger (19\/20,\u00a012\/13,\u00a000\/01)<\/li>\n<li>3-mal Europapokal der Landesmeister Sieger (75\/76,\u00a074\/75,\u00a073\/74)<\/li>\n<li>2-mal FIFA Klub-WM Sieger (20\/21,\u00a013\/14)<\/li>\n<li>2-mal Weltpokal Sieger (2001 ,\u00a01976)<\/li>\n<li>2-mal UEFA Supercup Sieger (20\/21,\u00a013\/14)<\/li>\n<li>1-mal UEFA Cup Sieger (95\/96)<\/li>\n<li>1-mal Europapokal der Pokalsieger Sieger (66\/67)<\/li>\n<li>10-mal deutscher Superpokalsieger (22\/23,\u00a021\/22,\u00a020\/21,\u00a018\/19,\u00a017\/18,\u00a016\/17,\u00a012\/13,\u00a010\/11,\u00a090\/91,\u00a087\/88)<\/li>\n<li>6-mal deutscher Ligapokalsieger (07\/08,\u00a004\/05,\u00a000\/01,\u00a099\/00, 98\/99,\u00a097\/98)<\/li>\n<li>1-mal s\u00fcddeutscher Pokalsieger (56\/57)<\/li>\n<\/ul>\n<\/dd>\n<dt>Wie viele nationale Meisterschaften hat der FC Bayern M\u00fcnchen gewonnen?<\/dt>\n<dd id=\"faq-accordion-answer-wie-viele-nationale-meisterschaften-hat-der-fc-bayern-m\u00fcnchen-gewonnen?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Der FC Bayern M\u00fcnchen hat 33-mal die deutsche Meisterschaft gewonnen.<\/p>\n<\/dd>\n<dt>Wer hat die meisten Spiele f\u00fcr den FC Bayern M\u00fcnchen absolviert?<\/dt>\n<dd id=\"faq-accordion-answer-wer-hat-die-meisten-spiele-f\u00fcr-den-fc-bayern-m\u00fcnchen-absolviert?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Aktuell h\u00e4lt Thomas M\u00fcller den Rekord f\u00fcr die meisten Eins\u00e4tze f\u00fcr den FC Bayern M\u00fcnchen. M\u00fcller absolvierte bislang 746 Pflichtspiele f\u00fcr den FCB.<\/p>\n<\/dd>\n<dt>Wer ist der beste Torsch\u00fctze in der Geschichte des FC Bayern M\u00fcnchen?<\/dt>\n<dd id=\"faq-accordion-answer-wer-ist-der-beste-torsch\u00fctze-in-der-geschichte-des-fc-bayern-m\u00fcnchen?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Die meisten Tore f\u00fcr den FC Bayern M\u00fcnchen hat Gerd M\u00fcller geschossen. Die mittlerweile verstorbene Vereinslegende traf 570-mal im Dress des deutschen Rekordmeisters. Daf\u00fcr brauchte er 613 Spiele.<\/p>\n<\/dd>\n<dt>Welche ber\u00fchmten Stars haben f\u00fcr den FC Bayern M\u00fcnchen gespielt?<\/dt>\n<dd id=\"faq-accordion-answer-welche-ber\u00fchmten-stars-haben-f\u00fcr-den-fc-bayern-m\u00fcnchen-gespielt?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>F\u00fcr den FC Bayern M\u00fcnchen spielten eine Vielzahl an legend\u00e4ren Fu\u00dfballern. Folgende Spieler trugen allesamt das Trikot des FCB:<\/p>\n<p>Oliver Kahn, Sepp Maier, Manuel Neuer, Franz Beckenbauer, Paul Breitner, Klaus Augenthaler, Philipp Lahm, David Alaba, Bixente Lizarazu, L\u00facio, Georg &#8222;Katsche&#8220; Schwarzenbeck, Stefan Effenberg, Michael Ballack, Bastian Schweinsteiger, Lothar Matth\u00e4us, Franz &#8222;Bulle&#8220; Roth, Joshua Kimmich, Xabi Alonso, Franck Rib\u00e9ry, Arjen Robben, Jamal Musiala, Mehmet Scholl, Uli Hoene\u00df, Gerd M\u00fcller, Karl-Heinz Rummenigge, Giovane \u00c9lber, Robert Lewandowski, Thomas M\u00fcller und Claudio Pizarro.<\/p>\n<\/dd>\n<dt>Welche ber\u00fchmten Trainer hatte der FC Bayern M\u00fcnchen? <\/dt>\n<dd id=\"faq-accordion-answer-welche-ber\u00fchmten-trainer-hatte-der-fc-bayern-m\u00fcnchen?-\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Beim FC Bayern M\u00fcnchen standen in der Geschichte viele ber\u00fchmte und erfolgreiche Trainer an der Seitenlinie. Dazu geh\u00f6ren:<\/p>\n<p>Zlatko &#8222;Tschik&#8220; Cajkovski, Udo Lattek, Dettmar Cramer, Jupp Heynckes, Erich Ribbeck, Franz Beckenbauer, Giovanni Trapattoni, Otto Rehhagel, Ottmar Hitzfeld, Felix Magath, J\u00fcrgen Klinsmann, Louis van Gaal, Pep Guardiola, Carlo Ancelotti, Hansi Flick und Thomas Tuchel.<\/p>\n<\/dd>\n<dt>Wie lautet der Spitzname des FC Bayern M\u00fcnchen?<\/dt>\n<dd id=\"faq-accordion-answer-wie-lautet-der-spitzname-des-fc-bayern-m\u00fcnchen?\" class=\"fco-faq-accordion-item__answer\" style=\"--answer-height:0px\">\n<p>Der Spitzname des FC Bayern M\u00fcnchen nimmt Bezug auf die Vereinsfarben. So werden die Spieler des deutschen Rekordmeisters meist nur &#8222;die Roten&#8220; genannt. <\/p>\n<p>Dar\u00fcber hinaus ist auch der Begriff &#8222;FC Hollywood&#8220; gebr\u00e4uchlich, welchen der ehemalige Trainer Giovanni Trapattoni pr\u00e4gte. Der Spitzname bezieht sich auf eine turbulente Zeit des Vereins w\u00e4hrend der 90er-Jahre, als es zwischen einigen hochrangigen Spielern und Funktion\u00e4ren des Klubs zu Auseinandersetzungen kam &#8211; \u00e4hnlich wie in einer t\u00e4glichen Seifenoper.<\/p>\n<\/dd>\n","protected":false},"excerpt":{"rendered":"Wann wurde der FC Bayern M\u00fcnchen gegr\u00fcndet? Der FC Bayern M\u00fcnchen wurde am 27. Februar 1900 im Schwabinger&hellip;\n","protected":false},"author":2,"featured_media":998006,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1827],"tags":[32636,772,923,58212,299,29,30,348,19172,1268,60900,1288],"class_list":{"0":"post-998005","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-muenchen","8":"tag-athletic-bilbao","9":"tag-bayern","10":"tag-bayern-muenchen","11":"tag-bayern-munich","12":"tag-bundesliga","13":"tag-deutschland","14":"tag-germany","15":"tag-la-liga","16":"tag-laliga","17":"tag-muenchen","18":"tag-n-williams","19":"tag-transfers"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116526184463338593","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/998005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=998005"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/998005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/998006"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=998005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=998005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=998005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}