{"id":152888,"count":1,"description":"","link":"https:\/\/www.europesays.com\/de\/tag\/rekordausgabe\/","name":"Rekordausgabe","slug":"rekordausgabe","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags\/152888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts?tags=152888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}