{"id":79699,"count":1,"description":"","link":"https:\/\/www.europesays.com\/ee\/tag\/rahvusvaheline-odede-paev\/","name":"rahvusvaheline \u00f5dede p\u00e4ev","slug":"rahvusvaheline-odede-paev","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ee\/wp-json\/wp\/v2\/tags\/79699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ee\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/ee\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/ee\/wp-json\/wp\/v2\/posts?tags=79699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}