{"id":282962,"date":"2025-12-11T14:24:20","date_gmt":"2025-12-11T14:24:20","guid":{"rendered":"https:\/\/www.europesays.com\/es\/282962\/"},"modified":"2025-12-11T14:24:20","modified_gmt":"2025-12-11T14:24:20","slug":"james-cameron-y-mi-abuelo-unen-al-mundo-con-sus-peliculas","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/282962\/","title":{"rendered":"\u201cJames Cameron y mi abuelo unen al mundo con sus pel\u00edculas\u201d"},"content":{"rendered":"<p class=\"article-text\">\n        Oona Chaplin lleva la interpretaci\u00f3n en los genes. O, al menos, una educaci\u00f3n en la que la cultura, y el cine, son importantes. Su abuelo era, ni m\u00e1s ni menos, que <a href=\"https:\/\/www.eldiario.es\/cultura\/cine\/chaplin-cine-sonrisas-lagrimas-toque-social-comenzo-chico_1_7188903.html\" data-mrf-recirculation=\"links-noticia\" class=\"link\" rel=\"nofollow noopener\" target=\"_blank\">Charles Chaplin,<\/a> uno de los cineastas m\u00e1s importantes de la historia. Un creador \u00fanico, capaz de unir sensibilidades, de alzar la voz cuando tocaba, de emocionar hasta la l\u00e1grima y hacer re\u00edr hasta la carcajada. Para el recuerdo dej\u00f3 obras maestras que siguen interpel\u00e1ndonos como si se hubieran rodado ayer: El gran dictador, La quimera del oro, Tiempos modernos\u2026 El gen art\u00edstico tambi\u00e9n est\u00e1n en su madre, esa Geraldine Chaplin que nos emocion\u00f3 en las pel\u00edculas <a href=\"https:\/\/www.eldiario.es\/cultura\/cine\/muere-carlos-saura-director-fundamental-historia-cine-espanol-91-anos_1_9794529.html\" data-mrf-recirculation=\"links-noticia\" class=\"link\" rel=\"nofollow noopener\" target=\"_blank\">de Carlos Saura<\/a> como Cr\u00eda Cuervos y en los filmes de Juan Antonio Bayona.\u00a0\n    <\/p>\n<p>    <a href=\"https:\/\/www.eldiario.es\/cultura\/cine\/james-cameron-rey-mundo-cine-regresa-avatar-habla-refugiados-migrantes_1_12824407.html\" data-mrf-recirculation=\"saber-mas\" data-dl-event=\"saber-mas\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p class=\"know-more__title\">James Cameron, el \u2018rey del mundo\u2019 del cine regresa: \u201c\u2018Avatar\u2019 habla de los refugiados, de los migrantes\u00bb<\/p>\n<p>            <img decoding=\"async\" class=\"lazy\" loading=\"lazy\" data-src=\"https:\/\/static.eldiario.es\/clip\/c641b9ac-d4ff-46fd-9350-a0ac3707fa49_16-9-aspect-ratio_default_0.jpg\" src=\"data:image\/svg+xml,%3Csvg xmlns=\" http:=\"\" viewbox=\"0 0 880 495\" alt=\"James Cameron, el \u2018rey del mundo\u2019 del cine regresa: \u201c\u2018Avatar\u2019 habla de los refugiados, de los migrantes&quot;\"\/><\/p>\n<p>                        <\/a><\/p>\n<p class=\"article-text\">\n        Para ella, hay algo de su abuelo <a href=\"https:\/\/www.eldiario.es\/cultura\/cine\/james-cameron-rey-mundo-cine-regresa-avatar-habla-refugiados-migrantes_1_12824407.html\" data-mrf-recirculation=\"links-noticia\" class=\"link\" rel=\"nofollow noopener\" target=\"_blank\">en James Cameron,<\/a> con quien ha trabajado en Avatar: Fuego y cenizas, en la que da vida a la temible villana Varang. Esa capacidad de que la gente se quede con la boca abierta delante de una pantalla, de crear una ceremonia com\u00fan en torno a una pel\u00edcula. Todo en un momento donde, adem\u00e1s, con la posible <a href=\"https:\/\/www.eldiario.es\/economia\/paramount-lanzado-opa-hostil-warner-bros-discovery-pasara-ahora-oferta-netflix_1_12829729.html\" data-mrf-recirculation=\"links-noticia\" class=\"link\" rel=\"nofollow noopener\" target=\"_blank\">compra de Warner por Netflix<\/a>, las salas parecen estar m\u00e1s amenazadas que nunca. Para Chaplin no hay duda, \u201ccon Avatar, James Cameron ha unido el mundo\u201d.\n    <\/p>\n<p class=\"article-text\">\n        \u201cHa creado una uni\u00f3n en el mundo de personas de todas las edades, de todas las inclinaciones pol\u00edticas, de todas las culturas, de todas las religiones. Nos ha metido en las salas del cine como una sola conciencia. Nos hemos vuelto todos azules. Es incre\u00edble el regalo de poder compartir esta experiencia con gente que sabes que est\u00e1 al otro lado\u201d, opina, y lo vincula con lo que tambi\u00e9n hac\u00eda Charlie Chaplin. \u201cMi abuelo era el otro gran unificador del mundo. Mi abuelo nos hizo llorar y re\u00edr juntos y sentir juntos de una forma que nadie jam\u00e1s lo volver\u00e1 a hacer as\u00ed. Porque adem\u00e1s era \u00e9l quien interpretaba, el que lo escrib\u00eda, compon\u00eda la m\u00fasica\u2026 Es el gran contador de historias de la historia humana. O al menos por lo que yo he podido experimentar\u201d, apunta la actriz, a la que muchos espectadores descubrieron en Juego de Tronos.\n    <\/p>\n<p class=\"article-text\">\n        No sabe si el arte va en los genes, pero confiesa que, cuando ve a su hija, que tiene poco m\u00e1s de dos a\u00f1os, de repente la ve \u201cmoverse como Chaplin\u201d. \u201cTiene una gracia de movimientos, algo que es muy \u00fanico y que yo lo veo con mi madre, lo veo con mi prima, mi t\u00eda Jane, mi t\u00eda Annie. Mi primo James. Hay algunos que lo tienen, y otros que no se mueven como Chaplin. Pero ella se mueve como yo. Creo que hay algo en los genes, pero tambi\u00e9n la cultura. Porque al final son los padres y el ambiente de los padres, el ambiente de la casa, lo que es importante. Ah\u00ed es donde va tu atenci\u00f3n y tu energ\u00eda. Los hijos aprendemos de eso\u201d, dice la actriz.\n    <\/p>\n<p>    Un alma hermosa<\/p>\n<p class=\"article-text\">\n        En la rueda de prensa de la pel\u00edcula en Par\u00eds, James Cameron dijo que Oona Chaplin era una de las almas m\u00e1s hermosas que hab\u00eda conocido, a pesar de que interpretaba a una villana despiadada. Cuando le recuerdan a la actriz esas palabras se emociona y le cuesta decir algo. \u201cEs que es muy buena persona\u201d, acierta a pronunciar sobre el cineasta, que \u201cinspira lo mejor\u201d de ella. \u201cCuando estamos juntos yo soy la mejor versi\u00f3n de m\u00ed misma. Porque \u00e9l me la saca, me inspira\u201d, a\u00f1ade.\n    <\/p>\n<p class=\"article-text\">\n        Rompe con la imagen que durante muchos a\u00f1os se ha tenido de \u00e9l de cineasta serio y estricto en los rodajes. Al rev\u00e9s, le define como \u201cjuguet\u00f3n, generoso y curioso\u201d. \u201cEs un l\u00edder, tiene mil preguntas, le encanta saber c\u00f3mo funcionan las cosas, el ser humano, la biolog\u00eda, la tecnolog\u00eda\u2026 es que se construy\u00f3 un submarino para ir al fondo del mar porque quer\u00eda saber c\u00f3mo era. Es un genio de otra categor\u00eda. Trabajar con \u00e9l saca esa curiosidad y esa determinaci\u00f3n para intentar responder a esas preguntas, y si no podemos, al menos son buenas preguntas para hacernos\u201d, remata.\n    <\/p>\n<p class=\"article-text\">\n        La prueba para Avatar le lleg\u00f3 cuando se encontraba viviendo en una casa en la selva cubana construida por ella misma. \u201cHab\u00eda muy pocas cosas que me hubieran sacado de esa caba\u00f1ita\u2026 yo estaba en un proceso muy profundo, pero esa llamada de Avatar s\u00ed que me sac\u00f3 de las trenzas y me fui para Los \u00c1ngeles. Lo dej\u00e9 todo. La primera pel\u00edcula me impact\u00f3 mucho\u201d, recuerda. Uno de los motivos de que dijera que s\u00ed, y tambi\u00e9n de que la primera le impresionara tanto, es que debajo de su capa de taquillazo se abordan temas importantes: \u201cPor supuesto, es que esto no es solo un blockbuster. Es una historia que a m\u00ed me importa. Y no hay regalo mayor para m\u00ed como actriz, como artista, que contar una historia que me importa\u201d.\n    <\/p>\n<p class=\"article-text\">\n        Ahora que ha salido de esa caba\u00f1a surge la pregunta que todav\u00eda no se ha respondido. Volver a la industria o seguir en su retiro, que ahora se encuentra en una granja, donde vive con varias familias en comunidad: \u201cEstamos sembrando nuestro jard\u00edn de Pandora en el norte de California, con muchos hijos que son salvajes\u201d. Es como si Cameron supiera que ella ten\u00eda el esp\u00edritu de sus personajes dentro. Poco a poco se fue enterando de que los v\u00ednculos entre persona y personaje eran fuertes.\n    <\/p>\n<p>    <a href=\"https:\/\/www.eldiario.es\/cultura\/musica\/fans-rosalia-quejan-caos-preventa-lux-tour-concierto-odisea_1_12830127.html\" data-mrf-recirculation=\"saber-mas-abajo\" data-dl-event=\"saber-mas-abajo\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p class=\"know-more__title\">Los fans de Rosal\u00eda se quejan del caos en la preventa de entradas del \u2018Lux Tour\u2019: \u201cIr a cualquier concierto es una odisea\u201d<\/p>\n<p>            <img decoding=\"async\" class=\"lazy\" loading=\"lazy\" data-src=\"https:\/\/static.eldiario.es\/clip\/04c58b22-eca2-4813-acde-fc917716c71c_16-9-aspect-ratio_default_0.jpg\" src=\"data:image\/svg+xml,%3Csvg xmlns=\" http:=\"\" viewbox=\"0 0 880 495\" alt=\"Los fans de Rosal\u00eda se quejan del caos en la preventa de entradas del \u2018Lux Tour\u2019: \u201cIr a cualquier concierto es una odisea\u201d\"\/><\/p>\n<p>                        <\/a><\/p>\n<p class=\"article-text\">\n        Oona Chaplin trabaja desde hace 15 a\u00f1os con tribus ind\u00edgenas y tiene relaci\u00f3n con \u201cm\u00e1s de 60 ancianos de diferentes culturas alrededor del mundo\u201d. A algunos de sus amigos les llev\u00f3 al set, y hasta organizaron una ceremonia para bendecir el rodaje con una ceremonia de humo e incienso donde particip\u00f3 \u201cdesde Kate Winslet hasta el \u00faltimo trabajador que organizaba el reciclaje\u201d. Fue, para ella, \u201cuno de los grandes regalos de Avatar\u201d, un proyecto que se ha entrelazado con su vida de una forma que no esperaba.\n    <\/p>\n","protected":false},"excerpt":{"rendered":"Oona Chaplin lleva la interpretaci\u00f3n en los genes. O, al menos, una educaci\u00f3n en la que la cultura,&hellip;\n","protected":false},"author":2,"featured_media":282963,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[17982,181,3702,68440,146,147,25,24,2501,13783,3013,43395,753,23,12047,60090],"class_list":{"0":"post-282962","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entretenimiento","8":"tag-abuelo","9":"tag-avatar","10":"tag-cameron","11":"tag-chaplin","12":"tag-entertainment","13":"tag-entretenimiento","14":"tag-es","15":"tag-espana","16":"tag-espanola","17":"tag-james","18":"tag-mundo","19":"tag-nieta","20":"tag-peliculas","21":"tag-spain","22":"tag-unen","23":"tag-villana"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115701393985728386","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/282962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=282962"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/282962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/282963"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=282962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=282962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=282962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}