{"id":289992,"date":"2025-12-15T19:31:11","date_gmt":"2025-12-15T19:31:11","guid":{"rendered":"https:\/\/www.europesays.com\/es\/289992\/"},"modified":"2025-12-15T19:31:11","modified_gmt":"2025-12-15T19:31:11","slug":"noora-louhimo-abandona-battle-beast","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/289992\/","title":{"rendered":"Noora Louhimo abandona BATTLE BEAST"},"content":{"rendered":"<p>\u00a0<\/p>\n<p><strong>Noora Louhimo<\/strong> <strong>abandona BATTLE BEAST<\/strong><br \/>\n<img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/12\/battle_beast_barna2025_1_500x267.jpg\" alt=\"B BEAST\" width=\"500\" height=\"267\"\/><\/p>\n<p>La cantante de <a href=\"https:\/\/battlebeast.fi\/\" target=\"_blank\" rel=\"noopener nofollow\"><strong>BATTLE BEAST<\/strong><\/a> <strong>Noora Louhimo<\/strong> ha abandonado la banda para centrarse en su carrera en solitario.<\/p>\n<p>La separaci\u00f3n se ha realizado de forma amistosa y ma\u00f1ana 16 de diciembre revelar\u00e1n el nombre de su sustituta.<\/p>\n<p><a href=\"https:\/\/battlebeast.fi\/\" target=\"_blank\" rel=\"noopener nofollow\"><strong>BATTLE BEAST<\/strong><\/a> dicen:<\/p>\n<p>\u00abTras seis \u00e1lbumes y 13 a\u00f1os juntos, anunciamos que Noora Louhimo deja BATTLE BEAST para centrarse en su carrera en solitario. Aunque nos entristece su marcha, apoyamos totalmente su decisi\u00f3n de tomar nuevos caminos, algo que no ha podido hacer debido a la exigente agenda de BATTLE BEAST.<\/p>\n<p>Noora comenta:<\/p>\n<p>\u00abDurante 13 a\u00f1os he crecido, he aprendido, y me desarrollado con BATTLE BEAST como m\u00fasico y como persona. Y ahora mi coraz\u00f3n necesita aventuras y volar hacia mis sue\u00f1os, que solo puedo conseguir si me centro en ellos. La vida est\u00e1 llena de diferentes etapas y ahora es el momento de una nueva. Siempre estar\u00e9 agradecida y amar\u00e9 a BATTLE BEAST y a nuestros fans. Esto no es el final, es el comienzo de una nueva aventura para ambos. \u00a1Nos vemos pronto, Little Beasts!\u00bb<\/p>\n<p><a href=\"https:\/\/battlebeast.fi\/\" target=\"_blank\" rel=\"noopener nofollow\"><strong>BATTLE BEAST<\/strong><\/a> editaron el 17 de octubre a trav\u00e9s de Nuclear Blast un nuevo disco titulado \u201cSteelbound\u201d.<\/p>\n<p>Todos los detalles en este <a href=\"https:\/\/www.rafabasa.com\/2025\/10\/17\/kiss-battle-beast-blood-incantation\/#BATTLE_BEAST\" rel=\"nofollow noopener\" target=\"_blank\">bloque<\/a> y su \u00faltimo single en <a href=\"https:\/\/www.rafabasa.com\/2025\/11\/18\/battle-beast-tyketto-aneuma\/#BB\" rel=\"nofollow noopener\" target=\"_blank\">este<\/a>.<\/p>\n<p>Nuestra cr\u00f3nica de su concierto en Barcelona en este <a href=\"https:\/\/www.rafabasa.com\/2025\/11\/05\/cronica-y-fotos-de-battle-beast-dominum-majestica-en-barcelona\/\" rel=\"nofollow noopener\" target=\"_blank\">enlace<\/a>.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p align=\"center\"><strong>Sigue el\u00a0<a href=\"https:\/\/whatsapp.com\/channel\/0029VaCprxVBA1f555USvT2O\" target=\"_blank\" rel=\"nofollow noopener\">Canal de RAFABASA.COM en WhatsApp<\/a>, donde encontrar\u00e1s todas nuestras novedades al instante<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"\u00a0 Noora Louhimo abandona BATTLE BEAST La cantante de BATTLE BEAST Noora Louhimo ha abandonado la banda para&hellip;\n","protected":false},"author":2,"featured_media":220388,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[170],"tags":[33867,146,147,25,24,184,185,69616,23],"class_list":{"0":"post-289992","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musica","8":"tag-battle-beast","9":"tag-entertainment","10":"tag-entretenimiento","11":"tag-es","12":"tag-espana","13":"tag-music","14":"tag-musica","15":"tag-noora-louhimo","16":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115725250974847396","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/289992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=289992"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/289992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/220388"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=289992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=289992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=289992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}