{"id":328906,"date":"2026-01-08T03:32:13","date_gmt":"2026-01-08T03:32:13","guid":{"rendered":"https:\/\/www.europesays.com\/es\/328906\/"},"modified":"2026-01-08T03:32:13","modified_gmt":"2026-01-08T03:32:13","slug":"ee-uu-da-un-giro-en-el-caso-contra-maduro-y-ya-no-se-enfoca-en-el-cartel-de-los-soles","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/328906\/","title":{"rendered":"EE.UU. da un giro en el caso contra Maduro y ya no se enfoca en el \u201cCartel de los Soles\u201d"},"content":{"rendered":"<p textalign=\"left\" class=\"\">\u201cLa idea de que el Cartel de los Soles es una organizaci\u00f3n terrorista unificada es en gran medida una construcci\u00f3n occidental. Ha circulado no porque refleje una realidad emp\u00edrica, sino porque ofrece utilidad geopol\u00edtica: crea una justificaci\u00f3n lista para la intervenci\u00f3n\u201d, indic\u00f3 Jenaro Abraham, polit\u00f3logo y profesor de pol\u00edtica latinoamericana en la Universidad de Gonzaga, a TRT World.<\/p>\n<p textalign=\"left\" class=\"\">Y la acusaci\u00f3n de Estados Unidos parece hacer tambi\u00e9n esta concesi\u00f3n.<\/p>\n<p textalign=\"left\" class=\"\">Mientras que el escrito original mencionaba al Cartel de los Soles m\u00e1s de 30 veces y se\u00f1alaba a Maduro como su l\u00edder, la nueva versi\u00f3n solo alude al t\u00e9rmino en dos ocasiones. Adem\u00e1s, a\u00f1ade que los acusados habr\u00edan convertido a Venezuela en un narcoestado, utilizando el poder del gobierno para proteger y facilitar env\u00edos masivos de coca\u00edna con destino a Estados Unidos.<\/p>\n<p textalign=\"left\" class=\"\">\u201cPresuntamente colaboraron con organizaciones terroristas extranjeras designadas, entre ellas las FARC (y sus sucesores), el ELN, el Cartel de Sinaloa, Los Zetas\/CDN y el Tren de Aragua, brindando protecci\u00f3n y apoyo a cambio de beneficios\u201d, se\u00f1ala la acusaci\u00f3n.<\/p>\n<p textalign=\"left\" class=\"\">Tambi\u00e9n afirma que Maduro, al igual que su predecesor, el expresidente Hugo Ch\u00e1vez, particip\u00f3 y protegi\u00f3 un sistema de patronazgo. La narrativa de Washington creci\u00f3 durante meses, pese a que Caracas neg\u00f3 esas acusaciones una y otra vez, destacando adem\u00e1s que Washington no aportaba ning\u00fan tipo de pruebas.<\/p>\n<p textalign=\"left\" class=\"\">Entonces, \u00bfde qu\u00e9 se le acusa ahora a Maduro? En la acusaci\u00f3n se imputan cuatro cargos: conspiraci\u00f3n para cometer \u201cnarcoterrorismo\u201d, conspiraci\u00f3n para importar coca\u00edna, posesi\u00f3n de ametralladoras y dispositivos destructivos, y conspiraci\u00f3n para poseer ametralladoras y dispositivos destructivos. Maduro se ha declarado inocente de todos los cargos.<\/p>\n<p textalign=\"left\" class=\"\">Con todo, el \u201cCartel de los Soles\u201d ya no figura como cargo oficial en la acusaci\u00f3n, pese a haber sido la justificaci\u00f3n m\u00e1s utilizada por Estados Unidos para sus operaciones en Venezuela: un giro en la estrategia legal estadounidense, que ahora deja de apoyarse en uno de los elementos m\u00e1s medi\u00e1ticos de su pol\u00edtica contra Maduro.<\/p>\n<p><a data-link-preview=\"\" href=\"https:\/\/www.trtespanol.com\/article\/9d0887c3884b\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" dir=\"ltr\" class=\"relative flex w-full px-4 py-3 flex-col items-start gap-6 rounded bg-[#F1F1F1] border-l-0 transition-all duration-200 ease-in-out box-border mb-4 hover:bg-[#F9F9F9] hover:shadow-[0_4px_6px_-1px_rgba(0,0,0,0.1),0_-4px_6px_-1px_rgba(0,0,0,0.06),4px_0_6px_-1px_rgba(0,0,0,0.06)] focus:bg-[#F9F9F9] focus:shadow-[0_4px_6px_-1px_rgba(0,0,0,0.1),0_-4px_6px_-1px_rgba(0,0,0,0.06),4px_0_6px_-1px_rgba(0,0,0,0.06)] before:content-[&quot;&quot;] before:absolute before:left-0 before:top-0 before:bottom-0 before:w-[3px] before:rounded-l-md before:bg-[#01ABD9]\"><img decoding=\"async\" class=\"flex justify-center items-center rounded-md !w-20 !h-20 aspect-square flex-shrink-0 sm:rounded md:rounded-md lg:!w-[84px] lg:!h-[84px] lg:rounded xl:rounded-md\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/bfb761a6037be96e24f2d612270aa29b21c0601609c483520432a95e1b7303db.JPG\"\/><\/p>\n<p>Relacionado<\/p>\n<p><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"\u201cLa idea de que el Cartel de los Soles es una organizaci\u00f3n terrorista unificada es en gran medida&hellip;\n","protected":false},"author":2,"featured_media":328907,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[17,18,13,14,11,61,62,63,64,19,20,9,10,15,16,12,21,22,65,66,67],"class_list":{"0":"post-328906","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-internacional","14":"tag-international","15":"tag-international-news","16":"tag-internationalnews","17":"tag-latest-news","18":"tag-latestnews","19":"tag-news","20":"tag-noticias","21":"tag-noticias-destacadas","22":"tag-noticiasdestacadas","23":"tag-titulares","24":"tag-ultimas-noticias","25":"tag-ultimasnoticias","26":"tag-world","27":"tag-world-news","28":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115857374784578660","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/328906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=328906"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/328906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/328907"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=328906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=328906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=328906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}