{"id":337034,"date":"2026-01-12T16:08:12","date_gmt":"2026-01-12T16:08:12","guid":{"rendered":"https:\/\/www.europesays.com\/es\/337034\/"},"modified":"2026-01-12T16:08:12","modified_gmt":"2026-01-12T16:08:12","slug":"el-arquitecto-japones-tadao-ando-y-la-disenadora-francesa-andree-putman","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/337034\/","title":{"rendered":"el arquitecto japon\u00e9s Tadao Ando y la dise\u00f1adora francesa Andr\u00e9e Putman"},"content":{"rendered":"<p data-journey-content=\"true\" data-node-id=\"2\" class=\"body-dropcap css-z34acw emevuu60\">Est\u00e1 en el coraz\u00f3n de Par\u00eds y su entorno posee una combinaci\u00f3n perfecta entre naturaleza y arte que ha marcado su personalidad. Situada muy cerca del Bosque de Boulogne y de la Fundaci\u00f3n de Arte Louis Vuitton, uno de <a href=\"https:\/\/www.elledecor.com\/es\/arte\/a41049800\/ruta-galerias-arte-paris\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/arte\/a41049800\/ruta-galerias-arte-paris\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"los museos m\u00e1s bonitos de Par\u00eds\" data-node-id=\"2.1\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">los museos m\u00e1s bonitos de Par\u00eds<\/a>, esta vivienda nos muestra un dise\u00f1o que mira a su alrededor y, a su vez, <strong data-node-id=\"2.3\">bebe de fuentes japonesas que transmiten una calma so\u00f1ada<\/strong>. Obra de <strong data-node-id=\"2.5\">los arquitectos y dise\u00f1adores franceses Samantha Hauvette y Lucas Madani, del estudio Hauvette &amp; Madani<\/strong>, sus espacios exploran un refinado equilibrio entre su arquitectura, el dise\u00f1o interior y el paisaje circundante: \u00abEl proyecto se basa en una doble l\u00ednea de referencias. Por un lado se inspira en <strong data-node-id=\"2.7\">el minimalismo arquitect\u00f3nico del japon\u00e9s Tadao Ando<\/strong>, que marca la distribuci\u00f3n di\u00e1fana y la relaci\u00f3n fluida entre interiores y exteriores; y por otro, en <strong data-node-id=\"2.9\"><a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/g34736994\/andree-putman-disenadora-decoradora\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/g34736994\/andree-putman-disenadora-decoradora\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"Andr\u00e9e Putman\" data-node-id=\"2.9.0\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">Andr\u00e9e Putman<\/a><\/strong>, que define las l\u00edneas limpias y los detalles cuidadosamente calibrados\u00bb.<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1600\" height=\"1200\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/terraza-hauvette-madani-interioristas-6960d6b5907ae.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1600\" height=\"1200\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/terraaza-japones-hauvette-madani-interioristas-6960d6b57d8ec.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p data-journey-content=\"true\" data-node-id=\"7\" class=\"css-6wxqfj emevuu60\">La filosof\u00eda en la obra del <strong data-node-id=\"7.1\"><a href=\"https:\/\/www.elledecor.com\/es\/arquitectura\/a44997672\/libro-tadao-ando-arquitectura-hormigon-luz-formas-naturales\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/arquitectura\/a44997672\/libro-tadao-ando-arquitectura-hormigon-luz-formas-naturales\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"arquitecto japon\u00e9s Tadao Ando\" data-node-id=\"7.1.0\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">arquitecto japon\u00e9s Tadao Ando<\/a><\/strong>, que busca el estilo<strong data-node-id=\"7.3\"> mon\u00e1stico, los planos limpios y la luz,<\/strong> inspir\u00f3 la distribuci\u00f3n di\u00e1fana del proyecto: \u00abPensamos en una serie de perspectivas claras y espacios abiertos que fomentan un estilo de vida tranquilo y consciente, en el que la sensibilidad japonesa se integra sutilmente en la vida cotidiana\u00bb, comentan los autores. <strong data-node-id=\"7.5\">La casa cuenta con tres niveles y se abre a<\/strong><strong data-node-id=\"7.6\"><a href=\"https:\/\/www.elledecor.com\/es\/arquitectura\/a37304195\/pabellon-camino-agua-tokio-jardines-hamarikyu-kazujo-sejima\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/arquitectura\/a37304195\/pabellon-camino-agua-tokio-jardines-hamarikyu-kazujo-sejima\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\" un jard\u00edn de inspiraci\u00f3n japonesa\" data-node-id=\"7.6.0\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\"> un jard\u00edn de inspiraci\u00f3n japonesa<\/a><\/strong> que ampl\u00eda visual y espacialmente los vol\u00famenes interiores. Dentro, la madera es protagonista y da unidad a su visi\u00f3n hol\u00edstica, mientras que otros elementos como la piedra verde en la cocina, los tejidos de terciopelo y <strong data-node-id=\"7.8\">la obras de arte de la Galerie Gastou <\/strong>proponen un punto de contraste.<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"900\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/salon-sofas-hauvette-madani-interioristas-6960d6b14969c.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/hauvette-madani-interioristas-chimenea-6960d6ac5b5a5.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/butacas-cortinas-hauvette-madani-interioristas-6960d6ac5bde5.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/comedor-vegetacion-hauvette-madani-interioristas-6960d6b0f2ce8.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/cocina-verde-madera-hauvette-madani-interioristas-6960d6ac58d72.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p>Adem\u00e1s, en sus interiores destaca la cuidada lista de muebles hechos a medida de <strong data-node-id=\"16\">la colecci\u00f3n \u00abEntremets\u00bb<\/strong> \u2014que incluye un sill\u00f3n, una l\u00e1mpara de pie, una mesa y un sof\u00e1\u2014 dise\u00f1ados por los arquitectos Hauvette &amp; Madani: <strong data-node-id=\"18\">\u00abLos muebles articulan el espacio con claridad, calidez y moderaci\u00f3n\u00bb<\/strong>.  Y en este sentido, la fuente de inspiraci\u00f3n para ellos fue la dise\u00f1adora e interiorista francesa Andr\u00e9e Putman. Sus espacios, alejados del exceso y la ostentaci\u00f3n, buscaban la elegancia en las ausencias, en las estructuras depuradas  y en la mezcla de materiales ricos y pobres, de ayer y de hoy. Y en esta vivienda, los dise\u00f1adores tomaron en cuenta este gui\u00f3n para dar con espacios en calma que hablan del <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/a44013849\/lujo-silencioso-tendencia-decoracion\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/a44013849\/lujo-silencioso-tendencia-decoracion\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"lujo silencioso\" data-node-id=\"20\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">lujo silencioso<\/a>.<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una escalera enmoquetada con un estampado de rombos blanco y negro\" loading=\"lazy\" width=\"2250\" height=\"3000\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/hauvette-madani-bagatelle-08atmatthewavignone-6960f7796a1c6.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/dormitorio-cabecero-espejo-hauvette-madani-interioristas-6960d6abd80bb.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/dormitorio-lavabo-hauvette-madani-interioristas-6960d6abdde0d.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"modern bathroom interior with a vanity and mirror\" title=\"modern bathroom interior with a vanity and mirror\" loading=\"lazy\" width=\"2250\" height=\"3000\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/hauvette-madani-bagatelle-15atmatthewavignone-6960f7f83c5ad.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/hauvette-madani-interioristas-dormitorio-juvenil-6960d6b0d8072.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"1200\" height=\"1600\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/hauvette-madani-interioristas-aseo-6960d6ac5affb.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Matthew Avignone<\/p>\n<p><img draggable=\"true\" alt=\"una casa con jardin y estilo japandi de los interioristas hauvette y madani\" title=\"Una casa con jardin y estilo japandi de los interioristas Hauvette y Madani\" loading=\"lazy\" width=\"2048\" height=\"2731\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/hauvette-madani-interioristas-6960d6b146a2c.jpg\" class=\"css-0 e1g79fud0\"\/>Matthew Avignone<\/p>\n<p> Samantha Hauvette &amp; Lucas Madani.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"34\" class=\"css-6wxqfj emevuu60\"><a href=\"https:\/\/www.hauvette-madani.com\/\" target=\"_blank\" rel=\"nofollow noopener\" data-vars-ga-outbound-link=\"https:\/\/www.hauvette-madani.com\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"www.hauvette-madani.com\" data-node-id=\"34.0\" class=\"body-link css-15fjk10 emevuu60\">www.hauvette-madani.com<\/a><\/p>\n<p><img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/1768234092_935_882c5372-60ec-4b62-a60a-c341658650f9_1660891498.file.png\" alt=\"Headshot of Gema Marcos\" title=\"Headshot of Gema Marcos\" width=\"100%\" height=\"100%\" decoding=\"async\" loading=\"lazy\" class=\"css-o0wq4v ev8dhu53\"\/><\/p>\n<p>\u00a0Gema Marcos es periodista y est\u00e1 especializada en temas de decoraci\u00f3n, dise\u00f1o, arquitectura y hoteles. Licenciada en Ciencia de la Informaci\u00f3n por la Universidad Complutense de Madrid, ha trabajado muchos a\u00f1os en la redacci\u00f3n de revistas de interiorismo y estilo de vida.\u00a0<\/p>\n<p>\u00a0En la cabecera Nuevo Estilo es donde se form\u00f3 y adquiri\u00f3 sus conocimientos sobre el mundo de interiores. Entrevistar a decoradores y arquitectos del panorama nacional, viajar a las ferias europeas de dise\u00f1o y acudir cada semana a ruedas de prensa de las marcas de muebles le ayudaron a conocer m\u00e1s a fondo el mundo del interiorismo. Adem\u00e1s tuvo la suerte de coordinar la secci\u00f3n hoteles de esa revista, lo que le permiti\u00f3 entender mejor el funcionamiento y la puesta en escena de algunos de los mejores hoteles de Espa\u00f1a y Europa.\u00a0<\/p>\n<p>\u00a0Actualmente es freelance y colabora para nuestras revistas Elle Decor y Nuevo Estilo, adem\u00e1s de llevar la comunicaci\u00f3n y difusi\u00f3n en medios de algunos estudios de interiorismo nacionales. Le gusta su trabajo y disfruta escribiendo sobre proyectos de viviendas, contract, artesan\u00eda y viajes. En realidad el mundo de la decoraci\u00f3n le ha atra\u00eddo desde que era peque\u00f1a&#8230; Sabe que rodearse de cosas bonitas es algo esencial para estar contentos cada d\u00eda.\u00a0<\/p>\n<p>\u00a0Gema se divierte descubriendo nuevos alojamientos y localizando objetos curiosos en tiendas y almonedas que le inspiran, adem\u00e1s, a la hora de escribir. Le encanta cambiar y mover los muebles de casa cada dos por tres, encender la chimenea, pasar horas en la cocina y abrir un vino en compa\u00f1\u00eda. Prefiere el invierno al verano y le gustan m\u00e1s los potajes que el gazpacho. Su lugar favorito es Villarrube, su pueblecito materno.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Est\u00e1 en el coraz\u00f3n de Par\u00eds y su entorno posee una combinaci\u00f3n perfecta entre naturaleza y arte que&hellip;\n","protected":false},"author":2,"featured_media":337035,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,232,234,1180,146,147,25,24,23],"class_list":{"0":"post-337034","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-design","13":"tag-diseno","14":"tag-editorial","15":"tag-entertainment","16":"tag-entretenimiento","17":"tag-es","18":"tag-espana","19":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115882997045713233","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/337034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=337034"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/337034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/337035"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=337034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=337034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=337034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}