{"id":342492,"date":"2026-01-15T17:25:17","date_gmt":"2026-01-15T17:25:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/342492\/"},"modified":"2026-01-15T17:25:17","modified_gmt":"2026-01-15T17:25:17","slug":"esta-luminosa-casa-de-85-metros-cuadrados-para-un-joven-soltero-se-ha-decorado-con-espacios-abiertos-colores-oscuros-y-materiales-con-textura","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/342492\/","title":{"rendered":"Esta luminosa casa de 85 metros cuadrados para un joven soltero se ha decorado con espacios abiertos, colores oscuros y materiales con textura"},"content":{"rendered":"<p data-journey-content=\"true\" data-node-id=\"2\" class=\"body-dropcap css-z34acw emevuu60\">Cada rinc\u00f3n de esta <strong data-node-id=\"2.1\">casa de 85 metros cuadrados<\/strong> destila un vibrante car\u00e1cter, reflejo de su due\u00f1o, un joven que \u00abno teme a la experimentaci\u00f3n y que disfruta de un estilo de vida abierto al mundo\u00bb, en palabras del <strong data-node-id=\"2.3\">interiorista Segey Tregubov.<\/strong> El dise\u00f1ador cuenta que \u00aben nuestro primer encuentro, le pregunt\u00e9 qu\u00e9 emoci\u00f3n deb\u00eda transmitir el interior. Me respondi\u00f3 que quer\u00eda una casa para descansar y recuperar energ\u00eda, pero al mismo tiempo sentirse en el centro de todo y en calma\u00bb.<br data-node-id=\"2.5\"\/><\/p>\n<p data-journey-content=\"true\" data-node-id=\"5\" class=\"css-6wxqfj emevuu60\">La distribuci\u00f3n original ya estaba pensada como espacio de descanso. En el amplio sal\u00f3n con ventanales en la esquina, el sof\u00e1 se orienta hacia las vistas del skyline urbano. Todas las puertas fueron eliminadas (salvo la del ba\u00f1o) mientras que una partici\u00f3n central, que act\u00faa tambi\u00e9n como soporte para la televisi\u00f3n, funciona como eje que organiza los espacios. \u00abAl distribuir los muebles, quise potenciar al m\u00e1ximo la dimensi\u00f3n t\u00e1ctil del espacio\u00bb, explica el dise\u00f1ador. Todas las piezas fueron hechas a medida siguiendo sus bocetos. <\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"3333\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-1-of-70-6964da3871553.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-1-of-70-6964da3871553.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a>Sergey Krasyuk<\/p>\n<p>El sof\u00e1 de Marac se combina con los bancos de Flexform, las l\u00e1mparas de pie de Louis Poulsen y las mesas de centro Monolith y Be Mine de Henge, que completan el conjunto.<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"3333\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-2-of-70-6964da3884137.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-2-of-70-6964da3884137.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Sergey Krasyuk<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"3333\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-5-of-70-6964da3da87d4.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Sergey Krasyuk<\/p>\n<p data-journey-content=\"true\" data-node-id=\"10\" class=\"css-6wxqfj emevuu60\">La <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/g63358820\/ideas-decorar-espacios-abiertos-cocina-salon\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/g63358820\/ideas-decorar-espacios-abiertos-cocina-salon\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"cocina abierta\" data-node-id=\"10.1\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">cocina abierta<\/a> se dise\u00f1\u00f3 para quedar pr\u00e1cticamente oculta: los frentes, tratados como paneles murales, se funden con el interior gracias a superficies de madera con inserciones de chapa trenzada y un c\u00edrculo decorativo central, una de las muchas referencias a la est\u00e9tica oriental que se encuentran en la casa. La zona derecha funciona como un bloque-bar con estantes met\u00e1licos para objetos decorativos y botellas de vidrio. El comedor se organiza en torno a una mesa inspirada en las esculturas de equilibrio de piedras del maestro japon\u00e9s Ikenishi Daisuke. La pieza transmite la sensaci\u00f3n de que basta un roce para desestabilizar toda la estructura, met\u00e1fora de la fragilidad de las relaciones humanas.<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"3333\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-19-of-70-6964da3edd7a7.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-19-of-70-6964da3edd7a7.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a>Sergey Krasyuk<\/p>\n<p>En el comedor-cocina los sistemas de almacenaje, la mesa y la cocina de Silver Home dialogan con la l\u00e1mpara de techo de Bomma, las sillas de Poltrona Frau, el papel pintado Charcoal Gray Veneered de Nobilis y el suelo en Rocky Reef de Coswick; los jarrones H-Vases de Henge aportan un acento decorativo.<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"3333\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-16-of-70-6964da3877624.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-16-of-70-6964da3877624.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Sergey Krasyuk<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"2500\" height=\"3333\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-30-of-70-6964da3873720.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-30-of-70-6964da3873720.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Sergey Krasyuk<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"2500\" height=\"3333\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-40-of-70-6964da3e6af17.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-40-of-70-6964da3e6af17.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Sergey Krasyuk<\/p>\n<p data-journey-content=\"true\" data-node-id=\"18\" class=\"css-6wxqfj emevuu60\">El dormitorio principal, concebido como un verdadero oasis de serenidad. Al entrar, sorprende una ba\u00f1era transparente en un intenso tono \u00e1mbar sobre un pedestal de piedra, situada junto al ventanal y enmarcada por listones de madera. Tras la cama, un panel de chapa de roble ondulada integra en su parte central un entramado de metal, cuero y cintas textiles. Frente a la cama, sobre una consola, cuelga el panel escult\u00f3rico del propio Tregubov titulado Cuatro elementos, que remite al equilibrio del Yin y el Yang: el metal simboliza el agua, las monta\u00f1as la tierra, el viento el aire y el fuego la pasi\u00f3n.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"20\" class=\"css-6wxqfj emevuu60\">A trav\u00e9s del vestidor se llega al ba\u00f1o principal, con una atm\u00f3sfera que recuerda a Bali: abundante vegetaci\u00f3n, una pared con textura de arena frente al mar, suelos de madera natural y una ducha con efecto cascada y lluvia tropical.<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"3333\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-48-of-70-6964da3e6c4ba.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-48-of-70-6964da3e6c4ba.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a>Sergey Krasyuk<\/p>\n<p>El vestidor, separado del dormitorio por una mampara de cristal, cuenta con sistemas de almacenaje de Silver Home y una butaca de Poltrona Frau, reforzando la continuidad est\u00e9tica.<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"2500\" height=\"3333\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-37-of-70-6964da3e66f57.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-37-of-70-6964da3e66f57.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Sergey Krasyuk<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"2500\" height=\"3333\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-45-of-70-6964da3879afc.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-45-of-70-6964da3879afc.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Sergey Krasyuk<\/p>\n<p><img draggable=\"true\" alt=\"casa zen colores oscuros\" title=\"casa zen colores oscuros \" loading=\"lazy\" width=\"2500\" height=\"3333\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/neva-web-53-of-70-6964da428e914.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a65928828\/85-metros-color-oscuro-espacio-abierto\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/neva-web-53-of-70-6964da428e914.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a>Sergey Krasyuk<\/p>\n<p>En el cuarto de ba\u00f1o, iluminaci\u00f3n de Fabbian y l\u00e1mpara colgante Leda de Karman Lighting, mueble exento de Duravit y sanitario suspendido de Antonio Lupi completan el conjunto.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"26\" class=\"css-6wxqfj emevuu60\"> El interiorista propuso basar el proyecto en sensaciones t\u00e1ctiles y en una variedad de texturas, con gui\u00f1os a la <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/a20728555\/consejos-decoracion-feng-shui\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/a20728555\/consejos-decoracion-feng-shui\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"filosof\u00eda oriental\" data-node-id=\"26.1\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">filosof\u00eda oriental<\/a> y los materiales naturales. La paleta crom\u00e1tica se construy\u00f3 en torno a dos conceptos clave \u2014emoci\u00f3n y tactilidad\u2014, con tonos c\u00e1lidos inspirados en el cuero, el tabaco, el caf\u00e9 y la neblina que envuelve el paisaje urbano. Porque uno de los puntos destacables del proyecto es la materialidad que se percibe en los espacios. Revestimientos muy t\u00e1ctiles, inspirados en la naturaleza, un concepto que se potencia a\u00fan m\u00e1s gracias a las <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/g25292365\/plantas-de-interior-resistentes\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/g25292365\/plantas-de-interior-resistentes\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"plantas de interior. \" data-node-id=\"26.3\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">plantas de interior. <\/a>Todo, en conjunto, confiere al ambiente una est\u00e9tica oriental. \u00abEl espacio se siente l\u00edmites ni \u00e1ngulos rectos, con formas suaves y unas vistas espectaculares. Los significados del proyecto se perciben de manera natural, y el interior invita a ser explorado con los sentidos\u00bb.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"28\" class=\"css-6wxqfj emevuu60\">\u0410sistente de dise\u00f1o: Alexey Derkach<br data-node-id=\"28.0.1\"\/>\u0421oordinador de materiales: Mikhail Gorbunov<br data-node-id=\"28.0.3\"\/>Estilismo: Milena Morozova<\/p>\n<p data-journey-content=\"true\" data-node-id=\"30\" class=\"css-6wxqfj emevuu60\"><a href=\"https:\/\/www.instagram.com\/tregubov_official\" target=\"_blank\" rel=\"nofollow noopener\" data-vars-ga-outbound-link=\"https:\/\/www.instagram.com\/tregubov_official\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"@tregubov_official\" data-node-id=\"30.0\" class=\"body-link css-15fjk10 emevuu60\">@tregubov_official<\/a><br data-node-id=\"30.1.0\"\/><\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Cada rinc\u00f3n de esta casa de 85 metros cuadrados destila un vibrante car\u00e1cter, reflejo de su due\u00f1o, un&hellip;\n","protected":false},"author":2,"featured_media":342493,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,232,234,1180,146,147,25,24,23],"class_list":{"0":"post-342492","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-design","13":"tag-diseno","14":"tag-editorial","15":"tag-entertainment","16":"tag-entretenimiento","17":"tag-es","18":"tag-espana","19":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115900286911170296","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/342492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=342492"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/342492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/342493"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=342492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=342492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=342492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}