{"id":346778,"date":"2026-01-18T02:36:11","date_gmt":"2026-01-18T02:36:11","guid":{"rendered":"https:\/\/www.europesays.com\/es\/346778\/"},"modified":"2026-01-18T02:36:11","modified_gmt":"2026-01-18T02:36:11","slug":"ee-uu-lleva-a-cabo-ataque-letal-contra-lider-afiliado-a-al-qaeda-en-siria","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/346778\/","title":{"rendered":"EE.UU. lleva a cabo ataque letal contra l\u00edder afiliado a al Qaeda en Siria"},"content":{"rendered":"<p>      CNN<br \/>\n        \u00a0\u2014\u00a0<\/p>\n<p class=\"paragraph inline-placeholder vossi-paragraph\" data-uri=\"es.cms.cnn.com\/_components\/paragraph\/instances\/cmkj0bbpz003e26ns5mszhjqi@published\" data-editable=\"text\" data-component-name=\"paragraph\" data-article-gutter=\"true\">\n            Estados Unidos anunci\u00f3 este s\u00e1bado que realiz\u00f3 un ataque letal en Siria contra un l\u00edder afiliado a al Qaeda que, seg\u00fan afirma, ten\u00eda v\u00ednculos directos con <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/13\/eeuu\/siria-mueren-soldados-ee-uu-trax\" rel=\"nofollow noopener\" target=\"_blank\">un atacante de ISIS que mat\u00f3<\/a> a tres estadounidenses a principios de diciembre.\n    <\/p>\n<p class=\"paragraph inline-placeholder vossi-paragraph\" data-uri=\"es.cms.cnn.com\/_components\/paragraph\/instances\/cmkj0gfso0005356pj481girq@published\" data-editable=\"text\" data-component-name=\"paragraph\" data-article-gutter=\"true\">\n            \u201cLa muerte de un operador terrorista vinculado a la muerte de tres estadounidenses demuestra nuestra determinaci\u00f3n de perseguir a los terroristas que atacan a nuestras fuerzas\u201d, dijo el almirante Brad Cooper, comandante del Comando Central de Estados Unidos (CENTCOM), en un comunicado en X.\n    <\/p>\n<p class=\"paragraph inline-placeholder vossi-paragraph\" data-uri=\"es.cms.cnn.com\/_components\/paragraph\/instances\/cmkj0gfso0006356pebdv9ftl@published\" data-editable=\"text\" data-component-name=\"paragraph\" data-article-gutter=\"true\">\n            El CENTCOM inform\u00f3 que Bilal Hasan al-Jasim \u201cera un l\u00edder terrorista experimentado\u201d y \u201cestaba directamente relacionado\u201d con el atacante de ISIS que mat\u00f3 a dos miembros de las Fuerzas Armadas estadounidenses y a un int\u00e9rprete civil el 13 de diciembre de 2025 en Palmira, Siria.\n    <\/p>\n<p class=\"paragraph inline-placeholder vossi-paragraph\" data-uri=\"es.cms.cnn.com\/_components\/paragraph\/instances\/cmkj0gfso0007356p1ve22y45@published\" data-editable=\"text\" data-component-name=\"paragraph\" data-article-gutter=\"true\">\n            CNN ha contactado a CENTCOM para obtener comentarios sobre el ataque y detalles sobre los presuntos v\u00ednculos del l\u00edder con el ataque de diciembre.\n    <\/p>\n<p class=\"paragraph inline-placeholder vossi-paragraph\" data-uri=\"es.cms.cnn.com\/_components\/paragraph\/instances\/cmkj0gfso0008356p2xsuflda@published\" data-editable=\"text\" data-component-name=\"paragraph\" data-article-gutter=\"true\">\n            Estados Unidos ha estado respondiendo a ISIS tras la emboscada mortal mediante una serie de ataques bajo la campa\u00f1a denominada <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/19\/mundo\/eeuu-ataques-siria-muerte-dos-soldados-trax\" rel=\"nofollow noopener\" target=\"_blank\">\u201cOperaci\u00f3n Hawkeye Strike\u201d.<\/a>\n    <\/p>\n<p class=\"paragraph inline-placeholder vossi-paragraph\" data-uri=\"es.cms.cnn.com\/_components\/paragraph\/instances\/cmkj0gfso0009356pp3hq89p2@published\" data-editable=\"text\" data-component-name=\"paragraph\" data-article-gutter=\"true\">\n            El secretario de Defensa, Pete Hegseth, respondi\u00f3 a la publicaci\u00f3n de CENTCOM, <a href=\"https:\/\/x.com\/PeteHegseth\/status\/2012643358678688011?s=20\" target=\"_blank\" rel=\"nofollow\">escribiendo en X<\/a>: \u201cNunca olvidaremos y nunca cederemos\u201d.\n    <\/p>\n","protected":false},"excerpt":{"rendered":"CNN \u00a0\u2014\u00a0 Estados Unidos anunci\u00f3 este s\u00e1bado que realiz\u00f3 un ataque letal en Siria contra un l\u00edder afiliado&hellip;\n","protected":false},"author":2,"featured_media":346779,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[78526,17,18,629,13,14,11,61,62,63,64,78527,19,20,9,10,15,16,32787,12,21,22,65,66,67],"class_list":{"0":"post-346778","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-al-qaeda","9":"tag-breaking-news","10":"tag-breakingnews","11":"tag-estados-unidos","12":"tag-featured-news","13":"tag-featurednews","14":"tag-headlines","15":"tag-internacional","16":"tag-international","17":"tag-international-news","18":"tag-internationalnews","19":"tag-isis","20":"tag-latest-news","21":"tag-latestnews","22":"tag-news","23":"tag-noticias","24":"tag-noticias-destacadas","25":"tag-noticiasdestacadas","26":"tag-siria","27":"tag-titulares","28":"tag-ultimas-noticias","29":"tag-ultimasnoticias","30":"tag-world","31":"tag-world-news","32":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115913777693789920","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/346778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=346778"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/346778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/346779"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=346778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=346778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=346778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}