{"id":347383,"date":"2026-01-18T11:16:24","date_gmt":"2026-01-18T11:16:24","guid":{"rendered":"https:\/\/www.europesays.com\/es\/347383\/"},"modified":"2026-01-18T11:16:24","modified_gmt":"2026-01-18T11:16:24","slug":"la-madera-es-la-gran-protagonista-del-proyecto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/347383\/","title":{"rendered":"La madera es la gran protagonista del proyecto"},"content":{"rendered":"<p data-journey-content=\"true\" data-node-id=\"2\" class=\"body-dropcap css-z34acw emevuu60\">En uno de los barrios m\u00e1s densos y vibrantes de Par\u00eds, el distrito 11, se esconde una vivienda tan inesperada como serena. Tras una puerta discreta y un recorrido pausado por un largo patio, aparece una casa familiar que rompe con la l\u00f3gica urbana de su entorno: un refugio silencioso, ba\u00f1ado por la luz natural y articulado en torno a la madera como lenguaje principal. El proyecto, firmado por <strong data-node-id=\"2.1\">Holzrausch Studio<\/strong>, ha transformado <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/a37010110\/patios-ideas-decoracion-ejemplos\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/a37010110\/patios-ideas-decoracion-ejemplos\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"una casa con patio\" data-node-id=\"2.3\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">una casa con patio<\/a> en Par\u00eds en un ejercicio de calma atemporal. El patio ajardinado, que se despliega como antesala de la vivienda, no es solo un espacio exterior, sino una prolongaci\u00f3n natural del interior. En los meses c\u00e1lidos, las <a href=\"https:\/\/www.elledecor.com\/es\/arquitectura\/a22881879\/casas-puertas-acristaladas-cerramientos-vistas\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/arquitectura\/a22881879\/casas-puertas-acristaladas-cerramientos-vistas\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"grandes aperturas acristaladas\" data-node-id=\"2.5\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">grandes aperturas acristaladas<\/a> permiten que la vida cotidiana fluya entre dentro y fuera, reforzando una forma de habitar pausada alejada del ritmo de la ciudad. \u201cQuer\u00edan un interior definido por la calma y la sencillez, evitando deliberadamente cualquier elemento de moda o instagrameable\u201d, explica Petri, cofundador y director de dise\u00f1o de Holzrausch. \u201cComo exmodelo, galerista y creativo, el cliente se sinti\u00f3 naturalmente atra\u00eddo por nuestro enfoque en la calidad de los materiales\u201d.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"5\" class=\"css-6wxqfj emevuu60\">Durante la renovaci\u00f3n, se elimin\u00f3 m\u00e1s del 80 % de la estructura existente. Las aberturas en el techo permiten la entrada de luz natural, moldeando la arquitectura y dando lugar a la escultural escalera que act\u00faa de eje conductor entre las cuatro plantas: <strong data-node-id=\"5.1\">350 metros cuadrados de vivienda<\/strong> que se distribuye en un amplio sal\u00f3n, una cocina con una larga <a href=\"https:\/\/www.elledecor.com\/es\/diseno\/g26982146\/mesas-comedor-iconos-diseno\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/diseno\/g26982146\/mesas-comedor-iconos-diseno\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"mesa en el comedor\" data-node-id=\"5.3\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">mesa en el comedor<\/a>, as\u00ed como cuatro dormitorios y cuatro ba\u00f1os, adapt\u00e1ndose a las necesidades de una familia.<br data-node-id=\"5.5\"\/><\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch30-sc-v2com-696a031acb909.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch30-sc-v2com-696a031acb909.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch33-sc-v2com-696a031b59d38.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch33-sc-v2com-696a031b59d38.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch-sc-v2com-696a0315afbc3.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch-sc-v2com-696a0315afbc3.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch18-sc-v2com-696a0315bd189.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch18-sc-v2com-696a0315bd189.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch38-sc-v2com-696a031fdeee1.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch38-sc-v2com-696a031fdeee1.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch32-sc-v2com-696a031aaae97.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch32-sc-v2com-696a031aaae97.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch19-sc-v2com-696a031481641.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch19-sc-v2com-696a031481641.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch16-sc-v2com-696a0315bd66e.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch16-sc-v2com-696a0315bd66e.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p data-journey-content=\"true\" data-node-id=\"15\" class=\"css-6wxqfj emevuu60\">La madera es la gran protagonista del proyecto y el roble macizo manda en suelos, paneles y mobiliario integrado envolviendo la vivienda con una calidez constante, sin estridencias. No es una elecci\u00f3n casual: Holzrausch naci\u00f3 como <strong data-node-id=\"15.1\">taller de carpinter\u00eda<\/strong>, y ese origen artesanal sigue marcando profundamente todos sus trabajos, en los que cada elemento parece pensado desde la materia, desde el tacto, desde la precisi\u00f3n del oficio.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"19\" class=\"css-6wxqfj emevuu60\">El interior se define por la <strong data-node-id=\"19.1\">reducci\u00f3n consciente de materiales<\/strong> \u2014madera, yeso, piedra y acero inoxidable\u2014 y por una ausencia deliberada de elementos superfluos. No hay piezas decorativas ni obras de arte que interrumpan la serenidad del conjunto. Todo responde a una idea clara de simplicidad, donde el espacio, la luz y la materialidad son suficientes.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"21\" class=\"css-6wxqfj emevuu60\">La escalera escult\u00f3rica, columna vertebral de la casa, articula los cuatro niveles y distribuye la luz que entra desde los lucernarios superiores. Al tratarse de un edificio en forma de L cuyas ventanas dan \u00fanicamente al patio, la <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/a46235264\/como-aumentar-luz-casa\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/a46235264\/como-aumentar-luz-casa\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"entrada de luz natural \" data-node-id=\"21.1\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">entrada de luz natural <\/a>desde arriba fue clave en el dise\u00f1o. El resultado es un espacio abierto, continuo, donde la arquitectura se percibe m\u00e1s como una secuencia de atm\u00f3sferas que como una suma de estancias cerradas. Fiel a su filosof\u00eda, Holzrausch firma una casa que huye de modas y referencias ef\u00edmeras. Un proyecto donde la <strong data-node-id=\"21.3\">atemporalidad y la calma se convierten en aut\u00e9nticos lujos<\/strong>, demostrando que, incluso en el coraz\u00f3n de Par\u00eds, todav\u00eda es posible encontrar espacios para el silencio.<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch36-sc-v2com-696a031b279f3.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch36-sc-v2com-696a031b279f3.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch21-sc-v2com-696a031acfa57.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch21-sc-v2com-696a031acfa57.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p><img draggable=\"true\" alt=\"casa paris madera patio\" title=\"casa paris madera patio\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/casa-paris-holzrausch22-sc-v2com-696a0315b706b.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a70017420\/casa-patio-minimalista-zen-paris\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/casa-paris-holzrausch22-sc-v2com-696a0315b706b.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Salva L\u00f3pez<\/p>\n<p data-journey-content=\"true\" data-node-id=\"26\" class=\"css-6wxqfj emevuu60\"><a href=\"https:\/\/www.holzrausch.de\/\" target=\"_blank\" rel=\"nofollow noopener\" data-vars-ga-outbound-link=\"https:\/\/www.holzrausch.de\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"www.holzrausch.de\" data-node-id=\"26.0\" class=\"body-link css-15fjk10 emevuu60\">www.holzrausch.de<\/a><\/p>\n<p><img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/ebe73ce5-cc2d-49f0-9bf3-17e1cd3f5a0a_1660891402.file.png\" alt=\"Headshot of Mar\u00eda Jes\u00fas Revilla\" title=\"Headshot of Mar\u00eda Jes\u00fas Revilla\" width=\"100%\" height=\"100%\" decoding=\"async\" loading=\"lazy\" class=\"css-o0wq4v ev8dhu53\"\/><\/p>\n<p>\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/mar%C3%ADa-jes%C3%BAs-revilla-084a1115b\/\" rel=\"nofollow noopener\" target=\"_blank\">Mar\u00eda Jes\u00fas Revilla<\/a> es experta en temas de decoraci\u00f3n, interiorismo, arquitectura y dise\u00f1o tras una larga trayectoria en publicaciones del sector. \u00a0\u00a0Es licenciada en Periodismo por la Universidad Complutense de Madrid y en sus comienzos profesionales como redactora trabaj\u00f3 en revistas de empresa, femeninas, juveniles, o incluso relacionadas con el mundo del motor.\u00a0<\/p>\n<p>\u00a0Se considera una todoterreno que encontr\u00f3 su sitio y su pasi\u00f3n en la decoraci\u00f3n y el dise\u00f1o de interiores. Le entretiene rastrear y escribir sobre edificios ic\u00f3nicos de la arquitectura del siglo XX, leer y aprender sobre urbanismo sostenible y seguir las tendencias en decoraci\u00f3n.\u00a0<\/p>\n<p>\u00a0Con su trabajo ha descubierto que el interiorismo y la arquitectura influyen mucho en la calidad de vida de las personas y, por lo tanto, tambi\u00e9n pueden contribuir a mejorarla, algo que procura transmitir en todo lo que hace.\u00a0<\/p>\n<p>\u00a0Tras muchos a\u00f1os en la redacci\u00f3n print de Nuevo Estilo, la revista decana de decoraci\u00f3n en Espa\u00f1a, emprendi\u00f3 su andadura en la versi\u00f3n online de Nuevo Estilo y ElleDecor donde, adem\u00e1s de escribir, desarrolla labores de coordinaci\u00f3n de proyectos audiovisuales para la web.\u00a0<\/p>\n<p>\u00a0Mar\u00eda Jes\u00fas sue\u00f1a con tener todo el tiempo del mundo para dedicarse al dolce far niente. A saber: pasear, darse ba\u00f1os en el mar, tomarse un vino y pasear un rato m\u00e1s (y tomarse otro vino)\u2026 sin preocupaciones.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"En uno de los barrios m\u00e1s densos y vibrantes de Par\u00eds, el distrito 11, se esconde una vivienda&hellip;\n","protected":false},"author":2,"featured_media":347384,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,232,253,234,1180,146,147,25,24,23],"class_list":{"0":"post-347383","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-design","13":"tag-discover","14":"tag-diseno","15":"tag-editorial","16":"tag-entertainment","17":"tag-entretenimiento","18":"tag-es","19":"tag-espana","20":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115915822916249321","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/347383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=347383"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/347383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/347384"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=347383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=347383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=347383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}