{"id":347819,"date":"2026-01-18T17:01:15","date_gmt":"2026-01-18T17:01:15","guid":{"rendered":"https:\/\/www.europesays.com\/es\/347819\/"},"modified":"2026-01-18T17:01:15","modified_gmt":"2026-01-18T17:01:15","slug":"esta-casa-de-arquitectura-brutalista-se-ha-construido-con-tecnicas-artesanales-integrada-en-la-naturaleza","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/347819\/","title":{"rendered":"Esta casa de arquitectura brutalista se ha construido con t\u00e9cnicas artesanales integrada en la naturaleza"},"content":{"rendered":"<p data-journey-content=\"true\" data-node-id=\"2\" class=\"body-dropcap css-z34acw emevuu60\">Rodeada de naturaleza, esta <strong data-node-id=\"2.1\">casa de 400 metros cuadrados <\/strong>se inserta en el paisaje fundi\u00e9ndose en \u00e9l con armon\u00eda. El <strong data-node-id=\"2.3\">estudio East Architecture<\/strong> compuso este proyecto combinando conceptos que puedan parecer opuestos: es a la vez un refugio \u00edntimo, un retiro -Capsule Retreat es el nombre de la construcci\u00f3n- y tambi\u00e9n sus espacios se abren al entorno circundante -con paisajismo de Loubna Hijaziy- a las vistas de los bosques de con\u00edferas del Monte L\u00edbano.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"5\" class=\"css-6wxqfj emevuu60\">El proceso de dise\u00f1o se plante\u00f3 centr\u00e1ndose en las condiciones f\u00edsicas y materiales del lugar, dejando en segundo plano las sensibilidades est\u00e9ticas y adapt\u00e1ndose como un guante al terreno. La construcci\u00f3n parte de filosof\u00edas <a href=\"https:\/\/www.elledecor.com\/es\/casas\/a65215430\/casa-brutalista-hormigon-retro\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/casas\/a65215430\/casa-brutalista-hormigon-retro\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"brutalistas, con el hormig\u00f3n desnudo\" data-node-id=\"5.1\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">brutalistas, con el hormig\u00f3n desnudo<\/a> como lenguaje formal y a su vez fondo constructivo. La casa se erigi\u00f3 sin grandes tecnolog\u00edas, utilizando t\u00e9cnicas de construcci\u00f3n propias de los entornos rurales que ayudan a integrar el dise\u00f1o en el contexto. Los materiales y el espacio se presentan en estado puro y el interior, deliberadamente monocrom\u00e1tico, construyendo una vivienda con una textura muy particular, con muros, <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/a62618884\/tipos-de-suelo-guia-consejos-experto\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/a62618884\/tipos-de-suelo-guia-consejos-experto\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"suelos y techos de hormig\u00f3n\" data-node-id=\"5.3\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">suelos y techos de hormig\u00f3n<\/a>, un material al que se a\u00f1ade, en contados toques, el acero inoxidable Este empleo del hormig\u00f3n remite a su papel en la arquitectura de mediados del siglo XX en la regi\u00f3n. <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/a40273548\/artesanos-espana-ceramica-textil-papel-artesania\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/a40273548\/artesanos-espana-ceramica-textil-papel-artesania\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"Artesanos locales\" data-node-id=\"5.5\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">Artesanos locales<\/a> participaron en su mezcla y vertido, usando encofrados realizados con madera de origen local y que posteriormente se ha reutilizado en elementos interiores de la vivienda, otorgando a las superficies cualidades \u00fanicas y ligadas al lugar.<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3813\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-4-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe76013c8.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-4-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe76013c8.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"2500\" height=\"5382\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-20-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe80e8b15.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-20-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe80e8b15.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"2500\" height=\"3334\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-6-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe75b897f.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-6-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe75b897f.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-21-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe80eef21.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-21-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe80eef21.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3751\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-9-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe760b1a9.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-9-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe760b1a9.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3751\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-10-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7abbf93.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-10-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7abbf93.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3751\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-11-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe75d9aad.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-11-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe75d9aad.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-19-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe80638f9.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-19-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe80638f9.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p data-journey-content=\"true\" data-node-id=\"15\" class=\"css-6wxqfj emevuu60\">El espacio principal, de planta abierta y una altura de cuatro metros, integra <a href=\"https:\/\/www.elledecor.com\/es\/decoracion\/g25045809\/ideas-decoracion-cocina-abierta\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elledecor.com\/es\/decoracion\/g25045809\/ideas-decoracion-cocina-abierta\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"cocina, comedor y sala de estar\" data-node-id=\"15.1\" class=\"body-link css-15fjk10 emevuu60\" rel=\"nofollow noopener\">cocina, comedor y sala de estar<\/a>, y se abre mediante ventanales de altura completa hacia el jard\u00edn y el bosque circundante. Esta gran zona com\u00fan y otros espacios de la casa, de inspiraci\u00f3n minimalista, sirven para albergar la extensa colecci\u00f3n de arte contempor\u00e1neo del propietario. Por ejemplo, una de las se\u00f1as de identidad m\u00e1s significativas de la casa es la cubierta contempor\u00e1nea dise\u00f1ada a medida por el artista y escultor iraqu\u00ed Dia Azzawi, que refuerza el impacto visual del conjunto y oculta de manera sutil los equipos mec\u00e1nicos. configura como un espacio singular para la vida dom\u00e9stica y el arte contempor\u00e1neo.<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"2500\" height=\"3751\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-12-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7b7acba.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-12-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7b7acba.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-14-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7be6341.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-14-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7be6341.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-16-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7cf20e3.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-16-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7cf20e3.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3334\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-14-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7be6341.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-14-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7be6341.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3751\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-13-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7b35cac.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-13-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7b35cac.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"2500\" height=\"3751\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-23-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe814a10f.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-23-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe814a10f.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3751\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-5-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe75de5d1.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-5-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe75de5d1.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"3754\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-1-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7b69820.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-1-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7b69820.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p><img draggable=\"true\" alt=\"casa hormigon brutalista\" title=\"casa hormigon brutalista\" loading=\"lazy\" width=\"4999\" height=\"2500\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/image-2-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7610d90.jpg\" class=\"css-0 e1g79fud0\"\/><a target=\"_blank\" rel=\"noopener nofollow\" data-theme-key=\"base-link\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.elledecor.com\/es\/casas\/a69975165\/casa-brutalista-paisaje-hormigon-arte\/&amp;description=elledecoresp&amp;media=https:\/\/hips.hearstapps.com\/hmg-prod\/images\/image-2-c-copyright-2025-east-architecture-studio-ieva-saudargaite-photographer-6964fe7610d90.jpg?resize=1600:*\" class=\"pinterest css-on9hn5 e1c1bym14\"><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elledecor.com\/_assets\/design-tokens\/fre\/static\/icons\/social\/pinterest.e8cf655.svg?primary=%2523ffffff\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" alt=\"pinterest\" class=\"css-4lml0h e1mlxuuw1\"\/><\/a><\/p>\n<p>Ieva Saudargaite\u0307<\/p>\n<p data-journey-content=\"true\" data-node-id=\"28\" class=\"css-6wxqfj emevuu60\"><a href=\"https:\/\/eastarchitecture.net\/\" target=\"_blank\" rel=\"nofollow noopener\" data-vars-ga-outbound-link=\"https:\/\/eastarchitecture.net\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"www.eastarchitecture.net\" data-node-id=\"28.0.0\" class=\"body-link css-15fjk10 emevuu60\">www.eastarchitecture.net<\/a><\/p>\n<p><img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/1768755675_74_ebe73ce5-cc2d-49f0-9bf3-17e1cd3f5a0a_1660891402.file.png\" alt=\"Headshot of Mar\u00eda Jes\u00fas Revilla\" title=\"Headshot of Mar\u00eda Jes\u00fas Revilla\" width=\"100%\" height=\"100%\" decoding=\"async\" loading=\"lazy\" class=\"css-o0wq4v ev8dhu53\"\/><\/p>\n<p>\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/mar%C3%ADa-jes%C3%BAs-revilla-084a1115b\/\" rel=\"nofollow noopener\" target=\"_blank\">Mar\u00eda Jes\u00fas Revilla<\/a> es experta en temas de decoraci\u00f3n, interiorismo, arquitectura y dise\u00f1o tras una larga trayectoria en publicaciones del sector. \u00a0\u00a0Es licenciada en Periodismo por la Universidad Complutense de Madrid y en sus comienzos profesionales como redactora trabaj\u00f3 en revistas de empresa, femeninas, juveniles, o incluso relacionadas con el mundo del motor.\u00a0<\/p>\n<p>\u00a0Se considera una todoterreno que encontr\u00f3 su sitio y su pasi\u00f3n en la decoraci\u00f3n y el dise\u00f1o de interiores. Le entretiene rastrear y escribir sobre edificios ic\u00f3nicos de la arquitectura del siglo XX, leer y aprender sobre urbanismo sostenible y seguir las tendencias en decoraci\u00f3n.\u00a0<\/p>\n<p>\u00a0Con su trabajo ha descubierto que el interiorismo y la arquitectura influyen mucho en la calidad de vida de las personas y, por lo tanto, tambi\u00e9n pueden contribuir a mejorarla, algo que procura transmitir en todo lo que hace.\u00a0<\/p>\n<p>\u00a0Tras muchos a\u00f1os en la redacci\u00f3n print de Nuevo Estilo, la revista decana de decoraci\u00f3n en Espa\u00f1a, emprendi\u00f3 su andadura en la versi\u00f3n online de Nuevo Estilo y ElleDecor donde, adem\u00e1s de escribir, desarrolla labores de coordinaci\u00f3n de proyectos audiovisuales para la web.\u00a0<\/p>\n<p>\u00a0Mar\u00eda Jes\u00fas sue\u00f1a con tener todo el tiempo del mundo para dedicarse al dolce far niente. A saber: pasear, darse ba\u00f1os en el mar, tomarse un vino y pasear un rato m\u00e1s (y tomarse otro vino)\u2026 sin preocupaciones.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Rodeada de naturaleza, esta casa de 400 metros cuadrados se inserta en el paisaje fundi\u00e9ndose en \u00e9l con&hellip;\n","protected":false},"author":2,"featured_media":347820,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,232,234,1180,146,147,25,24,23],"class_list":{"0":"post-347819","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-design","13":"tag-diseno","14":"tag-editorial","15":"tag-entertainment","16":"tag-entretenimiento","17":"tag-es","18":"tag-espana","19":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115917179745932075","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/347819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=347819"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/347819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/347820"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=347819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=347819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=347819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}