{"id":362955,"date":"2026-01-26T21:12:07","date_gmt":"2026-01-26T21:12:07","guid":{"rendered":"https:\/\/www.europesays.com\/es\/362955\/"},"modified":"2026-01-26T21:12:07","modified_gmt":"2026-01-26T21:12:07","slug":"el-templo-de-los-huesos-se-convierte-en-un-fracaso-en-taquilla-a-pesar-de-conquistar-a-critica-y-publico","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/362955\/","title":{"rendered":"El templo de los huesos se convierte en un fracaso en taquilla a pesar de conquistar a cr\u00edtica y p\u00fablico"},"content":{"rendered":"<p class=\"c-paragraph\">El pasado 16 de enero aterriz\u00f3 en las salas de cine <a href=\"https:\/\/www.hobbyconsolas.com\/hobbycine\/critica-28-anos-despues-templo-los-huesos-una-brutal-denuncia-fanatismo-descerebrado_6920829_0.html\" title=\"Cr\u00edtica de 28 a\u00f1os despu\u00e9s: El templo de los huesos, una brutal denuncia del fanatismo descerebrado\" rel=\"nofollow noopener\" target=\"_blank\">28 a\u00f1os despu\u00e9s: El templo de los huesos<\/a>, la segunda parte de la trilog\u00eda que contin\u00faa (y en principio, dar\u00e1 cierre) la popular saga de <b>terror<\/b> iniciada por Danny Boyle y Alex Garland en 2002.<\/p>\n<p class=\"c-paragraph\">Esta vez con <b>Nia DaCosta<\/b> en la direcci\u00f3n, la trama de la <b>pel\u00edcula<\/b> contin\u00faa tras los eventos de la anterior entrega, donde los infectados dejan de ser la mayor amenaza del planeta para dar paso a la inhumanidad que presentan buena parte de los supervivientes en el mundo conocido como el Templo de los huesos.<\/p>\n<p class=\"c-paragraph\">Bajo este escenario, el Dr. Kelso (<a href=\"https:\/\/www.hobbyconsolas.com\/listas\/actores-actrices-tienen-fama-ser-demasiado-conflictivos-rodajes-1411470\" title=\"Actores y actrices que tienen fama de ser demasiado conflictivos en los rodajes\" rel=\"nofollow noopener\" target=\"_blank\">Ralph Fiennes<\/a>)\u00a0<b><b>se ver\u00e1 envuelto en una nueva y sorprendente relaci\u00f3n, cuyas consecuencias podr\u00edan cambiar el mundo tal y como lo conocen<\/b><\/b>.<\/p>\n<p>28 a\u00f1os despu\u00e9s: El templo de los huesos se desploma en la taquilla mundial<\/p>\n<p class=\"c-paragraph\">Por lo general, la pel\u00edcula ha tenido muy buenas valoraciones entre la cr\u00edtica y el p\u00fablico, consiguiendo en <a href=\"https:\/\/www.rottentomatoes.com\/m\/28_years_later_the_bone_temple\" rel=\"nofollow noreferrer noopener\" title=\"Rotten Tomatoes\" target=\"_blank\">Rotten Tomatoes<\/a> una puntuaci\u00f3n del 93% de la prensa y un 88% por parte de la audiencia.<\/p>\n<p class=\"c-paragraph\">Sin embargo, a pesar de gustar bastante entre los espectadores, la nueva entrega de la franquicia de <a href=\"https:\/\/www.hobbyconsolas.com\/listas\/finales-inesperados-cine-terror-adolescente-hicisteis-ultimo-verano-scream-until-dawn-1473057\" title=\"Los finales m\u00e1s inesperados del cine de terror adolescente: desde S\u00e9 lo que hicisteis el \u00faltimo verano a Scream y Until Dawn\" rel=\"nofollow noopener\" target=\"_blank\">terror<\/a> no est\u00e1 dando los resultados esperados en la taquilla global.<\/p>\n<p class=\"c-paragraph\">Seg\u00fan recoge <a href=\"https:\/\/x.com\/GlobalBoxOffice\/status\/2015535223652380949?s=20\" rel=\"nofollow noreferrer\" title=\"Global Box Office\" target=\"_blank\">Global Box Office<\/a>, <b>28 a\u00f1os despu\u00e9s: El templo de los huesos recauda tan solo 46 millones de d\u00f3lares a nivel mundial tras dos fines de semana desde su estreno<\/b>, lo que supone todo un fracaso para la pel\u00edcula tras haber invertido 63 millones de d\u00f3lares de presupuesto en ella.<\/p>\n<p class=\"c-paragraph\">Adem\u00e1s, la recepci\u00f3n en taquilla ha ca\u00eddo un 71% con respecto al fin de semana de estreno, lo que no augura nada bueno para la cinta de <a href=\"https:\/\/www.hobbyconsolas.com\/listas\/grandes-directores-han-pegado-prometedoras-peliculas-2024-1416882\" title=\"8 grandes directores que se la han pegado con sus prometedoras pel\u00edculas en 2024\" rel=\"nofollow noopener\" target=\"_blank\">Nia DaCosta<\/a>.<\/p>\n<p class=\"c-paragraph\">A\u00fan es demasiado pronto para sacar conclusiones, pero <b>esta baja recepci\u00f3n en taquilla podr\u00eda suponer la cancelaci\u00f3n de la saga<\/b> y su desenlace, previsto para la siguiente entrega, se quede en el olvido y deje su trama completamente abierta. Por desgracia, no es la primera vez que una franquicia sufre un destino similar.<\/p>\n<p class=\"c-paragraph\">Queda por ver si Sony Pictures decide dar otra oportunidad a la saga y dar a los fans el final que esperan (y m\u00e1s teniendo en cuenta lo interesante que se queda 28 a\u00f1os despu\u00e9s: El templo de los huesos). \u00bfQu\u00e9 te parece que la <a href=\"https:\/\/www.hobbyconsolas.com\/hobbycine\/body-horror-terror-que-transforma-cuerpo-las-mejores-peliculas-genero-desde-sustancia-hasta-together_6883520_0.html\" title=\"Body Horror, el terror que transforma el cuerpo: las mejores pel\u00edculas del g\u00e9nero, desde La Sustancia hasta Together\" rel=\"nofollow noopener\" target=\"_blank\">pel\u00edcula<\/a> no est\u00e9 teniendo \u00e9xito en taquilla?<\/p>\n","protected":false},"excerpt":{"rendered":"El pasado 16 de enero aterriz\u00f3 en las salas de cine 28 a\u00f1os despu\u00e9s: El templo de los&hellip;\n","protected":false},"author":2,"featured_media":362956,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[169],"tags":[7350,988,177,987,146,147,25,24,176,4417,175,23,8258],"class_list":["post-362955","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cine","tag-7350","tag-anos","tag-cine","tag-despues","tag-entertainment","tag-entretenimiento","tag-es","tag-espana","tag-film","tag-los","tag-movies","tag-spain","tag-templo"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/115963464533685526","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/362955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=362955"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/362955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/362956"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=362955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=362955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=362955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}