{"id":392727,"date":"2026-02-12T06:34:08","date_gmt":"2026-02-12T06:34:08","guid":{"rendered":"https:\/\/www.europesays.com\/es\/392727\/"},"modified":"2026-02-12T06:34:08","modified_gmt":"2026-02-12T06:34:08","slug":"adios-a-la-superliga-el-madrid-y-la-uefa-llegan-a-un-acuerdo-para-olvidar-el-proyecto-el-pais-expres","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/392727\/","title":{"rendered":"Adi\u00f3s a la Superliga: el Madrid y la UEFA llegan a un acuerdo para olvidar el proyecto | El PA\u00cdS Expr\u00e9s"},"content":{"rendered":"<p><img fetchpriority=\"high\" alt=\"Florentino P\u00e9rez Superliga\" decoding=\"auto\" class=\"_re  a_m-h\" height=\"414\"  width=\"414\"  src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/02\/5I7IRYXGD5HZDAXTNLYBUFTEVY.jpg\" loading=\"eager\"\/>MADRID, 20\/12\/2023.- El presidente del Real Madrid, Florentino P\u00e9rez interviene en la presentaci\u00f3n del XI Coraz\u00f3n Classic Match, estes mi\u00e9rcoles en el estadio Santiago Bernab\u00e9u de Madrid. EFE\/ Mariscal&#13;<br \/>\nMariscal (EFE)<\/p>\n<p class=\"\">El proyecto de la Superliga ha quedado definitivamente enterrado. El Real Madrid, uno de los clubes que lo promovi\u00f3 en 2021, ha emitido un comunicado junto a la UEFA en el que aseguran haber llegado a un acuerdo \u201cpor el bien del f\u00fatbol europeo\u201d.<\/p>\n<p class=\"\"><b>\u00bfQu\u00e9 es la Superliga?<\/b> Fue anunciada en 2021 con la intenci\u00f3n de crear una competici\u00f3n cerrada y dominada por los clubes m\u00e1s poderosos de Europa.<\/p>\n<ul>\n<li>Sin embargo, provoc\u00f3 el rechazo de aficionados, ligas nacionales y de la propia UEFA, que consider\u00f3 que se trataba de un formato elitista y cerrado que no ten\u00eda en cuenta el m\u00e9rito deportivo para participar, al contrario que la Champions.<\/li>\n<\/ul>\n<p class=\"\"><b>Una guerra de cinco a\u00f1os. <\/b>El rechazo de la UEFA era tal que lleg\u00f3 a amenazar a clubes y futbolistas con sanciones si se llevaba a cabo, pero el Madrid insisti\u00f3 en impulsar la competici\u00f3n y lo llev\u00f3 hasta los juzgados.<\/p>\n<ul>\n<li>En 2023 el Tribunal Superior de Justicia de la Uni\u00f3n Europea determin\u00f3 que la UEFA no pod\u00eda impedir la intenci\u00f3n de poner en marcha el nuevo torneo, pero para entonces solo manten\u00edan el empe\u00f1o en \u00e9l el Madrid y el Barcelona.<\/li>\n<\/ul>\n<p class=\"\"><b>Y ahora se pone fin al proyecto.<\/b> El pasado s\u00e1bado, el Barcelona hizo p\u00fablico su distanciamiento definitivo de la iniciativa, y este mi\u00e9rcoles el Madrid firmaba la paz.<\/p>\n<ul>\n<li>Florentino P\u00e9rez y la UEFA han acordado cambios en el modelo del f\u00fatbol europeo y han dado por terminada la batalla legal (el Madrid y A22, empresa promotora del proyecto, reclamaban todav\u00eda m\u00e1s de 4.500 millones de euros a la UEFA por da\u00f1os y perjuicios).<\/li>\n<\/ul>\n<p class=\"\">\u00a9Foto: Mariscal (EFE)<\/p>\n<p class=\"\"><a href=\"https:\/\/elpais.com\/deportes\/futbol\/2026-02-11\/el-real-madrid-y-la-uefa-firman-la-paz-despues-de-cinco-anos-de-disputas-por-la-superliga.html\" target=\"_self\" rel=\"nofollow noopener\" title=\"https:\/\/elpais.com\/deportes\/futbol\/2026-02-11\/el-real-madrid-y-la-uefa-firman-la-paz-despues-de-cinco-anos-de-disputas-por-la-superliga.html\">Si quieres saber m\u00e1s, puedes leer aqu\u00ed.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"MADRID, 20\/12\/2023.- El presidente del Real Madrid, Florentino P\u00e9rez interviene en la presentaci\u00f3n del XI Coraz\u00f3n Classic Match,&hellip;\n","protected":false},"author":2,"featured_media":392728,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[168,25,24,15510,282,3048,23,167,20056,6674],"class_list":{"0":"post-392727","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-deportes","9":"tag-es","10":"tag-espana","11":"tag-florentino-perez","12":"tag-futbol","13":"tag-real-madrid","14":"tag-spain","15":"tag-sports","16":"tag-superliga","17":"tag-uefa"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116056271333887311","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/392727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=392727"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/392727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/392728"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=392727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=392727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=392727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}