{"id":432798,"date":"2026-03-06T19:43:10","date_gmt":"2026-03-06T19:43:10","guid":{"rendered":"https:\/\/www.europesays.com\/es\/432798\/"},"modified":"2026-03-06T19:43:10","modified_gmt":"2026-03-06T19:43:10","slug":"impact-sigue-creciendo-para-consolidar-una-medicina-de-precision-excelente","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/432798\/","title":{"rendered":"IMPaCT sigue creciendo para consolidar una medicina de precisi\u00f3n excelente"},"content":{"rendered":"<p><strong><a href=\"https:\/\/isanidad.com\/362008\/anuario-isanidad-2025-la-sanidad-contada-por-sus-protagonistas\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\">Anuario iSanidad 2025<\/a><br \/>Nieves Sebasti\u00e1n Mongares<\/strong><br \/>Cinco a\u00f1os despu\u00e9s de su puesta en marcha, la Infraestructura de Medicina de Precisi\u00f3n asociada a la Ciencia y la Tecnolog\u00eda (IMPaCT) se ha convertido en una de las grandes apuestas estrat\u00e9gicas de Espa\u00f1a para trasladar la investigaci\u00f3n biom\u00e9dica a la pr\u00e1ctica cl\u00ednica. Esta articula programas en red de medicina predictiva, ciencia de datos y gen\u00f3mica con un objetivo com\u00fan: avanzar hacia una medicina personalizada, equitativa y basada en evidencia.\u00a0Marina Poll\u00e1n, directora del Instituto de Salud Carlos III (ISCIII), hace balance del camino recorrido y expone los pr\u00f3ximos pasos previstos dentro del proyecto.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-363133\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=\" http:=\"\" alt=\"\" width=\"1080\" height=\"200\" data-lazy-src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/Banner-Horizontal-home-anuario-2022-540x100-3.gif\"\/><\/p>\n<p><strong>Hace ya cinco a\u00f1os que se aprob\u00f3 la convocatoria para poner en marcha IMPaCT. \u00bfQu\u00e9 balance hace de este periodo y qu\u00e9 hitos destacar\u00eda dentro del mismo?<br \/><\/strong>La infraestructura IMPaCT se ha consolidado en estos cinco a\u00f1os como un motor fundamental para el desarrollo de la medicina de precisi\u00f3n en Espa\u00f1a. Est\u00e1 impulsada y financiada desde el Instituto de Salud Carlos III (ISCIII), y se desarrolla con el apoyo del Ministerio de Ciencia, Innovaci\u00f3n y Universidades, y del Ministerio de Sanidad. Sus tres programas -Medicina Predictiva, Ciencia de Datos y Medicina Gen\u00f3mica- nos permiten avanzar y responder desde la investigaci\u00f3n a los retos que marca la medicina personalizada.<\/p>\n<p>Junto a la labor de estos tres programas, asociamos a IMPaCT proyectos de investigaci\u00f3n capaces de fomentar la implantaci\u00f3n de diagn\u00f3sticos y terapias personalizadas en el Sistema Nacional de Salud.<\/p>\n<p>\u201cLa infraestructura IMPaCT se ha consolidado en estos cinco a\u00f1os como un motor fundamental para el desarrollo de la medicina de precisi\u00f3n en Espa\u00f1a\u201d<\/p>\n<p><strong>La Cohorte IMPaCT es uno de los pilares del proyecto y aspira a recopilar datos de 200.000 personas durante 20 a\u00f1os. \u00bfC\u00f3mo se est\u00e1 avanzando en este eje y qu\u00e9 cree que pueden aportar los datos del mismo al avance y desarrollo de la medicina de precisi\u00f3n en Espa\u00f1a?<br \/><\/strong>Ya hay m\u00e1s de 26.000 personas reclutadas en este estudio, que cuenta con la colaboraci\u00f3n de 51 centros de salud de atenci\u00f3n primaria distribuidos por toda Espa\u00f1a. El objetivo es, gracias a un reclutamiento aleatorio que garantiza la representatividad poblacional y social de nuestra poblaci\u00f3n, conocer los factores de riesgo de las principales enfermedades que nos afectan como sociedad, aportar informaci\u00f3n para saber c\u00f3mo prevenirlas, desarrollando modelos predictivos para identificar las personas con mayor riesgo y, en general, comprender mejor la salud de la poblaci\u00f3n.<\/p>\n<p>La participaci\u00f3n comienza con la llamada telef\u00f3nica desde el centro de salud a las personas aleatoriamente seleccionadas. Si la persona acepta participar en el estudio, se le realizan diferentes pruebas cl\u00ednicas, recogida de muestras y un cuestionario sobre h\u00e1bitos de vida para obtener datos sobre su estado de salud. Estos datos gen\u00f3micos, cl\u00ednicos y de forma de vida, an\u00f3nimos y confidenciales, servir\u00e1n para impulsar la investigaci\u00f3n, conocer mejor las enfermedades que sufrimos, y hacer estrategias personalizadas de prevenci\u00f3n considerando la diferente probabilidad de enfermar. Adelantarnos en el tiempo para ser capaces de evitar o retrasar la enfermedad y mejorar as\u00ed la salud de la poblaci\u00f3n.<\/p>\n<p>Si recibes una llamada de tu centro de salud, no lo dudes: formando parte de la Cohorte IMPaCT har\u00e1s una gran labor social en beneficio de la ciencia y la salud. Por eso, uno de los lemas de la cohorte es Si te llaman, \u00a1ven!.<\/p>\n<p>\u201cEstos datos gen\u00f3micos, cl\u00ednicos y de forma de vida, an\u00f3nimos y confidenciales, servir\u00e1n para impulsar la investigaci\u00f3n, conocer mejor las enfermedades que sufrimos, y hacer estrategias personalizadas de prevenci\u00f3n\u201d<\/p>\n<p><strong>El segundo eje del plan es el relativo a la ciencia de datos. \u00bfQu\u00e9 herramientas y\/o plataformas se est\u00e1n desarrollando en este \u00e1mbito y qu\u00e9 recomendaciones se han emitido en cuanto al uso de tecnolog\u00edas y est\u00e1ndares para la gesti\u00f3n de los datos?<br \/><\/strong>Este programa apoya la creaci\u00f3n de un sistema com\u00fan, interoperable e integrado, de recogida y an\u00e1lisis de datos biom\u00e9dicos, partiendo del conocimiento y los recursos del Sistema Espa\u00f1ol de Ciencia y Tecnolog\u00eda. Queremos dar mejor respuesta a preguntas de investigaci\u00f3n a partir de los diferentes sistemas de informaci\u00f3n cl\u00ednica y molecular disponibles. Es muy importante consolidar que la comunidad investigadora tenga una perspectiva poblacional de la salud basada en datos individuales.<\/p>\n<p>El Eje IMPaCT-Data ya ha elaborado una serie de recomendaciones y buenas pr\u00e1cticas para la recolecci\u00f3n de informaci\u00f3n de historia cl\u00ednica electr\u00f3nica, garantizando la interoperabilidad de toda esta informaci\u00f3n. Tambi\u00e9n trabaja en el desarrollo de un entorno de investigaci\u00f3n virtual para el an\u00e1lisis de estos datos gen\u00f3micos, de historia cl\u00ednica y de imagen m\u00e9dica. Adem\u00e1s, identifica y\/o desarrolla herramientas de software para analizar esa informaci\u00f3n de forma federada.<\/p>\n<p><strong>La secci\u00f3n de gen\u00f3mica de IMPaCT busca mejorar el diagn\u00f3stico en enfermedades raras, c\u00e1ncer y otras patolog\u00edas gen\u00e9ticas. \u00bfCu\u00e1les son los principales desaf\u00edos en este \u00e1mbito actualmente y c\u00f3mo se est\u00e1 trabajando para darles respuesta?<br \/><\/strong>IMPaCT Gen\u00f3mica impulsa la secuenciaci\u00f3n del genoma completo entre las personas con enfermedades raras o con c\u00e1ncer familiar cuya mutaci\u00f3n no se ha identificado con objeto de avanzar en el posible diagn\u00f3stico que de momento no ha sido posible con las pruebas asistenciales habituales. Con herramientas de alta capacidad y estrategias de an\u00e1lisis gen\u00f3mico m\u00e1s avanzadas, intentamos ofrecer el mejor diagn\u00f3stico gen\u00e9tico para conocer la alteraci\u00f3n que produce esa enfermedad y permitir as\u00ed la b\u00fasqueda de nuevos tratamientos.<\/p>\n<p>\u201cEn sus primeros a\u00f1os de vida, IMPaCT Gen\u00f3mica ha permitido secuenciar el genoma completo de m\u00e1s de 2.000 pacientes con enfermedades raras sin diagn\u00f3stico y pacientes con sospecha de c\u00e1ncer hereditario\u201d<\/p>\n<p>Este programa cuenta con la participaci\u00f3n de m\u00e1s de 300 personas con las que colabora de forma directa, y una red de 110 hospitales de todas las comunidades aut\u00f3nomas. En sus primeros a\u00f1os de vida, IMPaCT Gen\u00f3mica ha permitido secuenciar el genoma completo de m\u00e1s de 2.000 pacientes con enfermedades raras sin diagn\u00f3stico y pacientes con sospecha de c\u00e1ncer hereditario.<\/p>\n<p><strong>Teniendo en cuenta la importancia de la participaci\u00f3n ciudadana, \u00bfc\u00f3mo se est\u00e1 trabajando desde el ISCIII para potenciar esta parte y qu\u00e9 respuesta est\u00e1 ofreciendo la sociedad a la llamada a participar en el proyecto?<br \/><\/strong>Hemos incorporado la participaci\u00f3n ciudadana en IMPaCT desde su dise\u00f1o inicial, porque es clave para la definici\u00f3n de estrategias, desarrollo y comunicaci\u00f3n. La ciudadan\u00eda debe contribuir a la sanidad del futuro a trav\u00e9s de la ciencia abierta: accesible, eficiente, democr\u00e1tica, transparente y din\u00e1mica, con participaci\u00f3n tanto de la comunidad cient\u00edfica como de la sociedad. Tenemos muy claro que hay que garantizar un desarrollo cient\u00edfico que beneficie realmente a las personas, y para ello necesitamos una conexi\u00f3n m\u00e1s estrecha entre investigaci\u00f3n, sociedad y pacientes.<\/p>\n<p>Al respecto, por poner alg\u00fan ejemplo, IMPaCT mantiene relaci\u00f3n con entidades como la Plataforma de Organizaciones de Pacientes, la Federaci\u00f3n Espa\u00f1ola de Enfermedades Raras (Feder) y la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer (AECC).<\/p>\n<p>\u201cCerca de un 50% de personas que reciben la llamada de su centro de salud para colaborar en IMPaCT Cohorte decide participar en el proyecto\u201d<\/p>\n<p>La Cohorte IMPaCT es un claro ejemplo de c\u00f3mo la participaci\u00f3n ciudadana est\u00e1 siendo clave en este proyecto. La tasa de respuesta positiva de las personas a las que llamamos desde Cohorte est\u00e1 siendo much\u00edsimo m\u00e1s alta que en otras iniciativas internacionales similares. Cerca de un 50% de personas que reciben la llamada de su centro de salud para colaborar en IMPaCT Cohorte decide participar en el proyecto. Gracias a ello, ya son m\u00e1s de 26.000 las personas reclutadas. La sociedad est\u00e1 respondiendo de maravilla.<\/p>\n<p><strong>\u00bfC\u00f3mo se coordina el trabajo en red dentro de IMPaCT entre todos los nodos establecidos a nivel nacional? \u00bfC\u00f3mo es la comunicaci\u00f3n con las infraestructuras europeas vinculadas a IMPaCT y qu\u00e9 aporta establecer este tipo de partenariados?<br \/><\/strong>Cada programa de IMPaCT coordina sus nodos, y desde el ISCIII, en el marco de su labor coordinadora, se realizan reuniones de seguimiento, jornadas cient\u00edficas anuales, reuniones conjuntas, eventos informativos y divulgaci\u00f3n de los proyectos de investigaci\u00f3n ligados a IMPaCT. En el \u00e1mbito internacional, no puede faltar la relaci\u00f3n con agentes transnacionales que persiguen objetivos comunes. Por ejemplo, Espa\u00f1a participa en la iniciativa Genome of Europe, y desde IMPaCT aportamos informaci\u00f3n gen\u00f3mica de la secuenciaci\u00f3n de personas que forman parte de la Cohorte.<\/p>\n<p><strong>\u00bfQu\u00e9 herramientas se est\u00e1n usando y c\u00f3mo se est\u00e1 monitorizando el avance de los distintos proyectos enmarcados dentro de IMPaCT?<br \/><\/strong>El ISCIII impulsa y financia la Infraestructura IMPaCT. Como organismo coordinador de esta iniciativa, llevamos a cabo un seguimiento continuado de los tres programas, que trabajan en colaboraci\u00f3n y de manera complementaria, y de todos los proyectos de investigaci\u00f3n que se financian en diferentes \u00e1reas cient\u00edficas.<\/p>\n<p>\u201cComo organismo coordinador de esta iniciativa, llevamos a cabo un seguimiento continuado de los tres programas, que trabajan en colaboraci\u00f3n y de manera complementaria\u201d<\/p>\n<p>Tambi\u00e9n nos apoyamos en el biobanco del ISCIII, que almacena muestras. Se est\u00e1 promoviendo la centralizaci\u00f3n de los datos (gen\u00f3micos, imagen y cl\u00ednicos) obtenidos en IMPaCT Gen\u00f3mica y los datos de los proyectos PMP concedidos en coordinaci\u00f3n con IMPaCT Data para poderlos ofrecer a la comunidad cient\u00edfica como un uso secundario en proyectos en beneficio de la salud de los pacientes y ciudadanos.<\/p>\n<p><strong>A modo de conclusi\u00f3n, \u00bfcu\u00e1les son las principales l\u00edneas o acciones que se est\u00e1n llevando a cabo actualmente y qu\u00e9 conclusiones o resultados se espera poder comunicar en el corto-medio plazo?<br \/><\/strong>Como he se\u00f1alado en anteriores respuestas, IMPaCT sigue creciendo para consolidar en el Sistema Nacional de Salud una medicina de precisi\u00f3n excelente, eficiente, equitativa y sostenible. La continuidad de esta infraestructura es clave para conocer mejor las enfermedades y para cuidar nuestra salud de la mejor manera posible.<\/p>\n<p>Estamos trabajando para disponer de una primera herramienta que visibilice los primeros datos de Cohorte para la comunidad cient\u00edfica, vamos a incorporar m\u00e1s centros de genotipado en la red ya existente, y se va a generar un data lake con los resultados obtenidos en los proyectos de investigaci\u00f3n asociados. En definitiva, los tres programas de IMPaCT seguir\u00e1n aportando conocimiento y evidencia para que Espa\u00f1a siga haciendo de la medicina personalizada una bandera de su ciencia.<\/p>\n<p>Tambi\u00e9n se han elaborado una serie de gu\u00edas sobre an\u00e1lisis gen\u00f3micos y gesti\u00f3n de datos, y modelos sobre informe diagn\u00f3sticos y recomendaciones cl\u00ednicas, siempre garantizando el respeto a los derechos de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"Anuario iSanidad 2025Nieves Sebasti\u00e1n MongaresCinco a\u00f1os despu\u00e9s de su puesta en marcha, la Infraestructura de Medicina de Precisi\u00f3n&hellip;\n","protected":false},"author":2,"featured_media":432799,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[3297,89167,25,24,165,26154,91551,166,23],"class_list":{"0":"post-432798","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salud","8":"tag-a1","9":"tag-anuario2025","10":"tag-es","11":"tag-espana","12":"tag-health","13":"tag-isciii","14":"tag-marina-pollan","15":"tag-salud","16":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116183944809270662","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/432798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=432798"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/432798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/432799"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=432798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=432798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=432798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}