{"id":433728,"date":"2026-03-07T08:16:26","date_gmt":"2026-03-07T08:16:26","guid":{"rendered":"https:\/\/www.europesays.com\/es\/433728\/"},"modified":"2026-03-07T08:16:26","modified_gmt":"2026-03-07T08:16:26","slug":"en-directo-rueda-de-prensa-de-hansi-flick-previa-al-partido-de-laliga-contra-el-athletic","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/433728\/","title":{"rendered":"EN DIRECTO | Rueda de prensa de Hansi Flick previa al partido de LaLiga contra el Athletic"},"content":{"rendered":"<p> Comparecencia de Flick, minuto a minuto<\/p>\n<p class=\"ue-c-article__paragraph \">Muy buenas tardes! Con el eco a\u00fan de las semifinales de la<strong> Copa del Rey,<\/strong> los catalanes se miden ma\u00f1ana al <strong>Athletic<\/strong>. Los azulgranas visitan <strong>San Mam\u00e9s<\/strong> con dos nuevas bajas: <strong>Kound\u00e9 y Balde.<\/strong> En cambio, <strong>Lewandowski <\/strong>podr\u00eda regresa a la lista. El polaco se ejercita desde el mi\u00e9rcoles con una m\u00e1scara protectora por culpa de una fractura \u00f3sea en la cara interna de la \u00f3rbita del ojo izquierdo que sufri\u00f3 contra el <strong>Villarreal<\/strong>. <\/p>\n","protected":false},"excerpt":{"rendered":"Comparecencia de Flick, minuto a minuto Muy buenas tardes! Con el eco a\u00fan de las semifinales de la&hellip;\n","protected":false},"author":2,"featured_media":433729,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[268],"tags":[14283,168,25,24,881,280,282,17435,281,23,167],"class_list":{"0":"post-433728","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-futbol","8":"tag-athletic-de-bilbao","9":"tag-deportes","10":"tag-es","11":"tag-espana","12":"tag-fc-barcelona","13":"tag-football","14":"tag-futbol","15":"tag-lewandowski","16":"tag-soccer","17":"tag-spain","18":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116186905727497576","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/433728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=433728"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/433728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/433729"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=433728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=433728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=433728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}