{"id":434117,"date":"2026-03-07T12:59:18","date_gmt":"2026-03-07T12:59:18","guid":{"rendered":"https:\/\/www.europesays.com\/es\/434117\/"},"modified":"2026-03-07T12:59:18","modified_gmt":"2026-03-07T12:59:18","slug":"asi-son-los-18-primeros-minutos-de-el-ser-querido-la-nueva-pelicula-de-rodrigo-sorogoyen-as-bestas-con-javier-bardem-y-victoria-luengo","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/434117\/","title":{"rendered":"As\u00ed son los 18 primeros minutos de &#8216;El ser querido&#8217;, la nueva pel\u00edcula de Rodrigo Sorogoyen (&#8216;As bestas&#8217;) con Javier Bardem y Victoria Luengo"},"content":{"rendered":"<p data-journey-content=\"true\" data-node-id=\"5\" class=\"css-6wxqfj emevuu60\">Rodrigo Sorogoyen (Madrid, 1981) probablemente tiene dos fechas marcadas en rojo en su calendario de 2026. Una es el 28 de agosto, cuando \u2018El ser querido\u2019, su s\u00e9ptimo largometraje como director en solitario,  llegar\u00e1 a los cines espa\u00f1oles. La otra, el 9 de abril, cuando el Festival de Cannes anunciar\u00e1 las pel\u00edculas seleccionadas para su pr\u00f3xima edici\u00f3n. Entre ambas fechas se mueve la expectativa de una pel\u00edcula que ya genera conversaci\u00f3n mucho antes de su estreno. Prueba de ello fue el encuentro que el cineasta madrile\u00f1o mantuvo este mi\u00e9rcoles en los cines Verdi de la capital con un reducido grupo de periodistas, entre los que se contaba FOTOGRAMAS, para mostrar el arranque de su \u00faltimo trabajo. Despu\u00e9s del fen\u00f3meno \u2018As bestas\u2019, Sorogoyen sigue hurgando en los retratos emocionales y los recodos y desv\u00edos que hay en toda relaci\u00f3n personal con un guion que, como sus anteriores obras, firma junto a Isabel Pe\u00f1a. En este caso, El ser querido arranca con un reencuentro: un padre y una hija, que llevan trece a\u00f1os sin verse, se sientan frente a frente en un restaurante. \u00c9l es Esteban, un director de cine reconocido. Ella, Emilia, una actriz que ha crecido lejos de su abrazo. \u00c9l es Javier Bardem. Ella, Victoria Luengo.<\/p>\n<p><img draggable=\"true\" alt=\"el ser querido\" title=\"el ser querido\" loading=\"lazy\" width=\"4000\" height=\"2400\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/el-ser-querido-pelicula-rodrigo-sorogoyen-javier-bardem-victoria-luengo-69aad17b10e55.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Movistar Plus+<\/p>\n<p>El riesgo como m\u00e9todo<\/p>\n<p data-journey-content=\"true\" data-node-id=\"13\" class=\"css-6wxqfj emevuu60\">La primera secuencia no solo abre la pel\u00edcula; la define y la arranca desde lo m\u00e1s alto, una demostraci\u00f3n de fuerza narrativa que quita el aliento. Para conseguirlo, Sorogoyen decidi\u00f3 que Javier Bardem y Victoria Luengo no ensayaran juntos antes de rodarla: \u201cSon dos personajes que no se ven desde hace 13 a\u00f1os y a m\u00ed me gustaba intentar emular eso de la manera m\u00e1s realista posible\u201d, explic\u00f3 el director, que durante meses trabaj\u00f3 por separado con cada actor. Construy\u00f3 biograf\u00edas completas, recuerdos compartidos y recuerdos divergentes que se despliegan ante el espectador arrastrado a un \u2018in media res\u2019 del que debe sacar sus propias conclusiones.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"17\" class=\"css-6wxqfj emevuu60\">\u201cCreamos muchos recuerdos para uno y muchos recuerdos para la otra, con matices distintos. Como pasa en la vida: yo recuerdo una cosa y otra persona la recuerda de manera distinta, y los dos recuerdos son v\u00e1lidos\u201d, se\u00f1al\u00f3 el director de \u2018Madre\u2019 (2019). La escena se rod\u00f3 el primer d\u00eda, en una sola toma de hora y media, con cinco c\u00e1maras ocultas y sin equipo visible en el restaurante. Hab\u00eda diez p\u00e1ginas de guion; el resto fue improvisaci\u00f3n. \u201cTodo lo que no eran esas diez p\u00e1ginas estaba abierto\u201d, cuenta el cineasta. \u201cPact\u00e9 cosas con cada uno. Mucha informaci\u00f3n que recib\u00eda Javier era nueva, y mucha informaci\u00f3n que recib\u00eda Victoria tambi\u00e9n lo era\u201d, relat\u00f3. El material fue tan contundente que alter\u00f3 la estructura prevista. \u201cNo era la primera escena en el guion. Hab\u00eda tres escenas anteriores, pero al ver esto decidimos quitarlas y empezar as\u00ed, con estas dos <strong data-node-id=\"17.1\">bestias de interpretaci\u00f3n<\/strong>\u201d, afirm\u00f3 en el encuentro con la prensa.<\/p>\n<p><img draggable=\"true\" alt=\"el ser querido\" title=\"el ser querido\" loading=\"lazy\" width=\"2560\" height=\"1609\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/elserquerido-copy-manolopavon-dsc2574web-scaled-6967d04adf640.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Manolo Pav\u00f3n<\/p>\n<p>Un duelo en primer plano<\/p>\n<p data-journey-content=\"true\" data-node-id=\"24\" class=\"css-6wxqfj emevuu60\">Visualmente, la secuencia apuesta por la contenci\u00f3n y la proximidad extrema. Planos cerrados, eje frontal, escorzos que invaden el encuadre contrario. El mundo exterior queda fuera. \u201cNo me interesaba el restaurante, ni los camareros. Me interesaban solo ellos dos. Quer\u00eda que el espectador estuviera atrapado en sus miradas\u201d, explic\u00f3 Sorogoyen de la soluci\u00f3n formal que encontr\u00f3 para una historia que fue escrita pensando en Bardem y Luengo desde el principio. \u201cEran nuestra primera y \u00fanica opci\u00f3n\u201d, reconoci\u00f3. Sobre Bardem, el director destac\u00f3 su forma de trabajar: \u201cHace todas las tomas distintas. Te da un abanico enorme. Y a veces cosas que en rodaje no me funcionaban luego, en montaje, te das cuenta de que eran las buenas\u201d.<\/p>\n<p><img draggable=\"true\" alt=\"el ser querido\" title=\"el ser querido\" loading=\"lazy\" width=\"5000\" height=\"2095\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/el-ser-querido-pelicula-rodrigo-sorogoyen-javier-bardem-69aad13775238.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Movistar Plus+<\/p>\n<p>Cine dentro del cine: experimentar con la forma<\/p>\n<p data-journey-content=\"true\" data-node-id=\"30\" class=\"css-6wxqfj emevuu60\">Tras ese arranque, la acci\u00f3n se trasladar\u00e1 a Fuerteventura. Esteban, el personaje de Bardem dirige una pel\u00edcula ambientada en el S\u00e1hara de los a\u00f1os 30 y propone a su hija participar en ella, interpretando a la protagonista en una decisi\u00f3n en la que, tras esos primeros 18 minutos, parece intentar construir un puente entre ambos. La convivencia profesional es el verdadero campo de tensi\u00f3n. Sorogoyen era consciente del riesgo de caer en el artificio del metacine vac\u00edo.<br data-node-id=\"30.1\"\/><\/p>\n<p data-journey-content=\"true\" data-node-id=\"34\" class=\"css-6wxqfj emevuu60\">\u201cNos daba miedo hacer escenas de rodaje porque s\u00ed. Nos empe\u00f1amos en que en todas hubiera un avance en la relaci\u00f3n entre ellos\u201d, explic\u00f3. La apuesta fue tambi\u00e9n formal. El director detall\u00f3 los cambios de registro que atraviesan la pel\u00edcula: \u201cHemos rodado en todo tipo de formatos: en fotoqu\u00edmica y en digital, en blanco y negro, en cuatro tercios\u2026 Al hacer cine dentro del cine me interesaba utilizar todos los mecanismos posibles, siempre con coherencia\u201d, se\u00f1al\u00f3. \u201cComo estamos hablando del relato, quer\u00eda que la forma tuviera que ver con el fondo, presentar distintas maneras de narrar y de filmar\u201d, a\u00f1adi\u00f3 apuntando que no se trata de un despliegue estil\u00edstico gratuito, sino una manera de cuestionar c\u00f3mo se construyen las historias, dentro y fuera de la pantalla.<\/p>\n<p><img draggable=\"true\" alt=\"el ser querido\" title=\"el ser querido\" loading=\"lazy\" width=\"5000\" height=\"2095\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/el-ser-querido-pelicula-rodrigo-sorogoyen-victoria-luengo-69aad13777148.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Movistar Plus+<\/p>\n<p>La coincidencia con &#8216;Valor sentimental&#8217;<\/p>\n<p data-journey-content=\"true\" data-node-id=\"40\" class=\"css-6wxqfj emevuu60\">Era el elefante en la habitaci\u00f3n, o en este caso en la platea, y no se plante\u00f3 hasta casi finalizar el encuentro: el parecido entre la trama de \u2018El ser querido\u2019 y la de uno de los grandes \u00e9xitos de esta temporada, la noruega \u2018Valor sentimental\u2019 de Joachim Trier, es m\u00e1s que razonable. Ambas cuentan el reencuentro entre un padre y una hija. En las dos \u00e9l es director y ella actriz. Y el nexo de uni\u00f3n entre los personajes es, tanto en una como en la otra, el rodaje de una pel\u00edcula. La coincidencia gener\u00f3 inquietud.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"44\" class=\"css-6wxqfj emevuu60\">\u201cMe acuerdo que estaba rodando \u2018Los a\u00f1os nuevos\u2019, \u2018El ser querido\u2019 ya estaba escrita y pactada\u2026 fue leer la sinopsis y decir: \u2018No puede ser\u2019. Nos afect\u00f3 much\u00edsimo, todo fue un drama, sobre todo para Isabel y para m\u00ed, \u00bfqu\u00e9 hacemos?\u201d. Sin embargo, con el paso del tiempo esa inquietud se transform\u00f3 en aceptaci\u00f3n: \u201cEso fue hace dos a\u00f1os. Nos ha dado tiempo a todo, a aceptarlo. Ahora lo veo como algo divertido, natural; ha pasado en la historia del cine tantas veces\u201d. Y subraya que, m\u00e1s all\u00e1 del punto de partida similar, \u201cson dos pel\u00edculas totalmente distintas\u201d , hasta el punto de que \u201cla gran diferencia es que nuestra pel\u00edcula es el rodaje y \u2018Valor sentimental\u2019 acaba en el rodaje\u201d, dice apuntando que puede resultar \u201cdivertido\u201d que el espectador compare dos miradas distintas que parten de una premisa semejante.<\/p>\n<p><img draggable=\"true\" alt=\"valor sentimental\" title=\"valor sentimental\" loading=\"lazy\" width=\"1600\" height=\"2400\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/valor-sentimental-pelicula-critica-opinion-estreno-cines-692da6ca817a9.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>El\u00e1stica Films<\/p>\n<p>El relato compartido<\/p>\n<p data-journey-content=\"true\" data-node-id=\"50\" class=\"css-6wxqfj emevuu60\">Aunque evita definir la pel\u00edcula de manera cerrada, Sorogoyen apunta a una cuesti\u00f3n central: \u201cEs una historia sobre un padre y una hija, por supuesto, pero tambi\u00e9n sobre qui\u00e9n cuenta el relato y c\u00f3mo a partir de este se construye la memoria\u201d. Terminada desde diciembre, cuando finiquitaron el montaje, esos 18 minutos iniciales que hemos visto de \u2018El ser querido\u2019 son parte fundamental de un metraje que, apuntan sus responsables, llegar\u00e1 a las \u201cdos horas y cuarto\u201d y en ellas podremos ver tambi\u00e9n el trabajo de Ra\u00fal Ar\u00e9valo, Marina Fo\u00efs \u2013que repite con el cineasta tras \u2018As bestas\u2019\u2013, Melina Matthews, Ra\u00fal Prieto o Mourad Ouani, entre otros. De momento, ese principio, Bardem y Luengo frente a frente, sin red, nos permite intuir lo que seguir\u00e1. Lo que falta por ver es si esa continuaci\u00f3n se presentar\u00e1 en mayo en Cannes, el deseo nada escondido de todo el equipo del film. Veremos si la cita francesa tambi\u00e9n tiene marcada en rojo \u2018el ser querido\u2019. <\/p>\n<p><img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/1772888358_469_529eb84f-b022-41e7-830f-afd1eca8f9d8_1740748752.file.png\" alt=\"Headshot of Roger Salvans\" title=\"Headshot of Roger Salvans\" width=\"100%\" height=\"100%\" decoding=\"async\" loading=\"lazy\" class=\"css-o0wq4v ev8dhu53\"\/><\/p>\n<p><a href=\"https:\/\/www.imdb.com\/es-es\/name\/nm1253103\/\" rel=\"nofollow noopener\" target=\"_blank\">Roger Salvans<\/a> es experto en cine y series de TV de ayer, hoy y siempre. Del Hollywood dorado a la generaci\u00f3n de los rebeldes de los a\u00f1os 70 que lo cambiaron todo. Los cl\u00e1sicos ochenteros los indies del cambio de siglo, blockbusters palomiteros \u2013con o sin capa\u2013 o las cintas de autor m\u00e1s rompedoras a las series de culto, consumo masivo y devoci\u00f3n absoluta.<\/p>\n<p><a href=\"https:\/\/www.filmaffinity.com\/es\/name.php?name-id=213435377\" rel=\"nofollow noopener\" target=\"_blank\">Roger<\/a> lleva 20 a\u00f1os escribiendo en las p\u00e1ginas de Fotogramas, revista de la que es actualmente redactor jefe de la edici\u00f3n impresa y para la que ha entrevistado a centenares de directores y estrellas de la gran y peque\u00f1a pantalla: los hermanos Coen, David Fincher, Scarlett Johansson, Paul Mescal, Steven Spielberg, Tim Burton, Martin Scorsese, Leonardo Di Caprio, Christopher Lee, Margot Robbie, Aaron Sorkin, Anya Taylor-Joy y much\u00edsimos m\u00e1s.<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/roger-salvans-ba53a319?originalSubdomain=es\" rel=\"nofollow noopener\" target=\"_blank\">Licenciado en Comunicaci\u00f3n Audiovisual<\/a>, profesor universitario durante 15 a\u00f1os, guionista y periodista con casi tres d\u00e9cadas de experiencia, tambi\u00e9n ha colaborado frecuentemente en distintos medios de radio y TV.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Rodrigo Sorogoyen (Madrid, 1981) probablemente tiene dos fechas marcadas en rojo en su calendario de 2026. Una es&hellip;\n","protected":false},"author":2,"featured_media":434118,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[169],"tags":[177,1180,146,147,25,24,176,175,23],"class_list":{"0":"post-434117","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cine","8":"tag-cine","9":"tag-editorial","10":"tag-entertainment","11":"tag-entretenimiento","12":"tag-es","13":"tag-espana","14":"tag-film","15":"tag-movies","16":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116188018694735204","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/434117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=434117"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/434117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/434118"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=434117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=434117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=434117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}