{"id":448822,"date":"2026-03-15T20:51:18","date_gmt":"2026-03-15T20:51:18","guid":{"rendered":"https:\/\/www.europesays.com\/es\/448822\/"},"modified":"2026-03-15T20:51:18","modified_gmt":"2026-03-15T20:51:18","slug":"el-desaire-de-brooklyn-que-va-a-digustar-y-mucho-a-su-madre-victoria-beckham-en-un-dia-importante","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/448822\/","title":{"rendered":"El desaire de Brooklyn que va a digustar (y mucho) a su madre, Victoria Beckham, en un d\u00eda importante"},"content":{"rendered":"<p id=\"euXEJiB_9y\" data-wc=\"94\">El distanciamiento entre Brooklyn Beckham y su familia vuelve a quedar en evidencia en una fecha especialmente significativa. Este fin de semana, <strong>mientras Reino Unido celebraba el Mothering Sunday,\u00a0<\/strong>el equivalente brit\u00e1nico a nuestro D\u00eda de la Madre, el hijo mayor de David y Victoria Beckham compart\u00eda<strong>\u00a0un cari\u00f1oso mensaje p\u00fablico\u2026 pero no dirigido a su madre, sino a su suegra,\u00a0<\/strong>Claudia Heffner Peltz, que cumpli\u00f3 71 a\u00f1os el pasado 12 de marzo y lo celebr\u00f3 con una fiesta familiar en la que no faltaron ni los globos ni las flores para la homenajeada.<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/cef206beffae-saveclipapp651026558185795441950084145525388736839100978n.jpg\"   width=\"768\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Nicola y su madre Claudia, el d\u00eda de su 71 cumplea\u00f1os\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 nicolaannepeltzbeckhamNicola y su madre Claudia, el d\u00eda de su 71 cumplea\u00f1os<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/7104bbd6e329-saveclipapp651397019185800636510404603205343003286520296n.jpg\"   width=\"576\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Brooklyn, junto a Nicola y Claudia\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 brooklynpeltzbeckhamBrooklyn, junto a Nicola y Claudia<\/p>\n<p id=\"eDhHCprSku1\" data-wc=\"65\">Brooklyn, que reside en Estados Unidos junto a su esposa, Nicola Peltz, desde <a class=\"hm-link ho-link\" href=\"https:\/\/www.hola.com\/novias\/20260120878861\/boda-brooklyn-beckham-nicola-peltz-vestido-victoria-beckham-cancelo\/\" data-mrf-recirculation=\"article-body-link\" rel=\"nofollow noopener\" target=\"_blank\">su boda en 2022,<\/a> public\u00f3 en Instagram una imagen en la que aparece con ella y con la madre de esta. La acompa\u00f1\u00f3 de un mensaje especialmente afectuoso: <strong>\u00abFeliz cumplea\u00f1os a la mejor suegra. Te quiero mucho y espero que hayas tenido el d\u00eda m\u00e1s incre\u00edble\u00bb, <\/strong>rematado con un gran coraz\u00f3n rojo.<\/p>\n<p id=\"eEfe38BNW0d\" data-wc=\"80\">La publicaci\u00f3n podr\u00eda haber pasado desapercibida en otro contexto, pero<strong>\u00a0el hecho de que Brooklyn la compartiera horas antes del D\u00eda de la Madre en Reino Unido ha sido interpretado como un nuevo desaire hacia su madre, Victoria Beckham.<\/strong> La dise\u00f1adora, que siempre ha proyectado una imagen muy unida a sus hijos, no ha recibido ning\u00fan mensaje p\u00fablico de su primog\u00e9nito en una jornada tan se\u00f1alada, a diferencia de David, Romeo, Cruz y Harper, que<a class=\"hm-link ho-link\" href=\"https:\/\/www.hola.com\/actualidad\/20260226886328\/nueva-generacion-beckham-por-que-romeo-cruz-harper-apuntan-superar-legado-padres\/\" data-mrf-recirculation=\"article-body-link\" rel=\"nofollow noopener\" target=\"_blank\">\u00a0s\u00ed le dedicaron emotivas felicitaciones.<\/a><\/p>\n<p id=\"eht4s1ZTd2V\" data-wc=\"54\"><strong>David Beckham<\/strong> comparti\u00f3 una fotograf\u00eda de Victoria embarazada y un mensaje lleno de cari\u00f1o: <strong>\u201cFeliz d\u00eda de la madre a la mam\u00e1 m\u00e1s incre\u00edble\u2026\u00a0<\/strong>Eres una inspiraci\u00f3n en todas las formas que una madre deber\u00eda ser para nuestros cuatro incre\u00edbles hijos. Te queremos mucho y estoy muy agradecido por la familia que hemos creado\u201d.<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/33f99b31fe6f-saveclipapp650730771185951001370249534235554974349731502n.jpg\"   width=\"768\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Imagen de Victoria Beckham embarazada compartida por David\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 davidbeckhamImagen de Victoria Beckham embarazada compartida por David<\/p>\n<p id=\"e-BctNT-KTB\" data-wc=\"101\">Por su parte, <strong>Romeo Beckham\u00a0<\/strong>public\u00f3 una imagen de su infancia, en la que aparece vestido con la equipaci\u00f3n del Manchester Unites en brazos de su madre<strong>: \u201cFeliz d\u00eda de la madre, mam\u00e1. Gracias por todo lo que haces,\u00a0<\/strong>nadie lo hace como t\u00fa. Te quiero mucho\u201d, le dedica a su madre. El joven modelo, que pronto dar\u00e1 su salto al cine y participar\u00e1 en la pel\u00edcula Forty Love junto a <strong>Catherine Deneuve,\u00a0<\/strong>complet\u00f3 su publicaci\u00f3n con una foto junto a sus padres. Cruz Beckham recurri\u00f3 a una fotograf\u00eda de cuando era peque\u00f1o, sin un diente, recibiendo un beso de Victoria.<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/7aabccc6bbd4-saveclipapp651974019183911881601546467626598804025678214n.jpg\"   width=\"576\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Romeo en brazos de Victoria\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 romeobeckhamRomeo en brazos de Victoria<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/17aa345186b1-saveclipapp651521040183911898101546467191268896922851828n.jpg\"   width=\"576\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Romeo Beckham con sus padres\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 romeobeckhamRomeo Beckham con sus padres<\/p>\n<p class=\"\" id=\"emFyIYkyLNT\" data-wc=\"141\">Hasta la benjamina de la familia se acordaba de su madre en este d\u00eda tan se\u00f1alado en Reino Unido, que en Espa\u00f1a celebramos el primer domingo de mayo. Harper Beckham escrib\u00eda en sus redes sociales \u00abFeliz D\u00eda de la Madre a la mejor mam\u00e1 del mundo. <strong>Gracias por estar ah\u00ed para m\u00ed, apoyarme y aguantarme incluso en mis peores d\u00edas.\u00a0<\/strong>No lo digo lo suficiente, pero estoy realmente agradecida por todo lo que haces por m\u00ed cada d\u00eda. Te quiero much\u00edsimo y espero que tengas un d\u00eda maravilloso porque te lo mereces\u201d, junto a una imagen en blanco y negro de madre e hija disfrutando de un paseo acu\u00e1tico. Un post que compart\u00eda despu\u00e9s Victoria con su comunidad virtual y le a\u00f1ad\u00eda un gran coraz\u00f3n rosa. Despu\u00e9s subi\u00f3 una nueva foto en la que madre e hija compart\u00edan un tierno beso.<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/ddfd309b4dea-saveclipapp6510174768422727622060345887618933419935979n.jpg\"   width=\"576\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Victoria y Harper Beckham\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 victoriabeckhamVictoria y Harper Beckham<\/p>\n<p id=\"eELuWMuxVZj\" data-wc=\"116\"><strong>El \u00fanico que no se ha acordado de ella ha sido Brooklyn, quien ha dado la callada por respuesta.\u00a0<\/strong>Aunque s\u00ed que ha felicitado a su suegra. Este silencio no es un hecho aislado. En los \u00faltimos dos a\u00f1os, la ausencia de Brooklyn en momentos familiares importantes se ha convertido en una constante. Tampoco se pronunci\u00f3 p\u00fablicamente para celebrar el reciente \u00e9xito de <a class=\"hm-link ho-link\" href=\"https:\/\/www.hola.com\/actualidad\/20260308888161\/los-beckham-cierran-filas-victoria-paris-brooklyn-fuera-plan-familiar\/\" data-mrf-recirculation=\"article-body-link\" rel=\"nofollow noopener\" target=\"_blank\">Victoria en la Semana de la Moda de Par\u00eds,\u00a0<\/a>un hito profesional que s\u00ed fue destacado por el resto de la familia. Su falta de presencia \u2014tanto f\u00edsica como en redes sociales\u2014 en fechas se\u00f1aladas ha alimentado la percepci\u00f3n de un distanciamiento que, al menos de puertas afuera, parece cada vez m\u00e1s evidente.<\/p>\n<p id=\"ekTXqM1RO6p\" data-wc=\"48\">En este contexto, su cari\u00f1osa felicitaci\u00f3n a su suegra, Claudia Heffner Peltz, contrasta a\u00fan m\u00e1s con su silencio hacia Victoria. Un contraste que vuelve a situar bajo el foco la compleja din\u00e1mica entre Brooklyn y el n\u00facleo familiar Beckham, especialmente en d\u00edas tan simb\u00f3licos como el Mothering Sunday.<\/p>\n<p id=\"e9220O9cQ33\" data-wc=\"106\">La felicitaci\u00f3n a su suegra se suma a otros gestos que muestran la estrecha relaci\u00f3n que el primog\u00e9nito de los Beckham mantiene con su familia pol\u00edtica. Su presencia en la celebraci\u00f3n del cumplea\u00f1os de Claudia Heffner Peltz, que \u00e9l mismo comparti\u00f3 en redes sociales, es una prueba m\u00e1s de qui\u00e9nes ocupan ahora un lugar central en su d\u00eda a d\u00eda. Su vida en Estados Unidos, su dedicaci\u00f3n a proyectos personales, a la cocina, uno de sus hobbies favoritos, y su presencia constante en los eventos familiares de los Peltz han alimentado la sensaci\u00f3n de que <a class=\"hm-link ho-link\" href=\"https:\/\/www.hola.com\/actualidad\/20260119878811\/brooklyn-beckham-rompe-su-silencio-disputa-familiar\/\" data-mrf-recirculation=\"article-body-link\" rel=\"nofollow noopener\" target=\"_blank\">su v\u00ednculo con los Beckham es ahora m\u00e1s distante que nunca.<\/a><\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/03\/3e75bc0bba19-brooklyn-beckham-nicola-peltz-segunda-boda.jpg\"   width=\"768\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Brooklyn Beckham y Nicola Peltz renovaron sus votos en una segunda ceremonia, en 2025, sin David ni Victoria\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 @brooklynpeltzbeckhamBrooklyn Beckham y Nicola Peltz renovaron sus votos en una segunda ceremonia, en 2025, sin David ni Victoria<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/12\/c6d2b3370f31-59042180612224538630603453252615595705881618n.jpg\"   width=\"576\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Brooklyn ahora se dedica a compartir recetas de cocina con sus seguidores\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 brooklynpeltzbeckhamBrooklyn ahora se dedica a compartir recetas de cocina con sus seguidores<\/p>\n<p id=\"e1RyYbGJ-lj\" data-wc=\"109\">Y, m\u00e1s, desde que el pasado mes de enero rompiera definitivamente todos los lazos con ellos despu\u00e9s de un comunicado demoledor en que dejaba claro su deseo de no querer reconciliarse con ellos. Su familia le ha hecho mucho da\u00f1o y \u00a0ha acusado a sus padres de intentar destruir su matrimonio con Nicola Peltz. \u00a0Adem\u00e1s, ha eliminado<a class=\"hm-link ho-link\" href=\"https:\/\/www.hola.com\/actualidad\/20260205882157\/brooklyn-beckham-gesto-demuestra-ruptura-definitiva-con-sus-padres\/\" data-mrf-recirculation=\"article-body-link\" rel=\"nofollow noopener\" target=\"_blank\">\u00a0los tatuajes que llevada dedicados a los suyos,\u00a0<\/a>especialmente el de su padre. Un gesto que muchos han interpretado como un s\u00edmbolo m\u00e1s de la etapa de distanciamiento que atraviesa la relaci\u00f3n entre el primog\u00e9nito y su familia, y que refuerza la impresi\u00f3n de que la brecha entre ambas partes contin\u00faa creciendo.\u00a0<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/02\/dacf69bab045-screenshot49.jpg\"   width=\"686\" height=\"1024\" loading=\"lazy\" decoding=\"async\" alt=\"Brooklyn Beckham\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 brooklynpeltzbeckhamBrooklyn Beckham muestra los tatuajes que lleva en su cuerpo<\/p>\n<p> <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/ed493d549c36-img7068.jpg\"   width=\"1024\" height=\"743\" loading=\"lazy\" decoding=\"async\" alt=\"Brooklyn Beckham y Nicola Peltz\" fetchpriority=\"auto\" class=\"image ho-image\"\/>\u00a9 @brooklynpeltzbeckhamBrooklyn Beckham y Nicola Peltz<\/p>\n","protected":false},"excerpt":{"rendered":"El distanciamiento entre Brooklyn Beckham y su familia vuelve a quedar en evidencia en una fecha especialmente significativa.&hellip;\n","protected":false},"author":2,"featured_media":448823,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[517,3064,255,146,147,25,24,256,23,3063],"class_list":{"0":"post-448822","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-famosos","8":"tag-actualidad","9":"tag-brooklyn-beckham","10":"tag-celebrities","11":"tag-entertainment","12":"tag-entretenimiento","13":"tag-es","14":"tag-espana","15":"tag-famosos","16":"tag-spain","17":"tag-victoria-beckham"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116235173117165093","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/448822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=448822"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/448822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/448823"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=448822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=448822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=448822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}