{"id":480643,"date":"2026-04-03T16:04:17","date_gmt":"2026-04-03T16:04:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/480643\/"},"modified":"2026-04-03T16:04:17","modified_gmt":"2026-04-03T16:04:17","slug":"los-medicos-coinciden-cuando-bebes-alcohol-las-neuronas-se-atrofian-y-pierdes-la-capacidad-de-crear-nuevos-recuerdos","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/480643\/","title":{"rendered":"Los m\u00e9dicos coinciden: \u201cCuando bebes alcohol las neuronas se atrofian y pierdes la capacidad de crear nuevos recuerdos\u201d"},"content":{"rendered":"<p class=\"\">El <b>alcohol <\/b>es una sustancia qu\u00edmica cuyo consumo, sobre todo aquel que se produce de forma continuada y repetida a lo largo del tiempo, se traduce en la <b>aparici\u00f3n de perjuicios y problemas de salud<\/b> en las personas afectadas. Lo grave no est\u00e1 en beber una bebida alcoh\u00f3lica de vez en cuando, sino en <b>repetir este acto de manera diaria, sin tener en cuenta unas consecuencias que, tarde o temprano, acaban llegando<\/b>.<\/p>\n<p class=\"\">En este contexto, los m\u00e9dicos comparten una opini\u00f3n similar: si podemos evitar consumir alcohol, mejor que mejor. As\u00ed, <b>Jorge \u00c1ngel, Nicol\u00e1s Badillo y Jos\u00e9 Manuel Felices<\/b> se han establecido como tres de los profesionales de la salud m\u00e1s vocales a la hora de mencionar <b>los diferentes problemas para la salud que puede ocasionar el consumo continuado de bebidas sazonadas con alcohol<\/b>.<\/p>\n<p>Jorge \u00c1ngel: \u201cNeurona que muere, neurona que no vuelve\u201d<img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/04\/KKIB3EBFEJCNBJRGSJDVFR5VWM.jpg\" alt=\"Los m\u00e9dicos coinciden: \u201cCuando bebes alcohol las neuronas se atrofian y pierdes la capacidad de crear nuevos recuerdos\u201d\" height=\"675\" width=\"1200\"   loading=\"lazy\"\/><\/p>\n<p class=\"\"><b>\u201cEl alcohol causa p\u00e9rdida de memoria a corto-largo plazo, dificultad para el aprendizaje, agresividad, p\u00e9rdida en la coordinaci\u00f3n y el equilibrio, reducci\u00f3n del n\u00famero y el tama\u00f1o de las neuronas. Neurona que muere, neurona que no vuelve\u201d<\/b>, explica Jorge \u00c1ngel, quien, a continuaci\u00f3n, afirma que <b>\u201cel alcohol es un depresor del sistema nervioso central\u201d<\/b>.<\/p>\n<p class=\"\">El enfermero, tras asegurar que todos estos efectos se multiplican <b>\u201csi eres menor de 18 a\u00f1os\u201d<\/b>, lanza un mensaje que, a menudo, muchos olvidan o se esfuerzan por no recordar o pasar por alto: <b>\u201cUna cosa es echarse una cerveza de vez en cuando, que tampoco va a pasar nada, que beber continuamente. El alcohol es mal\u00edsimo para el cerebro y para el resto del organismo\u201d,<\/b> concluye.<\/p>\n<p>Para Nicol\u00e1s Badillo el alcohol es \u201cilegal\u201d<img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/04\/TZ6SHV3GKRDITJ7AJZQK7OGGQA.jpg\" alt=\"Los m\u00e9dicos coinciden: \u201cCuando bebes alcohol las neuronas se atrofian y pierdes la capacidad de crear nuevos recuerdos\u201d\" height=\"675\" width=\"1200\"   loading=\"lazy\"\/><\/p>\n<p class=\"\">Pasando a la opini\u00f3n de <b>Nicol\u00e1s Badillo<\/b>, el m\u00e9dico se\u00f1ala que, adem\u00e1s del cerebro, el intestino y las hormonas tambi\u00e9n se ven afectadas por la ingesta de alcohol: <b>\u201cEst\u00e1 relacionado con ciertos tipos de c\u00e1ncer. Si el alcohol lo descubri\u00e9ramos hoy, ser\u00eda ilegal o no ser\u00eda tan socialmente aceptado\u201d<\/b>, indica.<\/p>\n<p class=\"\"><b>\u201cHay una zona que se llama la corteza prefrontal que se encarga de controlar nuestros pensamientos, cuando tomamos alcohol ese control se inactiva por eso, puedes decir cosas que no quieres decir o hacer cosas que no deber\u00edas haber hecho\u201d, <\/b>a\u00f1ade Badillo, quien, para terminar, afirma que esta sustancia hace que estamos <b>\u201cm\u00e1s ansiosos y m\u00e1s estresados\u201d<\/b>.<\/p>\n<p>Jos\u00e9 Manuel Felices, en la l\u00ednea de Jorge \u00c1ngel<img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/04\/KYZHTIBM6ZDK5F4YBEXUGFEILQ.jpeg\" alt=\"Los m\u00e9dicos coinciden: \u201cCuando bebes alcohol las neuronas se atrofian y pierdes la capacidad de crear nuevos recuerdos\u201d\" height=\"5464\" width=\"4371\"   loading=\"lazy\"\/><\/p>\n<p class=\"\"><b>Jos\u00e9 Manuel Felices<\/b>, al igual que Jorge \u00c1ngel, centra su atenci\u00f3n en la capacidad que posee el alcohol para atrofiar nuestra cerebro y nuestra neuronas: <b>\u201cCuando bebes alcohol se bloquean los receptores de la zona de memoria, por lo que el cerebro no consigue darle al bot\u00f3n de guardar, y por eso se provocan esas lagunas tan t\u00edpicas de un d\u00eda de borrachera\u201d<\/b>, inicia.<\/p>\n<p>Noticias relacionadas<img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/04\/3VP6V22YH5CE5GTFKYWPVFNPHI.jpg\" alt=\"\" class=\"\" height=\"9\" width=\"16\"   loading=\"lazy\" data-tb-thumbnail=\"\"\/><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/04\/SXPBPT7A3JBPTJW7ZVQ5GWHFLA.jpg\" alt=\"\" class=\"\" height=\"9\" width=\"16\"   loading=\"lazy\" data-tb-thumbnail=\"\"\/><\/p>\n<p class=\"\"><b>\u201cCada vez que consumes alcohol hay neuronas de esa zona que se atrofian.<\/b> Y al atrofiarse se pierde la materia gris y se sustituye por l\u00edquido. (&#8230;) <b>Pierdes tu capacidad para crear nuevos recuerdos, te despides de los que ten\u00edas almacenados<\/b>, te hace olvidar qui\u00e9n eres y tambi\u00e9n eres incapaz de almacenar todos los buenos momentos que tengas desde hoy. <b>Te hace dejar de ser t\u00fa\u201d<\/b>, concluye.<\/p>\n<p class=\"\"><b>\u00a1Tus opiniones importan!<\/b> Comenta en los art\u00edculos y suscr\u00edbete gratis a nuestra <a href=\"https:\/\/asfan.as.com\/newsletters\/\" target=\"_blank\" rel=\"nofollow noopener\" title=\"https:\/\/asfan.as.com\/newsletters\/\">newsletter<\/a> y a las alertas informativas en la <a href=\"https:\/\/as.com\/aplicacion-de-as-n\/\" target=\"_blank\" rel=\"nofollow noopener\" title=\"https:\/\/as.com\/aplicacion-de-as-n\/\">App<\/a> o el canal de <a href=\"https:\/\/www.whatsapp.com\/channel\/0029VaAasdA7j6g745nz9M10\" target=\"_blank\" rel=\"nofollow noopener\" title=\"https:\/\/www.whatsapp.com\/channel\/0029VaAasdA7j6g745nz9M10\">WhatsApp<\/a>. \u00bfBuscas licenciar contenido? Haz clic <a href=\"https:\/\/profesional.elpais.com\/landing-sindicacion?utm_medium=interno&amp;utm_source=crosslinking&amp;utm_campaign=sindicacion_as_pie_articulos\" target=\"_blank\" rel=\"nofollow noopener\" title=\"https:\/\/profesional.elpais.com\/landing-sindicacion?utm_medium=interno&amp;utm_source=crosslinking&amp;utm_campaign=sindicacion_as_pie_articulos\">aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"El alcohol es una sustancia qu\u00edmica cuyo consumo, sobre todo aquel que se produce de forma continuada y&hellip;\n","protected":false},"author":2,"featured_media":480644,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[25,24,165,166,23],"class_list":{"0":"post-480643","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salud","8":"tag-es","9":"tag-espana","10":"tag-health","11":"tag-salud","12":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116341628562786032","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/480643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=480643"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/480643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/480644"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=480643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=480643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=480643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}