{"id":486537,"date":"2026-04-07T08:12:19","date_gmt":"2026-04-07T08:12:19","guid":{"rendered":"https:\/\/www.europesays.com\/es\/486537\/"},"modified":"2026-04-07T08:12:19","modified_gmt":"2026-04-07T08:12:19","slug":"cribado-de-cancer-de-colon-y-la-edad","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/486537\/","title":{"rendered":"Cribado de c\u00e1ncer de colon y la edad"},"content":{"rendered":"<p><strong>La edad no debe ser el factor determinante para animar a la participaci\u00f3n en programas de cribado de <a href=\"https:\/\/unav.acblnk.com\/url\/ver\/939205850\/3694977\/abb8368b1b007253ae46c845478cf3c1\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">c\u00e1ncer de colon<\/a><\/strong>. Esa es la principal conclusi\u00f3n de un estudio del \u00c1rea de C\u00e1ncer Gastrointestinal del Cancer Center Cl\u00ednica Universidad de Navarra (CCUN) que propone tener en cuenta, adem\u00e1s, otras variables como el sexo masculino, el test positivo de sangre oculta en heces o el tabaquismo.<\/p>\n<p>Los facultativos lo justifican con los datos de una <strong>investigaci\u00f3n que ha demostrado la elevada prevalencia de lesiones neopl\u00e1sicas de colon en mayores de 65 a\u00f1os<\/strong> que no se hab\u00edan sometido a una colonoscopia. Estas lesiones son crecimientos anormales de tejido producidos por una proliferaci\u00f3n descontrolada de c\u00e9lulas que, aunque no siempre son cancerosas, pueden ser el paso previo.<\/p>\n<p>El <strong>cribado de c\u00e1ncer colorrectal<\/strong> ha demostrado reducir la incidencia y la mortalidad asociada a la enfermedad. Sin embargo, existe un debate en la comunidad cient\u00edfica sobre si sigue siendo beneficioso cuando se supera la edad habitual de finalizaci\u00f3n, que suele situarse en torno a los 69 a\u00f1os. Por eso, <strong>los autores han estudiado la prevalencia de lesiones neopl\u00e1sicas de colon en personas a partir de los 65 a\u00f1os<\/strong> que no se hab\u00edan sometido a una colonoscopia previa.<\/p>\n<p>Los resultados, obtenidos como parte de un trabajo final de grado presentado en la Facultad de Medicina de la Universidad de Navarra, han mostrado una alta frecuencia de este tipo de lesiones, ya que se <strong>detectaron adenomas en el 42,8% de los pacientes, adenomas avanzados en el 7% y c\u00e1ncer invasivo en el 2,7%<\/strong>. Seg\u00fan ha concluido la Dra. Maite Herr\u00e1iz, directora del Departamento de Digestivo de la Cl\u00ednica, \u201ces necesario <strong>personalizar el cribado en personas mayores en lugar de basarlo \u00fanicamente en la edad <\/strong>porque, adem\u00e1s, las lesiones se observan con mayor prevalencia en varones y en personas con test de sangre oculta en heces positivo. Tambi\u00e9n ser\u00eda importante considerar otras variables, como el tabaquismo y la situaci\u00f3n cl\u00ednica del paciente\u201d.<\/p>\n<p>Por eso, el Dr. Jos\u00e9 Mar\u00eda Riesco, codirector el Departamento de Digestivo, a\u00f1ade que, \u201cla constancia en el cribado de c\u00e1ncer colorrectal es clave, y ese seguimiento debe ser individualizado y adoptado junto con el m\u00e9dico, porque el riesgo no desaparece y hay factores que pueden influir en la aparici\u00f3n de la enfermedad del paciente m\u00e1s all\u00e1 de la edad\u201d.<\/p>\n<p>Del diagn\u00f3stico a la terapia<\/p>\n<p>Actualmente, el c\u00e1ncer de colon es el tumor m\u00e1s frecuente en Espa\u00f1a, pero tambi\u00e9n <strong>una de las neoplasias m\u00e1s prevenibles y tratables si se detecta a tiempo<\/strong>. Uno de los pilares preventivos fundamentales sigue siendo el cribado poblacional, basado en pruebas no invasivas, como el test de sangre oculta en heces. Este procedimiento permite identificar a pacientes con riesgo y derivarlos a la realizaci\u00f3n de una colonoscopia, optimizando los recursos sanitarios y aumentando la capacidad de detecci\u00f3n precoz.<\/p>\n<p>Gracias a la implementaci\u00f3n del cribado, como <strong><a href=\"https:\/\/unav.acblnk.com\/url\/ver\/939205857\/3694977\/abb8368b1b007253ae46c845478cf3c1\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">destaca la Sociedad Espa\u00f1ola de Oncolog\u00eda M\u00e9dica<\/a><\/strong>, <strong>la mortalidad por c\u00e1ncer de colon se ha reducido un 20% en nuestro pa\u00eds en las \u00faltimas dos d\u00e9cadas<\/strong>. En este tiempo, la colonoscopia se ha convertido en una t\u00e9cnica menos invasiva y con unos protocolos de preparaci\u00f3n m\u00e1s sencillos. \u201cLa gran ventaja es que, si detectamos p\u00f3lipos durante la prueba, podemos extirparlos en el mismo momento, evitando que evolucionen hasta convertirse en c\u00e1ncer\u201d, destaca la Dra. Herr\u00e1iz.<\/p>\n<p>Con estos avances, <strong>la endoscopia se consolida tambi\u00e9n como una de las opciones terap\u00e9utica prioritarias de prevenci\u00f3n<\/strong>, ofreciendo una alternativa a la cirug\u00eda en determinados casos. \u201cHoy podemos curar lesiones complejas mediante t\u00e9cnicas m\u00ednimamente invasivas, como la disecci\u00f3n endosc\u00f3pica submucosa, que permite extirpar p\u00f3lipos de gran tama\u00f1o y lesiones tumorales muy superficiales de colon y recto sin necesidad de realizar incisiones ni extirpar parte del intestino. Este enfoque reduce las complicaciones y mejora la recuperaci\u00f3n de los pacientes\u201d, se\u00f1ala el Dr. Riesco, responsable tambi\u00e9n de la Unidad de Endoscopia Digestiva de la Cl\u00ednica Universidad de Navarra.<\/p>\n","protected":false},"excerpt":{"rendered":"La edad no debe ser el factor determinante para animar a la participaci\u00f3n en programas de cribado de&hellip;\n","protected":false},"author":2,"featured_media":486538,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[5738,25,24,165,1294,166,23],"class_list":{"0":"post-486537","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salud","8":"tag-al-dia","9":"tag-es","10":"tag-espana","11":"tag-health","12":"tag-investigacion","13":"tag-salud","14":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116362421803369973","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/486537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=486537"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/486537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/486538"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=486537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=486537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=486537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}