{"id":52293,"date":"2025-08-16T22:06:14","date_gmt":"2025-08-16T22:06:14","guid":{"rendered":"https:\/\/www.europesays.com\/es\/52293\/"},"modified":"2025-08-16T22:06:14","modified_gmt":"2025-08-16T22:06:14","slug":"ciudad-real-puerta-grande-para-el-cid-y-emilio-de-justo-en-una-tarde-infumable-de-juan-pedro","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/52293\/","title":{"rendered":"Ciudad Real: Puerta grande para El Cid y Emilio de Justo en una tarde infumable de Juan Pedro"},"content":{"rendered":"<p><strong>FICHA DEL FESTEJO<\/strong><\/p>\n<p>Ciudad Real \u2013 Feria Taurina Virgen del Prado 2025<\/p>\n<p>S\u00e1bado, 16 de agosto. Plaza de toros de Ciudad Real. Primera de abono. Un cuarto largo de entrada en tarde muy calurosa. Presidencia para Diego Ortega.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/E2961BEF-7C4D-4018-8DF771BC327E70E1.JPEG\" alt=\"Primera de abono de la feria taurina en honor a la Virgen del Prado\" border=\"0\"\/>Primera de abono de la feria taurina en honor a la Virgen del Prado &#8211; Foto: Rueda Villaverde<\/p>\n<p>Se lidiaron seis toros de Juan Pedro Domecq, feos de tipo, pobres de presentaci\u00f3n, mansos, sin clase y con poco juego; s\u00f3lo primero y segundo ofrecieron algo m\u00e1s de trap\u00edo y emoci\u00f3n en la muleta.<\/p>\n<p>Manuel Jes\u00fas El Cid, de azul pavo y oro: oreja y oreja (estocada y estocada).<\/p>\n<p>Emilio de Justo, de blanco y azabache: dos orejas y silencio (estocada y pinchazo; media estocada y descabello a la segunda).<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/28AEC5F6-2943-46D7-8E26C4550D7AFD09.JPEG\" alt=\"Primera de abono de la feria taurina en honor a la Virgen del Prado\" border=\"0\"\/>Primera de abono de la feria taurina en honor a la Virgen del Prado &#8211; Foto: Rueda Villaverde<\/p>\n<p>Marco P\u00e9rez, de blanco y oro: palmas y oreja (estocada defectuosa y estocada trasera tras pinchazo).<\/p>\n<p>El Cid abr\u00eda cartel, en sustituci\u00f3n de Cayetano, y lo hizo con Narc\u00f3tico, toro de escasa transmisi\u00f3n al que salud\u00f3 por ver\u00f3nicas que fueron cogiendo vuelo en las dos \u00faltimas, con media de buen trazo. El quite, tambi\u00e9n a la ver\u00f3nica, no dijo mucho m\u00e1s. Malos pares. Brind\u00f3 al respetable y comenz\u00f3 por el derecho con un toro rebrincado, al que le encasquet\u00f3 tres tandas sin bajarle la mano que fueron calentando al respetable.<\/p>\n<p>Se vino abajo por el izquierdo, donde el toro se quedaba corto, y aunque lo intent\u00f3 de nuevo por el pit\u00f3n bueno, ya no hab\u00eda nada que rascar. En los compases finales se dobl\u00f3 con \u00e9l y le arranc\u00f3 un muletazo con gusto. Mat\u00f3 de estoconazo. Faena cumplidora, de esas que en los papeles se llamaban aseadas. Oreja.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/49F04449-1108-4970-B22F9882375D767D.JPEG\" alt=\"Primera de abono de la feria taurina en honor a la Virgen del Prado\" border=\"0\"\/>Primera de abono de la feria taurina en honor a la Virgen del Prado &#8211; Foto: Rueda Villaverde<\/p>\n<p>El segundo, Zancudo, fue para Emilio de Justo. Lo salud\u00f3 con dos ver\u00f3nicas y unas chicuelinas sin ajuste en los medios. Lo dej\u00f3 crudo y Morenito de Arl\u00e9s salud\u00f3 por su par. La faena comenz\u00f3 con una tanda de acople que cerr\u00f3 con dos soberbios pases de pecho. En la siguiente, lo mejor volvi\u00f3 a ser el remate. El toro met\u00eda la cara, ten\u00eda nobleza y un punto de transmisi\u00f3n. Por el izquierdo ya no era lo mismo, se quedaba al hilo y sin decir ni p\u00edo.<\/p>\n<p>Cuando parec\u00eda que todo iba para una oreja, como mucho, sin historia, se tir\u00f3 De Justo a matar y se llev\u00f3 tres revolcones de los que dejan al cuerpo tiritando. Se le apareci\u00f3 la Virgen del Prado, porque pudo matarlo. Lanz\u00f3 un beso al cielo y se le premi\u00f3 con dos orejas que no lo eran. Como mucho una, y gracias. Pero valieron m\u00e1s los revolcones que los muletazos. Puerta grande de hospital, que le cost\u00f3 el pase a la enfermer\u00eda.<\/p>\n<p>Tercero, Malospasos, para Marco P\u00e9rez. Y vaya si los tuvo. Lo quiso recibir por tafalleras, pero el toro no cuaj\u00f3. Intent\u00f3 despu\u00e9s ver\u00f3nicas a pies juntos sin \u00e9xito. La puya fue impropia y mal recetada. El salmantino no lo vio claro y le hizo un quite que pes\u00f3 m\u00e1s que ayud\u00f3. Faena sin contenido, sin estructura y sin toro. Mat\u00f3 a la tercera con una estocada defectuosa. Palmas, por educaci\u00f3n.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/D23B372E-4185-4222-A45E680EAD78A58B.JPEG\" alt=\"Primera de abono de la feria taurina en honor a la Virgen del Prado\" border=\"0\"\/>Primera de abono de la feria taurina en honor a la Virgen del Prado &#8211; Foto: Rueda Villaverde<\/p>\n<p>El cuarto se raj\u00f3 en cuanto lo mandaron al caballo. In\u00e9dito en el capote, el toro se dej\u00f3 lo justo. Malas banderillas. El Cid se puso enseguida con la zurda, pero el de Juan Pedro se met\u00eda por dentro con peligro sordo. Embest\u00eda por arriba, cabeceando al final, lo que quitaba toda emoci\u00f3n a lo que pod\u00eda tener de cierto temple.<\/p>\n<p>Le sac\u00f3 alg\u00fan natural con aguante que coquete\u00f3 con la hondura hasta que el toro cant\u00f3 la gallina en los medios y ah\u00ed se acab\u00f3 todo. Le propin\u00f3 una estocada algo tendida. Otra oreja, por honradez y por salvar los muebles.<\/p>\n<p>El quinto, bautizado como Lacerado, fue el peor de todos. Sali\u00f3 parado, sin chispa. Ovaci\u00f3n a Juan Bernal, que fue derribado y qued\u00f3 atrapado entre caballo y tablas en una situaci\u00f3n complicada, aunque recet\u00f3 el \u00fanico meido puyazo decente de los seis. La lidia de Morenito de Arl\u00e9s fue la mejor de la tarde y los pares de Neiro y Valcarce estuvieron a la altura.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/22AE5464-BE06-4D43-A4ABD2A3FE69F817.JPEG\" alt=\"Primera de abono de la feria taurina en honor a la Virgen del Prado\" border=\"0\"\/>Primera de abono de la feria taurina en honor a la Virgen del Prado &#8211; Foto: Rueda Villaverde<\/p>\n<p>Pero el toro era protest\u00f3n, rebrinc\u00f3n y rajado desde el principio. Sin fijeza, sin humillar, con la cara por arriba. Nada que hacer. Pinchazo, media estocada y descabello a la segunda. Bronca al toro. Silencio para De Justo.<\/p>\n<p>Cerr\u00f3 la infumable corrida Sabihondo, y lo pareci\u00f3: desde la tercera ver\u00f3nica ya se hablaba en los tendidos de \u00abtoro gaseosa\u00bb. Marco P\u00e9rez lo recibi\u00f3 con intenci\u00f3n al verlo al galope con cierto tranco, ppero el animal cay\u00f3 de manos y se desfond\u00f3 antes de tiempo.<\/p>\n<p>En varas, bronca por el leve y vergonzoso puyazo que le solt\u00f3 Alberto Sandoval. Banderillas sin pena ni gloria. Marco cit\u00f3 en los medios con pase del p\u00e9ndulo buscando levantar al p\u00fablico, pero aquello no tiraba.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/E52A0034-2E61-4BD7-B481DEBC7A29A3D6.JPEG\" alt=\"Primera de abono de la feria taurina en honor a la Virgen del Prado\" border=\"0\"\/>Primera de abono de la feria taurina en honor a la Virgen del Prado &#8211; Foto: Rueda Villaverde<\/p>\n<p>Por la derecha sac\u00f3 alg\u00fan muletazo con m\u00e1s temple que colocaci\u00f3n, sin bajarle la mano. Por el izquierdo, nada. Faena neoteorera, deslavazada, sin encaje y con el toro en las lejan\u00edas cortada por el mismo patr\u00f3n de casi siempre. La ovaci\u00f3n fue de medio tendido que compra los argumentos. Pinchazo y estocada trasera. Oreja por insistencia.<\/p>\n<p>M\u00e1s fotos:<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/48C5E333-4B81-417A-A0EE26F9F2CD0CE1.JPG\" alt=\"Puerta grande de El Cid y Emilio de Justo en tarde de petardo\" border=\"0\"\/>Puerta grande de El Cid y Emilio de Justo en tarde de petardo &#8211; Foto: Rueda  Villaverde<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/4EB5C1A7-2456-42C4-81ABCAE4FCB8C4FA.JPG\" alt=\"Puerta grande de El Cid y Emilio de Justo en tarde de petardo\" border=\"0\"\/>Puerta grande de El Cid y Emilio de Justo en tarde de petardo &#8211; Foto: Rueda  Villaverde<\/p>\n<p>Una tarde sin contenido y sin emoci\u00f3n, de esas que se olvidan pronto. La falta de raza en los animales, la escasa presencia y la nula clase en las embestidas marcaron un festejo que naufrag\u00f3 desde la salida del primer toro. Cuando no hay fondo ni toro, todo lo dem\u00e1s se vuelve accesorio. Arranca la feria, s\u00ed, pero lo hace con el paso cambiado y sin nada que llevarse a la boca m\u00e1s all\u00e1 del calor y el hast\u00edo.<\/p>\n","protected":false},"excerpt":{"rendered":"FICHA DEL FESTEJO Ciudad Real \u2013 Feria Taurina Virgen del Prado 2025 S\u00e1bado, 16 de agosto. Plaza de&hellip;\n","protected":false},"author":2,"featured_media":52294,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[277],"tags":[373,1940,168,25,24,1389,23,167,374,444],"class_list":{"0":"post-52293","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-toreo","8":"tag-bullfighting","9":"tag-ciudad-real","10":"tag-deportes","11":"tag-es","12":"tag-espana","13":"tag-plaza-de-toros","14":"tag-spain","15":"tag-sports","16":"tag-toreo","17":"tag-toros"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/52293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=52293"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/52293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/52294"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=52293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=52293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=52293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}