{"id":527727,"date":"2026-05-01T17:49:12","date_gmt":"2026-05-01T17:49:12","guid":{"rendered":"https:\/\/www.europesays.com\/es\/527727\/"},"modified":"2026-05-01T17:49:12","modified_gmt":"2026-05-01T17:49:12","slug":"salarios-agentes-libres-y-extensiones-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/527727\/","title":{"rendered":"Salarios, agentes libres y extensiones"},"content":{"rendered":"<p>Tras ser eliminados por los Knicks, los Atlanta Hawks tienen un verano repleto de decisiones que tomar en el mercado. <\/p>\n<p>Los Atlanta Hawks han cerrado una temporada m\u00e1s positiva de lo que cabr\u00eda esperar tras mover a Trae Young y alzar el vuelo al final de la campa\u00f1a.<\/p>\n<p>Atlanta arranc\u00f3 con un balance positivo (13-8), pero pronto se estabiliz\u00f3 en torno al 50 %. El traspaso de Young cambi\u00f3 el rumbo del equipo, que encontr\u00f3 en Jalen Johnson a su principal referente, firmando cifras cercanas a 20 puntos, 10 rebotes y 8 asistencias. La llegada de CJ McCollum y el crecimiento de Nickeil Alexander-Walker impulsaron al grupo, que lleg\u00f3 a encadenar once victorias consecutivas para asegurar la sexta plaza del Este y evitar el play-in.<\/p>\n<p>En Playoffs, el equipo compiti\u00f3 por encima de lo esperado, llegando a ponerse 2-1 en la serie. Sin embargo, sus limitaciones estructurales, especialmente en el juego interior, terminaron siendo decisivas. La falta de presencia en la pintura, con Onyeka Okongwu y Tony Bradley como principales referencias, condicion\u00f3 sus opciones.<\/p>\n<p>En este v\u00eddeo analizamos tambi\u00e9n la situaci\u00f3n de la franquicia de cara al mercado. Con margen salarial suficiente, Atlanta deber\u00e1 priorizar renovaciones clave, tomar decisiones sobre sus agentes libres y abordar el draft con dos selecciones relevantes. La necesidad de reforzar el juego interior y a\u00f1adir creaci\u00f3n ofensiva se presenta como prioritaria.<\/p>\n<p>Todo apunta a un verano importante para definir el siguiente paso de unos Hawks que han sido competitivos, pero que a\u00fan est\u00e1n lejos de consolidarse como aspirantes reales en la Conferencia Este.<\/p>\n<p>Los contratos de Atlanta Hawks en la temporada 2026-27<\/p>\n<tr>\n<td><strong>Jugador<\/strong><\/td>\n<td><strong>2026-27<\/strong><\/td>\n<td><strong>2027-28<\/strong><\/td>\n<td><strong>2028-29<\/strong><\/td>\n<td><strong>2029-30<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Jalen Johnson<\/td>\n<td>$30,000,000<\/td>\n<td>$30,000,000<\/td>\n<td>$30,000,000<\/td>\n<td>$30,000,000<\/td>\n<\/tr>\n<tr>\n<td>Dyson Daniels<\/td>\n<td>$25,000,000<\/td>\n<td>$25,000,000<\/td>\n<td>$25,000,000<\/td>\n<td>$25,000,000<\/td>\n<\/tr>\n<tr>\n<td>Jonathan Kuminga<\/td>\n<td>$24,300,000 (TO)<\/td>\n<td\/>\n<td\/>\n<td\/><\/tr>\n<tr>\n<td>Onyeka Okongwu<\/td>\n<td>$16,120,000<\/td>\n<td>$16,880,000<\/td>\n<td\/>\n<td\/><\/tr>\n<tr>\n<td>Nickeil Alexander-Walker<\/td>\n<td>$14,403,710<\/td>\n<td>$15,161,800<\/td>\n<td>$15,919,890 (PO)<\/td>\n<td\/><\/tr>\n<tr>\n<td>Corey Kispert<\/td>\n<td>$13,975,000<\/td>\n<td>$13,050,000<\/td>\n<td>$13,050,000<\/td>\n<td\/><\/tr>\n<tr>\n<td>Zaccharie Risacher<\/td>\n<td>$13,826,040<\/td>\n<td>$17,434,637<\/td>\n<td\/>\n<td\/><\/tr>\n<tr>\n<td>Buddy Hield<\/td>\n<td>$9,658,536<\/td>\n<td>$10,097,560 (PO)<\/td>\n<td\/>\n<td\/><\/tr>\n<tr>\n<td>Asa Newell<\/td>\n<td>$3,399,480<\/td>\n<td>$3,560,880<\/td>\n<td>$6,042,814<\/td>\n<td\/><\/tr>\n<tr>\n<td>Mouhamed Gueye<\/td>\n<td>$2,406,205 (TO)<\/td>\n<td\/>\n<td\/>\n<td\/><\/tr>\n<p>Los agentes libres de Atlanta Hawks<\/p>\n<ul class=\"wp-block-list\">\n<li>CJ McCollum <\/li>\n<li>Gabe Vincent<\/li>\n<li>Tony Bradley<\/li>\n<li>Keaton Wallace <\/li>\n<li>Jonathan Kuminga. Opci\u00f3n de equipo.<\/li>\n<li>Mo Gueye. Opci\u00f3n de equipo<\/li>\n<\/ul>\n<p>La situaci\u00f3n salarial de Atlanta Hawks<\/p>\n<ul class=\"wp-block-list\">\n<li>Salarios: 153 millones<\/li>\n<li>47,9 millones de margen sobre el lujo<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Tras ser eliminados por los Knicks, los Atlanta Hawks tienen un verano repleto de decisiones que tomar en&hellip;\n","protected":false},"author":2,"featured_media":527728,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[299,298,168,25,24,1725,23,167],"class_list":{"0":"post-527727","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-baloncesto","8":"tag-baloncesto","9":"tag-basketball","10":"tag-deportes","11":"tag-es","12":"tag-espana","13":"tag-nba","14":"tag-spain","15":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116500586102270269","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/527727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=527727"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/527727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/527728"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=527727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=527727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=527727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}