{"id":535770,"date":"2026-05-06T05:20:20","date_gmt":"2026-05-06T05:20:20","guid":{"rendered":"https:\/\/www.europesays.com\/es\/535770\/"},"modified":"2026-05-06T05:20:20","modified_gmt":"2026-05-06T05:20:20","slug":"atades-visita-el-entrenamiento-del-real-zaragoza-real-zaragoza","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/535770\/","title":{"rendered":"ATADES visita el entrenamiento del Real Zaragoza | Real Zaragoza"},"content":{"rendered":"<p>El entrenamiento de este martes del <strong>Real Zaragoza<\/strong> ha contado con la visita de medio centenar de usuarios del <strong>Centro Ocupacional y Residencia Santo \u00c1ngel de ATADES<\/strong> a la Ciudad Deportiva.<\/p>\n<p>Esta delegaci\u00f3n ha podido ver los \u00faltimos minutos de la sesi\u00f3n del equipo y, al t\u00e9rmino de la misma, se han podido fotografiar, pedir aut\u00f3grafos y pasar un agradable rato con los jugadores y miembros del cuerpo t\u00e9cnico.<\/p>\n<p>Un chute de energ\u00eda de cara al duelo clave que disputar\u00e1 el Real Zaragoza frente al Real Valladolid este pr\u00f3ximo s\u00e1bado. <strong>\u00a1Gracias, ATADES, por vuestro aliento y compa\u00f1\u00eda en estos momentos!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"El entrenamiento de este martes del Real Zaragoza ha contado con la visita de medio centenar de usuarios&hellip;\n","protected":false},"author":2,"featured_media":535771,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[168,25,24,23,167],"class_list":{"0":"post-535770","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-deportes","9":"tag-es","10":"tag-espana","11":"tag-spain","12":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116525952488453608","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/535770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=535770"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/535770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/535771"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=535770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=535770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=535770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}