{"id":535890,"date":"2026-05-06T07:00:17","date_gmt":"2026-05-06T07:00:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/535890\/"},"modified":"2026-05-06T07:00:17","modified_gmt":"2026-05-06T07:00:17","slug":"anticorrupcion-defendera-en-su-informe-una-rebaja-de-la-pena-a-aldama-mayor-que-la-que-pide-en-su-escrito","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/535890\/","title":{"rendered":"Anticorrupci\u00f3n defender\u00e1 en su informe una rebaja de la pena a Aldama mayor que la que pide en su escrito"},"content":{"rendered":"<p class=\"article-text\">\n        \u201cNo, no. Erratas ortogr\u00e1ficas no hab\u00eda ninguna que corregir\u201d, dijo con media sonrisa el fiscal jefe Anticorrupci\u00f3n, Alejandro Luz\u00f3n, cuando el presidente del tribunal le pregunt\u00f3 sobre los cambios en su escrito de conclusiones. En realidad, a\u00f1adi\u00f3, no eran cambios sustanciales los que hab\u00eda hecho, pero s\u00ed que afectaban al relato de hechos porque lo ampliaba. Pero si por Luz\u00f3n hubiera sido, las conclusiones que defender\u00e1 este mi\u00e9rcoles en el Supremo para exigir una condena para el exministro Jos\u00e9 Luis \u00c1balos, para su asesor Koldo Garc\u00eda y para el empresario V\u00edctor de Aldama, ser\u00edan diferentes. Habr\u00eda incluido mayores rebajas de pena para el empresario comisionista porque considera que, adem\u00e1s de que sus manifestaciones son \u201crelevantes y veraces\u201d, han sido ratificadas y completadas en la vista oral.\n    <\/p>\n<p>    <a href=\"https:\/\/www.eldiario.es\/politica\/abalos-critica-impostura-permanente-aldama-e-insinua-jesica-rodriguez-pacto-declaracion-supremo_1_13192199.html\" data-mrf-recirculation=\"saber-mas\" data-dl-event=\"saber-mas\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p class=\"know-more__title\">\u00c1balos critica la \u201cimpostura permanente\u201d de Aldama e insin\u00faa que J\u00e9sica Rodr\u00edguez pact\u00f3 con \u00e9l su declaraci\u00f3n en el Supremo<\/p>\n<p>            <img decoding=\"async\" class=\"lazy\" loading=\"lazy\" data-src=\"https:\/\/static.eldiario.es\/clip\/4d9c0c8f-a5e6-4deb-a189-29286005f0e9_16-9-aspect-ratio_default_0.jpg\" src=\"data:image\/svg+xml,%3Csvg xmlns=\" http:=\"\" viewbox=\"0 0 880 495\" alt=\"\u00c1balos critica la \u201cimpostura permanente\u201d de Aldama e insin\u00faa que J\u00e9sica Rodr\u00edguez pact\u00f3 con \u00e9l su declaraci\u00f3n en el Supremo\"\/><\/p>\n<p>                        <\/a><\/p>\n<p class=\"article-text\">\n        Despu\u00e9s de que el pasado lunes trascendiera que la fiscal general del Estado, Teresa Peramato, logr\u00f3 que Luz\u00f3n no modificara su escrito de conclusiones para incluir la atenuante muy cualificada que permitiera minorar la petici\u00f3n de c\u00e1rcel para Aldama, este mi\u00e9rcoles se pasa de pantalla. Llega el momento de los informes finales y el juicio se aproxima al &#8216;visto para sentencia&#8217;.\n    <\/p>\n<p class=\"article-text\">\n        El fiscal jefe anticorrupci\u00f3n Alejandro Luz\u00f3n ser\u00e1 quien abra la sesi\u00f3n con su informe y, seg\u00fan las fuentes fiscales consultadas por elDiario.es, se ce\u00f1ir\u00e1 a desgranar y valorar las pruebas recabadas a lo largo de la instrucci\u00f3n y de la vista oral intentando no extenderse demasiado. Lo esperable. Pero habr\u00e1 sorpresa en su exposici\u00f3n porque har\u00e1 especial menci\u00f3n al papel trascendental que ha jugado Aldama para la causa y, de alguna manera, defender\u00e1 que a su juicio s\u00ed merec\u00eda una mayor rebaja en la pena de la que ha quedado plasmada en su informe.\n    <\/p>\n<p class=\"article-text\">\n        En su escrito de acusaci\u00f3n -previo a la vista oral y que siempre es susceptible de ser modificado por el devenir del juicio- solicitaba siete a\u00f1os de c\u00e1rcel para Aldama aplic\u00e1ndole la atenuante de confesi\u00f3n del delito que permit\u00eda rebajar las penas: Cuatro a\u00f1os por organizaci\u00f3n criminal, tres a\u00f1os por un delito continuado de cohecho activo y una multa de 3,7 millones de euros por el delito de aprovechamiento de informaci\u00f3n privilegiada.\n    <\/p>\n<p class=\"article-text\">\n        El c\u00e1lculo se mantiene. Pero el lunes, en la exposici\u00f3n de la prueba documental, se pudo constatar que Luz\u00f3n s\u00ed toc\u00f3 el relato de manera que hac\u00eda hincapi\u00e9 en las aportaciones de Aldama durante la causa. Como muestra un bot\u00f3n, destacaba que el comisionista sostuvo que habr\u00eda reintegrado los pagos realizados por el entorno de Koldo Garc\u00eda del alquiler del piso que disfrut\u00f3 en Plaza de Espa\u00f1a la expareja de \u00c1balos, J\u00e9sica Rodr\u00edguez.\n    <\/p>\n<p class=\"article-text\">\n        Tambi\u00e9n se fijaba el fiscal en que determinadas aseveraciones del comisionista se han visto respaldadas por la prueba pericial y documental practicada. As\u00ed, incluy\u00f3 que la pericial caligr\u00e1fica confirm\u00f3 en el plenario que la letra manuscrita que aparec\u00eda en un listado sobre obra p\u00fablica que aport\u00f3 Aldama era, tal y como sostuvo, del propio Koldo Garc\u00eda.\n    <\/p>\n<p class=\"article-text\">\n        Y a\u00f1ad\u00eda Luz\u00f3n que se han incluido en la causa audios relativos al caso que se sigue en la Audiencia Nacional contra Santos Cerd\u00e1n sobre posibles mordidas a cambio de adjudicaciones p\u00fablicas. Explicaba que en el plenario se trat\u00f3 la pericial ac\u00fastica y electr\u00f3nica de los mismos, y dice que esos audios (grabados en secreto por Koldo Garc\u00eda y localizados por la Guardia Civil en el registro de su domicilio) encajan con lo declarado por Aldama durante el juicio.\n    <\/p>\n<p>    \u201cMantiene y completa\u201d su reconocimiento<\/p>\n<p class=\"article-text\">\n        Pero quiz\u00e1 la frase clave que a\u00f1adi\u00f3 Luz\u00f3n a su escrito sea la que reza: \u201cEl reconocimiento de los hechos ha sido mantenido y completado en su declaraci\u00f3n prestada en calidad de acusado el pasado 29 de abril de 2026 en este juicio oral\u201d.\n    <\/p>\n<p class=\"article-text\">\n        Con esas modificaciones incluidas en su escrito de conclusiones definitivas y con la exposici\u00f3n que realice este mi\u00e9rcoles, las fuentes consultadas esperan que esas \u201cmanifestaciones relevantes\u201d de Aldama puedan influir en los siete magistrados que componen el tribunal sentenciador de manera que opten por una mayor rebaja de pena para el comisionista. Entienden que la Sala puede valorar y decidir si aplica la atenuante muy cualificada.\n    <\/p>\n<p class=\"article-text\">\n        En caso de que entraran a deliberar ese aspecto, muletas no les faltan a los magistrados. La acusaci\u00f3n popular, cuya direcci\u00f3n letrada ostenta el PP, ya solicit\u00f3 el lunes que se aplicara la atenuante muy cualificada por su confesi\u00f3n y colaboraci\u00f3n con la justicia, y acomod\u00f3 las penas que ped\u00eda para el comisionista de manera que ning\u00fan delito superara los dos a\u00f1os de c\u00e1rcel. En el caso de que la condena se ajustara a lo que pide el PP, el tribunal tendr\u00e1 la \u00faltima palabra a la hora de decidir si pisa c\u00e1rcel con delitos individuales que no llegan a esos dos a\u00f1os. Y eso teniendo en cuenta que la suma de los siete delitos que le imputan suman cinco a\u00f1os y dos meses de prisi\u00f3n.\n    <\/p>\n<p>    <a href=\"https:\/\/www.eldiario.es\/politica\/pp-rebaja-peticion-pena-aldama-manera-evitaria-prision_1_13194542.html\" data-mrf-recirculation=\"saber-mas-abajo\" data-dl-event=\"saber-mas-abajo\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p class=\"know-more__title\">El PP rebaja la petici\u00f3n de pena a Aldama para intentar que no entre en prisi\u00f3n<\/p>\n<p>            <img decoding=\"async\" class=\"lazy\" loading=\"lazy\" data-src=\"https:\/\/static.eldiario.es\/clip\/63e945e9-819e-4515-8327-b408185825d3_16-9-aspect-ratio_default_0.jpg\" src=\"data:image\/svg+xml,%3Csvg xmlns=\" http:=\"\" viewbox=\"0 0 880 495\" alt=\"El PP rebaja la petici\u00f3n de pena a Aldama para intentar que no entre en prisi\u00f3n\"\/><\/p>\n<p>                        <\/a><\/p>\n<p class=\"article-text\">\n        Y dado que este juicio ofrece contrastes dif\u00edciles de encajar, en el otro extremo est\u00e1 la postura de la defensa de Koldo Garc\u00eda, que el lunes indic\u00f3 en el plenario, con cierta sorna, que si se modificaba la petici\u00f3n de pena para Aldama deb\u00eda ser para aumentarla porque la Unidad Central Operativa (UCO) de la Guardia Civil ubica al comisionista como el jefe real de la trama: \u201cQuien paga manda\u201d.\n    <\/p>\n","protected":false},"excerpt":{"rendered":"\u201cNo, no. Erratas ortogr\u00e1ficas no hab\u00eda ninguna que corregir\u201d, dijo con media sonrisa el fiscal jefe Anticorrupci\u00f3n, Alejandro&hellip;\n","protected":false},"author":2,"featured_media":535891,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[15778,2314,17,18,25,24,13,14,11,8803,19,20,9,10,15,16,23,12,21,22],"class_list":{"0":"post-535890","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-titulares","8":"tag-aldama","9":"tag-anticorrupcion","10":"tag-breaking-news","11":"tag-breakingnews","12":"tag-es","13":"tag-espana","14":"tag-featured-news","15":"tag-featurednews","16":"tag-headlines","17":"tag-informe","18":"tag-latest-news","19":"tag-latestnews","20":"tag-news","21":"tag-noticias","22":"tag-noticias-destacadas","23":"tag-noticiasdestacadas","24":"tag-spain","25":"tag-titulares","26":"tag-ultimas-noticias","27":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116526345455771045","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/535890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=535890"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/535890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/535891"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=535890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=535890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=535890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}