{"id":537785,"date":"2026-05-07T07:46:11","date_gmt":"2026-05-07T07:46:11","guid":{"rendered":"https:\/\/www.europesays.com\/es\/537785\/"},"modified":"2026-05-07T07:46:11","modified_gmt":"2026-05-07T07:46:11","slug":"un-nuevo-crispr-actua-como-interruptor-letal-que-destruye-el-adn-de-celulas-enfermas","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/537785\/","title":{"rendered":"Un nuevo CRISPR act\u00faa como \u2018interruptor letal\u2019 que destruye el ADN de c\u00e9lulas enfermas"},"content":{"rendered":"<p>A diferencia del conocido sistema CRISPR Cas9, que act\u00faa como unas tijeras moleculares para modificar el ADN, Cas12a2 funciona como una trituradora. Cuando reconoce una secuencia diana \u2014en este caso un ARN espec\u00edfico\u2014 se activa y provoca da\u00f1os masivos en el genoma que conducen a la muerte celular. Los resultados se publican en la revista\u00a0Nature.<\/p>\n<p>Atacar\u00a0c\u00e9lulas enfermas sin da\u00f1ar las sanas<\/p>\n<p>\u201cSu objetivo no es corregir nada, sino destruir todo lo que ve\u201d, explica a SINC\u00a0<a href=\"https:\/\/liu.biochem.utah.edu\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Yang Liu<\/strong><\/a>,\u00a0bioqu\u00edmico de Utah Health y coautor senior. Seg\u00fan detalla, Cas12a2\u00a0act\u00faa como un \u2018kill switch\u2019, un mecanismo molecular que activa la muerte celular al reconocer una secuencia de ARN, lo que desencadena da\u00f1o masivo en el ADN. Adem\u00e1s, puede distinguir\u00a0<strong>cambios m\u00ednimos en el c\u00f3digo gen\u00e9tico<\/strong>, lo que permite atacar c\u00e9lulas enfermas sin da\u00f1ar las sanas.<\/p>\n<p>El origen de este hallazgo se remonta a estudios en bacterias. \u201cEn 2023 se descubri\u00f3 que Cas12a2 pod\u00eda provocar la muerte celular como parte del sistema inmunitario bacteriano\u201d, se\u00f1ala Liu.\u00a0<\/p>\n<p><a href=\"https:\/\/wa.me\/?text=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Solo%20se%20pone%20en%20marcha%20cuando%20detecta%20una%20secuencia%20muy%20concreta.%20Puede%20distinguir%20incluso%20diferencias%20de%20una%20sola%20letra%20en%20el%20c%C3%B3digo%20gen%C3%A9tico:+https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;via=agencia_sinc&amp;text=Solo%20se%20pone%20en%20marcha%20cuando%20detecta%20una%20secuencia%20muy%20concreta.%20Puede%20distinguir%20incluso%20diferencias%20de%20una%20sola%20letra%20en%20el%20c%C3%B3digo%20gen%C3%A9tico\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;t=Solo%20se%20pone%20en%20marcha%20cuando%20detecta%20una%20secuencia%20muy%20concreta.%20Puede%20distinguir%20incluso%20diferencias%20de%20una%20sola%20letra%20en%20el%20c%C3%B3digo%20gen%C3%A9tico\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;title=Solo%20se%20pone%20en%20marcha%20cuando%20detecta%20una%20secuencia%20muy%20concreta.%20Puede%20distinguir%20incluso%20diferencias%20de%20una%20sola%20letra%20en%20el%20c%C3%B3digo%20gen%C3%A9tico&amp;summary=Solo%20se%20pone%20en%20marcha%20cuando%20detecta%20una%20secuencia%20muy%20concreta.%20Puede%20distinguir%20incluso%20diferencias%20de%20una%20sola%20letra%20en%20el%20c%C3%B3digo%20gen%C3%A9tico&amp;source=agencia_sinc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Un-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas#\" rel=\"nofollow noopener\" target=\"_blank\">Su equipo decidi\u00f3 comprobar si ese mecanismo pod\u00eda trasladarse a c\u00e9lulas humanas, pese a sus complejos sistemas de reparaci\u00f3n del ADN. El momento clave lleg\u00f3 cuando observaron da\u00f1o masivo en el n\u00facleo celular. \u201cFue un aut\u00e9ntico<strong>\u00a0momento eureka<\/strong>\u201d, recuerda.<\/p>\n<p>La clave de su potencial terap\u00e9utico reside en la\u00a0<strong>precisi\u00f3n<\/strong>. Aunque la enzima destruye el ADN de forma indiscriminada una vez activada, solo se pone en marcha cuando detecta una secuencia muy concreta. \u201cPuede distinguir incluso diferencias de una sola letra en el c\u00f3digo gen\u00e9tico\u201d, afirma Liu.<\/p>\n<p>Esto permite dirigirla contra mutaciones espec\u00edficas del c\u00e1ncer o contra ARN virales sin afectar a c\u00e9lulas sanas, aunque advierte que ser\u00e1 necesario evaluar cuidadosamente posibles efectos no deseados en cada aplicaci\u00f3n.<\/p>\n<p>Contra tumores y virus<\/p>\n<p>En experimentos con c\u00e9lulas humanas, los investigadores lograron reducir en un 50 % el crecimiento de c\u00e9lulas de c\u00e1ncer de pulm\u00f3n con mutaciones en el gen KRAS, un resultado comparable al de f\u00e1rmacos como el cisplatino, pero sin da\u00f1ar c\u00e9lulas sanas. En paralelo, al dirigir Cas12a2 contra el virus del papiloma humano (VPH), eliminaron m\u00e1s del 90 % de las c\u00e9lulas infectadas en cultivos.<\/p>\n<p><a href=\"https:\/\/wa.me\/?text=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=En%20experimentos%20con%20c%C3%A9lulas%20humanas%2C%20los%20investigadores%20lograron%20reducir%20en%20un%2050%20%25%20el%20crecimiento%20de%20c%C3%A9lulas%20de%20c%C3%A1ncer%20de%20pulm%C3%B3n%20con%20mutaciones%20en%20el%20gen%20KRAS:+https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;via=agencia_sinc&amp;text=En%20experimentos%20con%20c%C3%A9lulas%20humanas%2C%20los%20investigadores%20lograron%20reducir%20en%20un%2050%20%25%20el%20crecimiento%20de%20c%C3%A9lulas%20de%20c%C3%A1ncer%20de%20pulm%C3%B3n%20con%20mutaciones%20en%20el%20gen%20KRAS\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;t=En%20experimentos%20con%20c%C3%A9lulas%20humanas%2C%20los%20investigadores%20lograron%20reducir%20en%20un%2050%20%25%20el%20crecimiento%20de%20c%C3%A9lulas%20de%20c%C3%A1ncer%20de%20pulm%C3%B3n%20con%20mutaciones%20en%20el%20gen%20KRAS\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;title=En%20experimentos%20con%20c%C3%A9lulas%20humanas%2C%20los%20investigadores%20lograron%20reducir%20en%20un%2050%20%25%20el%20crecimiento%20de%20c%C3%A9lulas%20de%20c%C3%A1ncer%20de%20pulm%C3%B3n%20con%20mutaciones%20en%20el%20gen%20KRAS&amp;summary=En%20experimentos%20con%20c%C3%A9lulas%20humanas%2C%20los%20investigadores%20lograron%20reducir%20en%20un%2050%20%25%20el%20crecimiento%20de%20c%C3%A9lulas%20de%20c%C3%A1ncer%20de%20pulm%C3%B3n%20con%20mutaciones%20en%20el%20gen%20KRAS&amp;source=agencia_sinc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Un-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas#\" rel=\"nofollow noopener\" target=\"_blank\">Los ensayos tambi\u00e9n muestran que este m\u00e9todo puede funcionar en modelos animales. La inyecci\u00f3n de Cas12a2 en tumores infectados por VPH en ratones ralentiz\u00f3 su crecimiento, lo que sugiere su\u00a0<strong>posible aplicaci\u00f3n en organismos vivos<\/strong>.<\/p>\n<p>Frente a la quimioterapia, que da\u00f1a tanto c\u00e9lulas sanas como tumorales, Cas12a2 ofrece una alternativa m\u00e1s dirigida. \u201cPuede programarse para eliminar solo las c\u00e9lulas no deseadas\u201d, subraya Liu. A diferencia de herramientas como Cas9, dise\u00f1adas para reparar genes, esta nueva prote\u00edna tiene como objetivo eliminar c\u00e9lulas problem\u00e1ticas, lo que la hace\u00a0<strong>especialmente \u00fatil en c\u00e1ncer<\/strong>.<\/p>\n<p>M\u00e1s all\u00e1 de la oncolog\u00eda, el sistema podr\u00eda adaptarse a otras enfermedades. \u201cVemos un gran potencial en terapias personalizadas contra el c\u00e1ncer, pero tambi\u00e9n en infecciones virales\u201d, apunta el investigador. Incluso plantea aplicaciones en\u00a0<strong>enfermedades neurodegenerativas o relacionadas con el envejecimiento<\/strong>, mediante la eliminaci\u00f3n de c\u00e9lulas da\u00f1inas.<a\/><\/p>\n<p>Mejora de la edici\u00f3n gen\u00e9tica<\/p>\n<p>Otra de sus aplicaciones inmediatas podr\u00eda ser mejorar la propia edici\u00f3n gen\u00e9tica. El equipo ha demostrado que Cas12a2 puede eliminar las c\u00e9lulas que no han sido correctamente editadas, lo que aumenta la eficacia de t\u00e9cnicas como la edici\u00f3n gen\u00e9tica cl\u00e1sica o las m\u00e1s recientes, como la edici\u00f3n de bases (base editing), utilizada para\u00a0<a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Estas-son-las-diez-personas-mas-relevantes-para-la-ciencia-en-2025-segun-Nature\" rel=\"nofollow noopener\" target=\"_blank\">curar un beb\u00e9 de una enfermedad ultrarrara en 2025<\/a>. \u201cPodr\u00eda enriquecer las c\u00e9lulas corregidas y potenciar el efecto terap\u00e9utico global\u201d, explica Liu.<\/p>\n<p><a href=\"https:\/\/wa.me\/?text=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=El%20equipo%20ha%20demostrado%20que%20Cas12a2%20puede%20eliminar%20las%20c%C3%A9lulas%20que%20no%20han%20sido%20correctamente%20editadas:+https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;via=agencia_sinc&amp;text=El%20equipo%20ha%20demostrado%20que%20Cas12a2%20puede%20eliminar%20las%20c%C3%A9lulas%20que%20no%20han%20sido%20correctamente%20editadas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;t=El%20equipo%20ha%20demostrado%20que%20Cas12a2%20puede%20eliminar%20las%20c%C3%A9lulas%20que%20no%20han%20sido%20correctamente%20editadas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fwww.agenciasinc.es%2FNoticias%2FUn-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas&amp;title=El%20equipo%20ha%20demostrado%20que%20Cas12a2%20puede%20eliminar%20las%20c%C3%A9lulas%20que%20no%20han%20sido%20correctamente%20editadas&amp;summary=El%20equipo%20ha%20demostrado%20que%20Cas12a2%20puede%20eliminar%20las%20c%C3%A9lulas%20que%20no%20han%20sido%20correctamente%20editadas&amp;source=agencia_sinc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Un-nuevo-CRISPR-actua-como-interruptor-letal-que-destruye-el-ADN-de-celulas-enfermas#\" rel=\"nofollow noopener\" target=\"_blank\">Este avance se produce en un contexto de r\u00e1pida evoluci\u00f3n de las herramientas CRISPR. En los \u00faltimos a\u00f1os han surgido tecnolog\u00edas capaces de corregir mutaciones sin cortar el ADN y ya se han aplicado en\u00a0<strong>casos cl\u00ednicos experimentales<\/strong>. En este panorama, Cas12a2 aporta una v\u00eda complementaria: no reparar, sino eliminar.<\/p>\n<p>Aun as\u00ed, quedan<strong>\u00a0importantes desaf\u00edos antes de su uso cl\u00ednico<\/strong>. La mayor\u00eda de los experimentos se han realizado en cultivos celulares y ser\u00e1 necesario demostrar su seguridad y eficacia en organismos completos. Adem\u00e1s, la entrega de la prote\u00edna a los tejidos adecuados sigue siendo un obst\u00e1culo clave.<\/p>\n<p>Pese a ello, el objetivo es ambicioso. \u201cCurar lo incurable\u201d, concluye Liu.<\/p>\n<p><strong>Referencia<\/strong>:<\/p>\n<p>Yang Liu et al.\u00a0RNA-triggered cell killing with CRISPR\u2013Cas12a2.\u00a0<a href=\"https:\/\/www.nature.com\/articles\/s41586-026-10466-y\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Nature<\/a>, 2026.<\/p>\n<p>Fuente:\u00a0<strong>SINC<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"A diferencia del conocido sistema CRISPR Cas9, que act\u00faa como unas tijeras moleculares para modificar el ADN, Cas12a2&hellip;\n","protected":false},"author":2,"featured_media":537786,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[1066,47570,25,24,165,105263,166,23,2275],"class_list":{"0":"post-537785","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salud","8":"tag-cancer","9":"tag-crispr","10":"tag-es","11":"tag-espana","12":"tag-health","13":"tag-muerte-celular","14":"tag-salud","15":"tag-spain","16":"tag-virus"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/537785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=537785"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/537785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/537786"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=537785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=537785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=537785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}