{"id":539602,"date":"2026-05-08T07:06:12","date_gmt":"2026-05-08T07:06:12","guid":{"rendered":"https:\/\/www.europesays.com\/es\/539602\/"},"modified":"2026-05-08T07:06:12","modified_gmt":"2026-05-08T07:06:12","slug":"barcelona-tiene-en-sus-manos-el-derrumbe-de-real-madrid","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/539602\/","title":{"rendered":"Barcelona tiene en sus manos el derrumbe de Real Madrid"},"content":{"rendered":"<p class=\"mb-4 text-lg md:leading-8 break-words\">Este fin de semana, <b>Barcelona<\/b> tiene en sus manos el derrumbe de <b>Real Madrid<\/b>. Si los cul\u00e9s ganan El Cl\u00e1sico, programado para el 10 de mayo, asegurar\u00e1n el campeonato de <b>LaLiga <\/b>de Espa\u00f1a y, de paso, dejar\u00e1n a los merengues sin t\u00edtulo por primera vez en cinco a\u00f1os.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">LaLiga vivir\u00e1 su jornada 35 de 38 entre este viernes y domingo. El partido m\u00e1s atractivo no s\u00f3lo para Espa\u00f1a, sino para todo el mundo, es El Cl\u00e1sico, que se disputar\u00e1 en el estadio Spotify Camp Nou.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Por historial (106 triunfos para Real Madrid y 105 para Barcelona, adem\u00e1s de 52 empates) luce como un partido parejo. Sin embargo, el presente de ambos los coloca muy distantes.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Barcelona acumula 88 puntos y si empata o gana El Cl\u00e1sico 264 ya nadie lo podr\u00e1 alcanzar en las restantes tres jornadas de la temporada 2025-26.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Esto significar\u00eda el t\u00edtulo 29 de Barcelona en la primera divisi\u00f3n de Espa\u00f1a, acerc\u00e1ndose un poco m\u00e1s a los 36 del l\u00edder hist\u00f3rico, Real Madrid.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Los merengues, en contraste, necesitan aferrarse al triunfo. Llegan a El Cl\u00e1sico con 77 puntos y empatar o perder significar\u00eda ceder el trofeo de LaLiga a su ac\u00e9rrimo rival por segunda temporada consecutiva. Ya no importar\u00eda si Real Madrid triunfa en sus partidos restantes contra <b>Oviedo<\/b>, <b>Sevilla <\/b>y <b>Athletic de Bilbao<\/b>.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cVeo al equipo muy bien, entrenando mentalizados y concentrados para este partido, que es muy importante para nosotros y para la afici\u00f3n. Se tiene que ir al 200% para ganarlo\u201d, expres\u00f3 el canterano cul\u00e9, Gavi.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">No s\u00f3lo eso. Enfatiz\u00f3 el anhelo del plantel por ganar sus partidos restantes (Real Madrid, Alav\u00e9s, Betis y Valencia) para alcanzar 100 puntos, cifra que \u00fanicamente han logrado en la temporada 2012-13, bajo la direcci\u00f3n t\u00e9cnica de Tito Vilanova. Ahora el entrenador es Hansi Flick.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cEstamos haciendo un temporad\u00f3n y tenemos que ganar todo lo que queda para repetir algo hist\u00f3rico como una liga con 100 puntos\u201d, complement\u00f3 el mediocampista de 21 a\u00f1os.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Barcelona s\u00f3lo ha perdido uno de los \u00faltimos seis partidos contra Real Madrid en todas las competencias. El encuentro m\u00e1s reciente fue una derrota dolorosa para los merengues (2-3) en la final de la Supercopa de Espa\u00f1a en enero de este a\u00f1o.<\/p>\n<p><b>Merengues en caos<\/b><\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Perder El Cl\u00e1sico confirmar\u00eda que Real Madrid no gane un solo t\u00edtulo en la temporada 2025-26, algo que no ocurr\u00eda desde la 2020-21.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Considerado uno de los equipos con mayor capital del mundo, su desempe\u00f1o ha sido decepcionante en esta temporada. Fue eliminado apenas en octavos de final de Copa del Rey por Albacete, en cuartos de<b> Champions League<\/b> por <b><a href=\"https:\/\/www.eleconomista.com.mx\/deportes\/psg-bayern-goleadores-champions-boleto-budapest-20260505-812029.html\" rel=\"nofollow noopener\" target=\"_blank\" data-ylk=\"elm:link;elmt:article_link;slk:Bayern M\u00fanich;itc:0;sec:content-canvas\" data-yga=\"{&quot;yLinkElement&quot;:&quot;context_link&quot;,&quot;yModuleName&quot;:&quot;content-canvas&quot;,&quot;yLinkText&quot;:&quot;Bayern M\u00fanich&quot;}\" class=\"link \">Bayern M\u00fanich<\/a><\/b> y la ya mencionada derrota en la final de la Supercopa de Espa\u00f1a ante Barcelona.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">La temporada anterior, aunque no gan\u00f3 LaLiga, Real Madrid se qued\u00f3 con el trofeo de la <b>Supercopa UEFA<\/b> y la <b>Copa Intercontinental de la FIFA<\/b>.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Pero eso no es lo \u00fanico preocupante de su presente. Horas antes de El Cl\u00e1sico, se confirm\u00f3 un enfrentamiento interno entre sus mediocampistas <b>Federico Valverde <\/b>y <b>Aurelien Tchouameni<\/b>, que deriv\u00f3 en la lesi\u00f3n y baja del uruguayo.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u201cTras las pruebas realizadas a Fede Valverde por los servicios m\u00e9dicos del Real Madrid, se le ha diagnosticado un traumatismo craneoencef\u00e1lico. Valverde se encuentra en su domicilio en buen estado y deber\u00e1 permanecer en reposo entre 10 y 14 d\u00edas, como marcan los protocolos m\u00e9dicos para este diagn\u00f3stico\u201d, inform\u00f3 el club.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Tambi\u00e9n indic\u00f3 que abrieron expedientes disciplinarios para ambos y que cuando concluyan los procedimientos internos se dar\u00e1 a conocer la resoluci\u00f3n.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Seg\u00fan un mensaje que public\u00f3 Valverde, discuti\u00f3 con Tchouameni en un entrenamiento pero su lesi\u00f3n no proviene de una agresi\u00f3n de su compa\u00f1ero, sino de un golpe \u201caccidental\u201d contra una mesa.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Ante todo esto, Barcelona puede agasajarse de tener en sus manos el derrumbe de Real Madrid: irse con cero t\u00edtulos en la temporada antes del <b>Mundial 2026 <\/b>y envuelto en un caos interno.<\/p>\n","protected":false},"excerpt":{"rendered":"Este fin de semana, Barcelona tiene en sus manos el derrumbe de Real Madrid. Si los cul\u00e9s ganan&hellip;\n","protected":false},"author":2,"featured_media":539603,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[105521,210,168,20328,25,24,288,3048,23,167,20421],"class_list":{"0":"post-539602","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-10-de-mayo","9":"tag-barcelona","10":"tag-deportes","11":"tag-el-clasico","12":"tag-es","13":"tag-espana","14":"tag-laliga","15":"tag-real-madrid","16":"tag-spain","17":"tag-sports","18":"tag-supercopa-de-espana"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116537693661207913","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/539602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=539602"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/539602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/539603"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=539602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=539602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=539602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}