{"id":540509,"date":"2026-05-08T18:50:25","date_gmt":"2026-05-08T18:50:25","guid":{"rendered":"https:\/\/www.europesays.com\/es\/540509\/"},"modified":"2026-05-08T18:50:25","modified_gmt":"2026-05-08T18:50:25","slug":"trump-aun-no-ha-decidido-sobre-retirada-de-tropas-de-espana","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/540509\/","title":{"rendered":"Trump a\u00fan no ha decidido sobre retirada de tropas de Espa\u00f1a"},"content":{"rendered":"<p>El secretario de Estado de Estados Unidos, <strong>Marco Rubio<\/strong>, ha revelado este viernes en Roma que el presidente <strong>Donald Trump <\/strong>todav\u00eda no ha decidido sobre una posible retirada de las tropas de EE.UU. de pa\u00edses como Espa\u00f1a e Italia por su oposici\u00f3n a la guerra en Ir\u00e1n.<\/p>\n<p>As\u00ed lo ha se\u00f1alado tras verse por separado con la primera ministra italiana, <strong>Giorgia Meloni<\/strong>, y su hom\u00f3logo <strong>Antonio Tajani<\/strong>, despu\u00e9s de las recientes cr\u00edticas de Trump a su antigua aliada por su postura sobre el conflicto en Oriente Medio. \u00abUna de las ventajas de estar en la OTAN es que nos permite tener<strong> fuerzas desplegadas en Europa y bases<\/strong> que nos permiten tener la capacidad log\u00edstica para proyectar nuestra fuerza en el caso de contingencias\u00bb, ha explicado Rubio en declaraciones a la prensa.<\/p>\n<p>\t<strong>Trump no ha decidido sobre una retirada de tropas de Espa\u00f1a<\/strong><\/p>\n<p>Rubio durante una rueda de prensa en Roma tras reunirse con la primera ministra italiana, Giorgia Meloni\u00a0Stefano Rellandini\/Pool Photo via AP<\/p>\n<p>\u00abAlgunos pa\u00edses en Europa, como por ejemplo Espa\u00f1a \u2014ha continuado\u2014, nos han negado el uso de esas bases para una contingencia muy importante, lo que de alguna manera ha impedido la misi\u00f3n, no de forma grave, pero a un coste y, de hecho, ha creado algunos peligros innecesarios\u00bb, ha dicho Rubio, en alusi\u00f3n al ataque estadounidense contra Ir\u00e1n.<\/p>\n<p>Sobre la retirada, \u00abesa <strong>es una decisi\u00f3n que el presidente debe tomar<\/strong>, su equipo y gente como yo y otros le aportar\u00e1n opciones potenciales, pero al final \u00e9l tendr\u00e1 que tomar una decisi\u00f3n, que todav\u00eda no ha tomado\u00bb, ha agregado el responsable.<\/p>\n<p>Rubio no ha hablado de los detalles con Meloni<\/p>\n<p>En ese sentido, Rubio ha asegurado que no ha hablado sobre los detalles de este tema durante su reuni\u00f3n de este viernes con Meloni. El jefe de la diplomacia de Estados Unidos ha mencionado tambi\u00e9n el<strong> caso de Alemania<\/strong>, donde EE.UU. est\u00e1 llevando a cabo una retirada de tropas, que, de acuerdo a sus datos, representan menos del 14 % del total de fuerzas que tiene en ese pa\u00eds.<\/p>\n<p>Rubio ha mantenido un encuentro con Meloni al mediod\u00eda en el Palacio Chigi, sede del Ejecutivo italiano, despu\u00e9s de entrevistarse a primera hora de la ma\u00f1ana con Tajani. En declaraciones a la prensa tras la reuni\u00f3n con Rubio, el ministro italiano ha explicado que ha defendido ante su hom\u00f3logo que Estados Unidos necesita a Europa, pese al alejamiento de Trump de sus aliados europeos, del mismo modo que estos precisan de Washington.<\/p>\n<p>\u00abEsas son las relaciones transatl\u00e1nticas y la unidad de Occidente es fundamental\u00bb, ha dicho Tajani, quien ha apuntado que para su pa\u00eds es \u00abimportante\u00bb la presencia estadounidense en el continente europeo para reforzar la OTAN, al igual que es clave \u00abun compromiso fuerte de los europeos\u00bb con la Alianza Atl\u00e1ntica.<\/p>\n<p>Ambos han conversado, adem\u00e1s, sobre Venezuela y Cuba, aunque el italiano no ha dado detalles sobre el contenido de su di\u00e1logo en estos puntos. La situaci\u00f3n por la guerra en Ir\u00e1n tambi\u00e9n ha centrado su discusi\u00f3n.<\/p>\n<p>\u00abHe expuesto nuestra posici\u00f3n sobre la situaci\u00f3n en Medio Oriente. Somos favorables y apoyamos todas las iniciativas que puedan conducir a un <strong>alto el fuego permanente<\/strong>\u00ab, ha se\u00f1alado Tajani, quien ha reiterado durante la reuni\u00f3n con Rubio la disponibilidad de Italia a enviar un dispositivo para el desminado del estrecho de <strong>Ormuz<\/strong>, siempre y cuando se alcance una tregua \u00abestable\u00bb.<\/p>\n<p>Rubio ha indicado en su rueda de prensa que no entiende por qu\u00e9 \u00abnadie\u00bb apoya los esfuerzos de EE.UU. para evitar que Ir\u00e1n tenga armamento nuclear. \u00abAhora Ir\u00e1n afirma que tiene el derecho a controlar un paso naval, dice que tiene el derecho a controlarlo. \u00bfY qu\u00e9 va a hacer el mundo sobre eso?\u00bb, se ha preguntado Rubio.<\/p>\n<p>EE.UU., a la espera de una respuesta de Ir\u00e1n<\/p>\n<p>En ese contexto, Rubio ha asegurado que EE.UU. espera a lo largo de este viernes una respuesta iran\u00ed  para tener <strong>negociaciones \u00abserias\u00bb<\/strong>. \u00abDeber\u00edamos saber algo hoy. Quiero decir, estamos esperando una respuesta de ellos. Veremos qu\u00e9 implica la respuesta. La esperanza es que sea algo que pueda ponernos en un proceso serio de negociaci\u00f3n\u00bb, ha subrayado.<\/p>\n<p>Rubio se ha reunido con Meloni y Tajani despu\u00e9s de acudir la v\u00edspera al Vaticano para tener un encuentro con el <strong>papa Le\u00f3n XIV<\/strong>, con motivo del primer aniversario de su pontificado, en una cita que el estadounidense remarc\u00f3 que ha servido para subrayar el compromiso de ambos para \u00abpromover la paz y la dignidad humana\u00bb.<\/p>\n<p>La visita de Rubio a Italia y el Vaticano se produce en medio de un <strong>deterioro de las relaciones por las cr\u00edticas de Trump al santo padre <\/strong>por su oposici\u00f3n a la pol\u00edtica migratoria de EE.UU. y a la guerra contra Ir\u00e1n.<\/p>\n<p>El rechazo de Meloni a esas cr\u00edticas del inquilino de la Casa Blanca al papa y las diferencias por el conflicto de Ir\u00e1n le han valido tambi\u00e9n el desprecio de Trump, quien ha arremetido contra su antigua aliada por su defensa de Le\u00f3n XIV, por su negativa a participar en la guerra de Ir\u00e1n, y por la suspensi\u00f3n de su acuerdo de Defensa con Israel, principal aliado de EE.UU. en Oriente Medio.<\/p>\n<p>En una entrevista telef\u00f3nica con el diario italiano \u00abCorriere della Sera\u00bb, publicada en abril tras la suspensi\u00f3n de ese acuerdo, Trump acus\u00f3 a Meloni de cobard\u00eda: \u00abSu primera ministra no est\u00e1 haciendo nada para conseguir petr\u00f3leo\u00bb, lament\u00f3 el presidente estadounidense, quien admiti\u00f3 que hac\u00eda tiempo que no hablaba con ella.<\/p>\n<p>\u00abEstoy en shock -sigui\u00f3-, pensaba que ten\u00eda valor, pero estaba equivocado\u00bb. <\/p>\n","protected":false},"excerpt":{"rendered":"El secretario de Estado de Estados Unidos, Marco Rubio, ha revelado este viernes en Roma que el presidente&hellip;\n","protected":false},"author":2,"featured_media":540510,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[17,18,13,14,11,61,62,63,64,19,20,9,10,15,16,12,21,22,65,66,67],"class_list":{"0":"post-540509","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-internacional","14":"tag-international","15":"tag-international-news","16":"tag-internationalnews","17":"tag-latest-news","18":"tag-latestnews","19":"tag-news","20":"tag-noticias","21":"tag-noticias-destacadas","22":"tag-noticiasdestacadas","23":"tag-titulares","24":"tag-ultimas-noticias","25":"tag-ultimasnoticias","26":"tag-world","27":"tag-world-news","28":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116540462021441108","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/540509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=540509"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/540509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/540510"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=540509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=540509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=540509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}