{"id":540840,"date":"2026-05-08T23:14:12","date_gmt":"2026-05-08T23:14:12","guid":{"rendered":"https:\/\/www.europesays.com\/es\/540840\/"},"modified":"2026-05-08T23:14:12","modified_gmt":"2026-05-08T23:14:12","slug":"la-conservadora-laura-fernandez-es-nombrada-presidenta-costa-rica","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/540840\/","title":{"rendered":"La conservadora Laura Fern\u00e1ndez es nombrada presidenta Costa Rica"},"content":{"rendered":"<p style=\"text-align:justify;\"><strong>Laura Fern\u00e1ndez<\/strong>, nueva <strong>presidenta de Costa Rica<\/strong>, ha sido investida en el cargo este viernes tras el acto del traspaso de mando presidencial en el Estadio Nacional, en San Jos\u00e9. Una toma de posesi\u00f3n en la que ha estado presente el rey Felipe VI.<\/p>\n<p style=\"text-align:justify;\">La costarricense toma el cargo hasta 2030 tras haber ganado con una amplia mayor\u00eda las elecciones del 1 de febrero, en las que su partido <strong>Pueblo Soberano<\/strong>, de l\u00ednea conservadora, obtuvo<strong> 30 de los 57 esca\u00f1os de la Asamblea Legislativa<\/strong> de Costa Rica. La oposici\u00f3n, el <strong>Partido Liberaci\u00f3n Nacional<\/strong>, tan solo obtuvo <strong>17 diputados.<\/strong><\/p>\n<p style=\"text-align:justify;\">La nueva mandataria se describe como una continuadora del legado del hasta ahora presidente<strong> Rodrigo Chaves<\/strong>, que tom\u00f3 posesi\u00f3n hace cuatro a\u00f1os. Durante la administraci\u00f3n de Chaves, Fern\u00e1ndez fue <strong>ministra de la Presidencia entre 2024 y 2025<\/strong> y de <strong>Planificaci\u00f3n Nacional y Pol\u00edtica Econ\u00f3mica entre 2022 y 2025<\/strong>.<\/p>\n<p>El acto de investidura<\/p>\n<p>La toma de posesi\u00f3n en la que Laura Fern\u00e1ndez se ha convertido en la <strong>50.\u00ba presidenta constitucional de Costa Rica<\/strong> se ha celebrado en un Estadio Nacional al que han acudido miles de personas que entraron de forma gratuita. Fern\u00e1ndez, de 39 a\u00f1os y del derechista Partido Pueblo Soberano, ha recibido la banda presidencial y ha prestado juramento ante la presidenta de la<strong> Asamblea Legislativa, la oficialista Yara Jim\u00e9nez<\/strong>, la primera vez que una mujer juramenta a otra como gobernante del pa\u00eds centroamericano.<\/p>\n<p>ersonas asisten a la ceremonia de investidura de la presidenta electa de Costa Rica, Laura Fern\u00e1ndez, en el Estadio Nacional de San Jos\u00e9\u00a0John Duran \/ AFP<\/p>\n<p>Durante su discurso, Laura Fern\u00e1ndez ha hecho \u00e9nfasis en que es la \u00ab<strong>heredera del cambio<\/strong>. La heredera de una forma de hacer pol\u00edtica sin aflojar\u00bb. Ha abogado por<strong> \u00abmodernizar\u00bb el estado<\/strong>: \u00abNo podemos continuar con 335 instituciones p\u00fablicas\u00bb, ha manifestado la presidenta electa.<\/p>\n<p>Fern\u00e1ndez tambi\u00e9n ha prometido a los asistentes que \u00abvolver\u00e1n a <strong>confiar en el sistema judicial y la separaci\u00f3n de poderes<\/strong>\u00ab. \u00abNo podemos aceptar que el narcotr\u00e1fico encuentre grietas en nuestras instituciones\u00bb, ha clamado. <\/p>\n<p>El rey Felipe VI y nuevos aliados<\/p>\n<p>La ceremonia ha contado con la asistencia de Felipe VI. Se trata de la s\u00e9ptima vez que el monarca est\u00e1 presente, ya sea como pr\u00edncipe o como rey, en la toma de posesi\u00f3n en Costa Rica, desde el a\u00f1o 1996.<\/p>\n<p>El rey de Espa\u00f1a, Felipe VI, asiste a la ceremonia de investidura de la polit\u00f3loga Laura Fern\u00e1ndez como presidenta de Costa Rica\u00a0Jeffrey Arguedas \/ EFE<\/p>\n<p>Sin embargo, el jefe de Estado en Espa\u00f1a no ha sido la \u00fanica entidad relevante entre los invitados. En su d\u00eda de investidura, Fern\u00e1ndez se ha rodeado de las caras m\u00e1s distinguidas del conservadurismo internacional, como los presidentes <strong>Bernardo Ar\u00e9valo<\/strong> (Guatemala), <strong>Nasry Asfura<\/strong> (Honduras), <strong>Jos\u00e9 Ra\u00fal Mulino<\/strong> (Panam\u00e1), <strong>Jos\u00e9 Antonio Kast<\/strong> (Chile),<strong> Isaac Herzog<\/strong> (Israel) y <strong>Luis Abinader<\/strong> (Rep\u00fablica Dominicana), as\u00ed como el vicesecretario de Estado de Estados Unidos, <strong>Christopher Landau<\/strong>. Adem\u00e1s, han estado presentes cancilleres y vicecancilleres de pa\u00edses como Nicaragua, Uruguay, Per\u00fa, Argentina, Colombia y M\u00e9xico. Una lista que enmarca la l\u00ednea pol\u00edtica de los socios con los que pretende alinearse la reci\u00e9n investida Fern\u00e1ndez.<\/p>\n<p><strong>Mario Quir\u00f3s<\/strong>, analista pol\u00edtico costarricense, explica que \u00abexiste un <strong>bloque de pa\u00edses en Latinoam\u00e9rica que ahora se perciben cercanos a la Casa Blanca\u00bb,<\/strong> y es con dichos estados con los que Costa Rica va a tener mejor relaci\u00f3n. El analista considera que esta nueva etapa supondr\u00e1\u00bb el refuerzo (a\u00fan mayor) de las relaciones con Estados Unidos\u00bb: \u00abEE.UU. es el principal socio comercial del pa\u00eds. Durante esta legislatura van a seguir fortaleciendo el combate contra el narcotr\u00e1fico\u00bb. Actualmente, ambos estados cuentan con un acuerdo para el traslado de personas deportadas de Estados Unidos.<\/p>\n<p>Adem\u00e1s de la presidenta electa, tambi\u00e9n han tomado posesi\u00f3n los vicepresidentes <strong>Francisco Gamboa Soto y Douglas Soto Campos<\/strong>, que suceden a la vicepresidenta saliente <strong>Mary Munive<\/strong>.<\/p>\n<p>&#8216;Heredera&#8217; del legado de Chaves<\/p>\n<p style=\"text-align:justify;\">A pesar de que Rodrigo Chaves dejar\u00e1 de ocupar su cargo como presidente, permanecer\u00e1 en el gobierno entrante como<strong> ministro de la Presidencia y de Hacienda del Gobierno.<\/strong> Es la primera vez en la historia reciente del pa\u00eds que un presidente saliente toma un cargo como ministro de la siguiente Administraci\u00f3n.<\/p>\n<p style=\"text-align:justify;\">No obstante, el legado de Chaves no se respaldar\u00e1 \u00fanicamente en su figura. Laura Fern\u00e1ndez dar\u00e1 continuidad a figuras claves del Gobierno del anterior presidente, en<strong> los puestos de ministros de Relaciones Exteriores, Seguridad, Educaci\u00f3n y Obras P\u00fablicas y Transportes<\/strong>, as\u00ed como en instituciones estrat\u00e9gicas como la seguridad social, la de electricidad y la Comisi\u00f3n Nacional de Emergencias.<\/p>\n<p>El presidente de Costa Rica, Rodrigo Chaves (i), saluda a la presidenta electa, Laura Fern\u00e1ndez, este martes durante la presentaci\u00f3n del nuevo gabinete en San Jos\u00e9\u00a0Jeffrey Arguedas \/ EFE<\/p>\n<p style=\"text-align:justify;\">Seg\u00fan Quir\u00f3s, la nueva presidenta ha admitido varias veces que su propuesta era de \u00abcontinuidad\u00bb: \u00abSu candidatura se present\u00f3 como una segunda etapa de este movimiento pol\u00edtico, al nivel de que Chaves seguir\u00e1 presente desde los ministerios\u00bb, se\u00f1ala, que asegura que ambos compartir\u00e1n el poder durante la legislatura.<\/p>\n<p>Hace unos d\u00edas Fern\u00e1ndez explic\u00f3 que su mandato tiene como fin la<strong> \u00abprofundizaci\u00f3n del legado de Chaves, que har\u00e1 llegar a Costa Rica todav\u00eda m\u00e1s lejos\u00bb. <\/strong>Un Chaves que ha dejado la presidencia de Costa Rica con altos niveles de popularidad ciudadana, a pesar del aumento de la criminalidad: \u00abLa mayor\u00eda de encuestas colocan por encima del 7 la valoraci\u00f3n de la gesti\u00f3n presidencial de Chaves\u00bb, explica Quir\u00f3s, \u00abEs un l\u00edder que sale con un apoyo inusualmente alto\u00bb.<\/p>\n<p>El conservadurismo se instala en Latinoam\u00e9rica<\/p>\n<p>El partido de Chaves y Fern\u00e1ndez, Pueblo Soberano, se cataloga como<strong> liberal en lo econ\u00f3mico y conservador en lo social<\/strong>, promoviendo austeridad fiscal, inversi\u00f3n privada, menos burocracia y defensa de valores tradicionales. Su \u00e9xito durante dos legislaturas seguidas marcha en consonancia con una tendencia de los pa\u00edses de Am\u00e9rica Latina, en los que poco a poco se ha antepuesto el conservadurismo. <\/p>\n<p>De los 20 l\u00edderes de los pa\u00edses que conforman Latinoam\u00e9rica, 8 de ellos son catalogados como mandatarios de derechas: <strong>Jose Antonio Kast<\/strong> en <strong>Chile<\/strong>; <strong>Nayib Bukele<\/strong> en <strong>El Salvador<\/strong>, <strong>Javier Milei<\/strong> en <strong>Argentina<\/strong>; <strong>Daniel Noboa<\/strong> en <strong>Ecuador<\/strong>; <strong>Santiago Pe\u00f1a<\/strong> en <strong>Paraguay<\/strong>; <strong>Nasry Asfura <\/strong>en <strong>Honduras;<\/strong> y <strong>Jose Ra\u00fal Mulino<\/strong> en <strong>Panam\u00e1<\/strong>, adem\u00e1s de la propia Fern\u00e1ndez.<\/p>\n<p>\u00abEn gran parte de los pa\u00edses de Am\u00e9rica Latina, las transformaciones sociales que se promet\u00edan se han acabado posponiendo. Esto a la gente le ha frustrado y se lo ha achacado a los gobiernos progresistas, cambiando el p\u00e9ndulo hacia la derecha\u00bb, a\u00f1ade Quir\u00f3s.<\/p>\n<p style=\"text-align:justify;\">En los \u00faltimos d\u00edas, la mandataria ha insistido en la necesidad de reformas estructurales en el poder judicial, y ha puesto \u00e9nfasis en mantener <strong>mano dura con la inmigraci\u00f3n<\/strong>, un tema central en la legislatura de Rodrigo Chaves: \u00abLa principal preocupaci\u00f3n de los costarricenses es la inseguridad provocada por el narcotr\u00e1fico\u00bb, matiza Quir\u00f3s. Actualmente, el gobierno est\u00e1 construyendo un <strong>Centro de Alta Contenci\u00f3n del Crimen Organizado (CACCO)<\/strong>, inspirado en el <strong>Centro de Confinamiento del Terrorismo (CECOT)<\/strong> de El Salvador, concebido como una instalaci\u00f3n que resguarde a personas privadas de libertad con alta peligrosidad, especialmente vinculadas al crimen organizado.<\/p>\n","protected":false},"excerpt":{"rendered":"Laura Fern\u00e1ndez, nueva presidenta de Costa Rica, ha sido investida en el cargo este viernes tras el acto&hellip;\n","protected":false},"author":2,"featured_media":540841,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[17,18,13,14,11,61,62,63,64,19,20,9,10,15,16,12,21,22,65,66,67],"class_list":{"0":"post-540840","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-internacional","14":"tag-international","15":"tag-international-news","16":"tag-internationalnews","17":"tag-latest-news","18":"tag-latestnews","19":"tag-news","20":"tag-noticias","21":"tag-noticias-destacadas","22":"tag-noticiasdestacadas","23":"tag-titulares","24":"tag-ultimas-noticias","25":"tag-ultimasnoticias","26":"tag-world","27":"tag-world-news","28":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116541500415594742","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/540840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=540840"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/540840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/540841"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=540840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=540840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=540840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}