{"id":541397,"date":"2026-05-09T08:01:11","date_gmt":"2026-05-09T08:01:11","guid":{"rendered":"https:\/\/www.europesays.com\/es\/541397\/"},"modified":"2026-05-09T08:01:11","modified_gmt":"2026-05-09T08:01:11","slug":"avanza-la-escultura-de-los-patos-en-el-paseo-de-roma","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/541397\/","title":{"rendered":"Avanza la escultura de los patos en el Paseo de Roma"},"content":{"rendered":"<p>09\/05\/2026 a las 02:00h.<\/p>\n<p class=\"v-d-p\" style=\"\">Terminada la escultura, ya barnizada, de la loba, Lupe Ar\u00e9valo y Javi Porrino, trabajadores de FCC, se ponen ahora a moldear arte en forma de  &#8230; patos en el otro pino del Paseo de Roma golpeado por los temporales. Dos pinos que ya no tienen vida vegetal, pero s\u00ed escult\u00f3rica, gracias al trabajo desinteresado de esos dos empleados de la empresa de limpieza y parques.<\/p>\n","protected":false},"excerpt":{"rendered":"09\/05\/2026 a las 02:00h. Terminada la escultura, ya barnizada, de la loba, Lupe Ar\u00e9valo y Javi Porrino, trabajadores&hellip;\n","protected":false},"author":2,"featured_media":541398,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,8866,232,234,146,147,25,1246,24,2755,62944,438,23],"class_list":{"0":"post-541397","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-avanza","13":"tag-design","14":"tag-diseno","15":"tag-entertainment","16":"tag-entretenimiento","17":"tag-es","18":"tag-escultura","19":"tag-espana","20":"tag-paseo","21":"tag-patos","22":"tag-roma","23":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116543572533911799","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/541397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=541397"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/541397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/541398"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=541397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=541397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=541397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}