{"id":541411,"date":"2026-05-09T08:11:11","date_gmt":"2026-05-09T08:11:11","guid":{"rendered":"https:\/\/www.europesays.com\/es\/541411\/"},"modified":"2026-05-09T08:11:11","modified_gmt":"2026-05-09T08:11:11","slug":"el-viejo-continente-en-el-divan","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/541411\/","title":{"rendered":"El Viejo Continente en el div\u00e1n"},"content":{"rendered":"<p class=\"paragraph\">Europa no atraviesa un buen momento. La crisis financiera del 2008 fue un mazado para su autoconfianza. El coronavirus y la guerra de Ucrania agravaron una crisis de identidad que la mantienen postrada. Los esfuerzos para salir adelante han sido loables, sobre todo con el covid. Los planes de transici\u00f3n ecol\u00f3gica y resiliencia tecnol\u00f3gica tambi\u00e9n han ayudado, pero no han sido suficientes para recuperar la confianza. La desorientaci\u00f3n y la depresi\u00f3n persisten. Tambi\u00e9n la sensaci\u00f3n de soledad. Estados Unidos, garante de la seguridad, ha decidido que el proyecto de paz e igualdad que representa la Uni\u00f3n Europea no le interesa. El presidente Trump preferir\u00eda que la UE no existiera. Esta orfandad plantea un dilema existencial: \u00bfqu\u00e9 soy y qu\u00e9 quiero ser? Resolverlo es muy complicado. No solo por la diversidad de opiniones entre los socios, sino porque la instituci\u00f3n tampoco lo tiene claro. \u00bfC\u00f3mo podemos prepararnos para la guerra si somos un proyecto de paz? \u00bfC\u00f3mo es que no defendemos con m\u00e1s ah\u00ednco a los palestinos y los inmigrantes si los derechos humano son la expresi\u00f3n m\u00e1s clara de los valores europeos?<\/p>\n<p class=\"paragraph\">Europa se siente d\u00e9bil y no vive seg\u00fan sus principios. Sabe que debe valerse por s\u00ed misma, pero tiembla ante la certeza de que Estados Unidos ya no ser\u00e1 su protector incondicional. Prescindir de la energ\u00eda rusa y admitir que debe cambiar su modelo productivo para reducir la dependencia de las manufacturas\u00a0made in China\u00a0, a\u00fan complica m\u00e1s del diagn\u00f3stico.<\/p>\n<p class=\"paragraph\">Los presidentes y primeros ministros tienen sobre sus mesas de trabajo varias hojas de ruta para salir adelante. Tener el diagn\u00f3stico y el remedio, sin embargo, no resuelve nada si el paciente no colabora.<\/p>\n<p class=\"paragraph\">Hoy, m\u00e1s que nunca, resuena la sinceridad de Jean-Claude Juncker, presidente de la Comisi\u00f3n Europea entre 2014 y 2019, cuando dijo que \u201ctodos sabemos lo que hay que hacer, pero si lo hacemos no sabremos c\u00f3mo ser reelegidos\u201d.<\/p>\n<p class=\"paragraph\">Por eso sentamos a la Uni\u00f3n Europea en el div\u00e1n del psicoanalista para que nos cuente qu\u00e9 le pasa y ayudarla a afrontar este momento del ahora o nunca.<\/p>\n<p class=\"paragraph\"><b>ME FALTA LIDERAZGO<\/b><\/p>\n<p class=\"paragraph\"><b>Macron, Merz y Starmer quieren pero no pueden<\/b><\/p>\n<p class=\"paragraph\">Alemania, motor econ\u00f3mico de la UE, no afronta la reforma de su modelo productivo y Francia, reserva espiritual de nuestros valores, ha olvidado c\u00f3mo ser coherente. El Reino Unido, por su parte, a quien le debemos la victoria sobre el nazismo, no est\u00e1 en disposici\u00f3n de ayudar. Su crisis de identidad es a\u00fan m\u00e1s grave que la nuestra. El primer ministro Starmer tiene una aplastante mayor\u00eda parlamentaria, que, sin embargo, no utiliza para tomar la decisi\u00f3n m\u00e1s l\u00f3gica y trascendental: iniciar el camino de regreso a casa, a la UE, al mercado com\u00fan, su principal socio comercial. Sin embargo, gobierna desde un posibilismo centrista que no soluciona nada. Al contrario, da alas a los radicales, que saben aprovechar el malestar de la ciudadan\u00eda por el colapso del statu quo.<\/p>\n<p class=\"paragraph\">El canciller Merz y el presidente Macron est\u00e1n en la misma encrucijada. A Macron le queda un a\u00f1o de mandato y sin mayor\u00eda parlamentaria solo puede gobernar de cara a la galer\u00eda, pero Merz, que est\u00e1 al frente de una amplia coalici\u00f3n, deber\u00eda hacer m\u00e1s, y no solo por Alemania, sino por Europa.<\/p>\n<p class=\"paragraph\">Merz y Macron deber\u00edan inspirarse en Kohl y Miterrand. Kohl ofreci\u00f3 el marco para crear el euro, como le ped\u00eda Miterrand, y \u00e9ste accedi\u00f3 a la r\u00e1pida reunificaci\u00f3n de Alemania, pese de los fantasmas del pasado.<\/p>\n<p class=\"paragraph\">Ser valiente comporta unos riesgos que parecen re\u00f1idos con el liberalismo contempor\u00e1neo. Las voces m\u00e1s atrevidas no surgen de la socialdemocracia ni del centroderecha, sino de los extremistas antieuropeos.<\/p>\n<p class=\"paragraph\">\u201cEstamos perdiendo a los europeos\u201d, exclam\u00f3 la eurodiputada liberal Val\u00e9rie Hayer cuando tom\u00f3 la palabra en el \u00faltimo discurso sobre el estado de la Uni\u00f3n. Explic\u00f3 que, a pesar de nuestra riqueza y libertad, los europeos no confiamos en nuestros l\u00edderes porque los vemos d\u00e9biles. \u201cSomos d\u00e9biles frente a Trump, Putin, China y el clima\u201d, dijo. Y es con esta debilidad que hacemos frente a nuestros grandes retos, como son la seguridad, la inmigraci\u00f3n y el estado del bienestar.<\/p>\n<p class=\"paragraph\"><b>EL INMIGRANTE ME ASUSTA<\/b><\/p>\n<p class=\"paragraph\"><b>Los gobiernos asumen que Europa no somos todos<\/b><\/p>\n<p class=\"paragraph\">Nos olvidamos de los derechos humanos cuando afrontamos el fen\u00f3meno de la inmigraci\u00f3n. La mayor\u00eda de los europeos no quieren m\u00e1s inmigrantes. Los partidos racistas consiguen grandes resultados electorales. Las fuerzas centristas sienten la tentaci\u00f3n de romper el cord\u00f3n sanitario. Se ha roto en Suecia desde el centroderecha y en Rumania desde el centroizquierda, y lo ha roto tambi\u00e9n el PP con Vox en varias autonom\u00edas espa\u00f1olas. Una vez que un partido con principios morales rompe el cord\u00f3n sanitario, luego lo tiene m\u00e1s f\u00e1cil para justificar pol\u00edticas inmorales.<\/p>\n<p class=\"paragraph\">El rechazo al inmigrante \u2013confirmado por la falta de una pol\u00edtica de asilo com\u00fan\u2013 esconde una patolog\u00eda a\u00fan m\u00e1s grave: la poblaci\u00f3n europea que no es blanca ni cristiana participa menos de la vida democr\u00e1tica. Se a\u00edsla en sus comunidades, vive al margen, y esta marginaci\u00f3n demuestra que el proyecto europeo es solo para algunos europeos.<\/p>\n<p class=\"paragraph\">Un liderazgo d\u00e9bil y la falta de recursos financieros para sostener el estado del bienestar dejan a la ciudadan\u00eda a merced de sus instintos m\u00e1s primarios. Es f\u00e1cil creer que tenemos m\u00e1s derechos que los dem\u00e1s, sobre todo cuando los populistas as\u00ed nos lo dicen.<\/p>\n<p class=\"paragraph\"><b>ME FALTA BIENESTAR<\/b><\/p>\n<p class=\"paragraph\"><b>El estado no atiende las necesidades b\u00e1sicas<\/b><\/p>\n<p class=\"paragraph\">Los radicales no tendr\u00edan opciones de gobernar si los estados pudieran garantizar las necesidades b\u00e1sicas de la ciudadan\u00eda. El coste de la vivienda y el deterioro de la sanidad, la educaci\u00f3n y el transporte dificultan la vida de la gran mayor\u00eda de europeos. Redistribuir la riqueza y apuntalar el estado del bienestar es una de las principales se\u00f1as de identidad de los europeos. No conseguirlo es un fracaso que da las al radicalismo.<\/p>\n<p class=\"paragraph\">Los estados no lo tienen f\u00e1cil. A sus econom\u00edas les falta productividad. Nunca han recuperado los niveles que ten\u00edan antes de la gran crisis financiera del 2008. Los programas de crecimiento de la UE para acelerar la transici\u00f3n ecol\u00f3gica y la fabricaci\u00f3n de chips, por ejemplo, no bastan para impedir que cada vez tenga menos peso en el PIB mundial.<\/p>\n<p class=\"paragraph\">Sin dinero es dif\u00edcil pagar el bienestar. El cierre de Ormuz, por ejemplo, ha disparado el precio de la energ\u00eda y la inflaci\u00f3n. Las ayudas p\u00fablicas a las empresas y las familias implican aumentar un gasto que, si no puede asumirse con los impuestos, implica m\u00e1s deuda. Este es el embrollo que Starmer y otros estadistas no pueden solucionar.<\/p>\n<p class=\"paragraph\">Europa tiene el mercado m\u00e1s importante del mundo y, sin embargo, no puede garantizar el bienestar de su ciudadan\u00eda porque es incapaz de reforzarlo. El informe Draghi indica c\u00f3mo hacerlo, pero ning\u00fan l\u00edder asume el coste de intentarlo.<\/p>\n<p class=\"paragraph\"><b>ESTOY INDEFENSA Y SOLA<\/b><\/p>\n<p class=\"paragraph\"><b>Necesito armas, justo lo que cre\u00eda que nunca necesitar\u00eda<\/b><\/p>\n<p class=\"paragraph\">Europa es un proyecto de paz que se prepara para la guerra. Vaya contradicci\u00f3n. La diplomacia y la colaboraci\u00f3n internacional que tanto ha defendido la UE parece que no sirven de nada ahora que EE.UU., Rusia y China imponen la ley del m\u00e1s fuerte.<\/p>\n<p class=\"paragraph\">Es igual que Trump retire a 5.000 soldados de Alemania porque lo que necesita Europa son misiles, muchos misiles de medio y largo alcance para neutralizar a Rusia y no hay forma de fabricarlos. Necesita ganar tiempo para poder hacerlo. Tiempo tambi\u00e9n para fabricar drones y munici\u00f3n, para reforzar la seguridad cibern\u00e9tica y las comunicaciones estrat\u00e9gicas. Hay tanto por hacer que ser\u00e1 imposible sin romper el tab\u00fa de la defensa compartida. No necesitamos 27 ej\u00e9rcitos. Nos bastar\u00eda con uno. Nos bastar\u00eda con la disuasi\u00f3n nuclear de Francia y el Reino Unido si pudieran ser realmente europeas, pero no lo son. Europa no tiene lo que necesita, pero no est\u00e1 sola. Ha perdido a EE.UU., pero tiene a Canad\u00e1 y otros amigos en Asia y el sur global que estar\u00e1n a su lado para ayudarla a valerse por s\u00ed misma, como demuestran los 40\u00a0 acuerdos comerciales firmados con unos 80 estados, incluida India y los pa\u00edses del Mercosur.<\/p>\n<p><img decoding=\"async\" width=\"65\" height=\"65\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/01\/63e3e09bbc205.jpeg\" alt=\"Xavier Mas de Xax\u00e0s Faus\"\/><\/p>\n<p class=\"author_bio\">Corresponsal diplom\u00e1tico de La Vanguardia. Ha cubierto los principales acontecimientos internacionales desde la ca\u00edda del muro de Berl\u00edn y numerosos conflictos en especial en Oriente Pr\u00f3ximo. Como corresponsal en EE.UU. fue testigo del 11-S<\/p>\n","protected":false},"excerpt":{"rendered":"Europa no atraviesa un buen momento. La crisis financiera del 2008 fue un mazado para su autoconfianza. El&hellip;\n","protected":false},"author":2,"featured_media":541412,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[17,18,13,14,11,61,62,63,64,19,20,9,10,15,16,12,21,22,65,66,67],"class_list":{"0":"post-541411","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-featured-news","11":"tag-featurednews","12":"tag-headlines","13":"tag-internacional","14":"tag-international","15":"tag-international-news","16":"tag-internationalnews","17":"tag-latest-news","18":"tag-latestnews","19":"tag-news","20":"tag-noticias","21":"tag-noticias-destacadas","22":"tag-noticiasdestacadas","23":"tag-titulares","24":"tag-ultimas-noticias","25":"tag-ultimasnoticias","26":"tag-world","27":"tag-world-news","28":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116543611599782033","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/541411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=541411"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/541411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/541412"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=541411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=541411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=541411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}