{"id":541427,"date":"2026-05-09T08:24:15","date_gmt":"2026-05-09T08:24:15","guid":{"rendered":"https:\/\/www.europesays.com\/es\/541427\/"},"modified":"2026-05-09T08:24:15","modified_gmt":"2026-05-09T08:24:15","slug":"el-universo-de-leo-de-palma-en-artgallery","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/541427\/","title":{"rendered":"El universo de Leo de Palma en ArtGallery"},"content":{"rendered":"<p>Bajo el lema \u2018When everybody was there\u2019 (Cuando todo el mundo estaba all\u00ed), Leo de Palma inaugur\u00f3 el pasado 30 de abril nueva exposici\u00f3n en la sala ArtGallery del Hotel Artmadams. All\u00ed se reunieron amigos y seguidores de su obra, que estar\u00e1 expuesta hasta el 13 de mayo pr\u00f3ximo.<br \/>Artista pl\u00e1stico holand\u00e9s de larga trayectoria en Mallorca, donde reside desde hace 25 a\u00f1os, sus creaciones se caracterizan por una marcada dimensi\u00f3n evocadora, en la que las im\u00e1genes de la memoria se convierten en el eje central de su lenguaje art\u00edstico. <br \/>A trav\u00e9s de sus composiciones, Leo de Palma construye relatos visuales en los que la figura humana adquiere un protagonismo esencial, presentando personajes que parecen poseer luz propia y una identidad \u00edntima. <br \/>Sus pinturas sugieren historias abiertas, cargadas de sensibilidad y profundidad emocional, invitando al espectador a una interpretaci\u00f3n personal. Son trabajos que se sit\u00faan en un territorio donde la memoria, la narrativa y la expresi\u00f3n pl\u00e1stica convergen, consolid\u00e1ndolo como un artista con una voz singular.<\/p>\n","protected":false},"excerpt":{"rendered":"Bajo el lema \u2018When everybody was there\u2019 (Cuando todo el mundo estaba all\u00ed), Leo de Palma inaugur\u00f3 el&hellip;\n","protected":false},"author":2,"featured_media":541428,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,2084,232,234,146,147,25,24,2085,2086,2087,2088,23,2083],"class_list":{"0":"post-541427","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-conciertos-en-mallorca","13":"tag-design","14":"tag-diseno","15":"tag-entertainment","16":"tag-entretenimiento","17":"tag-es","18":"tag-espana","19":"tag-eventos-en-mallorca","20":"tag-exposiciones-en-mallorca","21":"tag-fiestas-en-mallorca","22":"tag-ocio-en-mallorca","23":"tag-spain","24":"tag-zona-vip"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116543662727333018","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/541427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=541427"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/541427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/541428"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=541427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=541427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=541427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}