{"id":543374,"date":"2026-05-10T11:45:13","date_gmt":"2026-05-10T11:45:13","guid":{"rendered":"https:\/\/www.europesays.com\/es\/543374\/"},"modified":"2026-05-10T11:45:13","modified_gmt":"2026-05-10T11:45:13","slug":"en-la-valmuza-el-objetivo-es-hacer-club-no-solo-jugar-al-golf-y-la-gente-esta-muy-a-gusto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/543374\/","title":{"rendered":"\u00abEn La Valmuza, el objetivo es hacer club, no solo jugar al golf, y la gente est\u00e1 muy a gusto\u00bb"},"content":{"rendered":"<p><img decoding=\"async\" class=\"v-ath__i\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/04\/autor-6000-foto-1.png\" alt=\"Alex G. Santana\"\/><\/p>\n<p>10\/05\/2026 a las 10:47h.<\/p>\n<p class=\"v-d-p\" style=\"\">La Valmuza Golf comienza en estas semanas su primera \u00e9poca fuerte de torneos en este 2026 y su director y gerente, Alberto D\u00e1vila, analiza el pasado, presente y futuro del club, junto al presidente, Eustaquio Andr\u00e9s.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>Han pasado algo m\u00e1s de cinco a\u00f1os desde que Grupo Andr\u00e9s se hizo cargo de La Valmuza Golf. \u00bfEn qu\u00e9 situaci\u00f3n est\u00e1?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Muy cerca de lo que quer\u00edamos. En los inicios ten\u00edamos que generar jugadores y llegar a toda la sociedad. Que vinieran a vernos, que nos conocieran y darles facilidades para que probaran este deporte. Empezamos con Do\u00f1inos, empresas, instituciones y padres y ni\u00f1os y ya han pasado cerca de 10.000 personas.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>\u00bfHan cumplido entonces el objetivo de hacer del golf un deporte menos exclusivo?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Eso ha cambiado mucho. Yo vengo de una familia golfista y cuando empec\u00e9 a jugar en Madrid para simplemente acceder a una clase ten\u00edas que ser socio o accionista, y eso ya restring\u00eda mucho el acceso al golf. Hoy en d\u00eda, entre los campos p\u00fablicos que hay o nosotros, que somos un campo privado pero tenemos tarifas para no abonados, te cuesta igual o menos que en un gimnasio u otra actividad f\u00edsica. Nuestra idea es que cualquier persona pueda practicar golf.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>Hablaba de esas 10.000 personas, la mayor\u00eda de las cuales llegaron por los &#8216;Bautismos de golf&#8217;.<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Es fundamental el trabajo de los profesores y del club para intentar que la gente venga a nuestro campo. Que vengan, lo conozcan y lo vean, porque muchas veces si no se lo explicas es complicado. Mi labor antes de la de los profesores es explicar precios de un juego de palos o de hacerte abonado, que puedas venir a tomar un caf\u00e9 o pegar unas bolas sin ser socio por dos euros e irte a casa. El golf tiene muchos clich\u00e9s y hay que explicarlo. Despu\u00e9s, l\u00f3gicamente, hay que hacer una conversi\u00f3n: si pasan 10.000 personas vamos a intentar que el 1% o el 2% terminen jugando. Esa es la idea.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>Otro pilar es la escuela.<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014La cantera es muy importante, porque el jugador va cumpliendo a\u00f1os, aunque es verdad que el golf es un deporte que te permite jugar desde los 4 hasta los 90 a\u00f1os. Estamos muy orgullosos porque dir\u00eda que el 95% de los que est\u00e1n ahora son alumnos nuestros desde que empezamos. Y ya tenemos alg\u00fan campe\u00f3n de Espa\u00f1a. Es gracias al trabajo de los profesores y el director deportivo, Dani Guerra. Intentamos que salgan jugadores buenos y si sale un John Rahm o Ballesteros de La Valmuza, pues mucho mejor.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>La han impulsado con el Plan de Promesas de Grupo Andr\u00e9s.<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Esto a nivel privado no es normal. S\u00ed hay planes de subvenciones cuando entran en equipos de federaciones, pero con este plan de Grupo Andr\u00e9s ayudamos a viajar a los que ya est\u00e1n compitiendo. Y es un incentivo.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>Siguen potenciando el campo. Por ejemplo, con la cancha de pr\u00e1cticas.<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Es fundamental porque es donde la gente empieza a jugar. Nos decidimos por la tecnolog\u00eda Toptracer Range porque sirve para que un jugador ya experimentado tenga sus datos en el m\u00f3vil. Y para la escuela puedes programar entrenamientos. Nos sirve tambi\u00e9n como l\u00ednea de negocio de ocio, para hacer eventos como si fuera una bolera.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>\u00bfQu\u00e9 me dice de la tienda?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Nos embarcamos en tener una tienda importante y que la gente lo tenga como referencia, sobre todo en Castilla y Le\u00f3n. En estos cinco a\u00f1os se ha convertido en uno de los mejores departamentos que tenemos y ya nos van conociendo fuera de la Comunidad.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>\u00bfQu\u00e9 importancia tiene el Restaurante Aire?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Es el punto social del club, Es decir, la gente sale a jugar, pero en el hoyo dos o tres ya est\u00e1 pensando en la cervecita, el pincho del final&#8230; Ahora tenemos a una familia con cocina tradicional y de toda la vida, que es lo que queremos. Y que cualquier persona de fuera pueda venir y comer a precios asequibles como en cualquier otro restaurante, pero con vistas a la dehesa, las encinas, los lagos con patos&#8230; y al aire libre.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>\u00bfQu\u00e9 destacar\u00eda de lo que es el campo?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Hemos empezado con un plan a tres a\u00f1os para darle un plus de mantenimiento. La gente se queda con el cari\u00f1o que le damos y que la propiedad y la direcci\u00f3n est\u00e1n involucrados en el d\u00eda a d\u00eda. (Aqu\u00ed interviene Eustaquio Andr\u00e9s para apostillar: \u00abEn zonas de la costa o Madrid los campos se hacen pensando en hacer una urbanizaci\u00f3n y el campo est\u00e1 en terreno con subidas y bajadas, y si no tienes un buggy es imposible jugar. Y desde que entras en La Valmuza no ves una casa y s\u00ed la plena naturaleza, que es lo que pretendemos\u00bb). Y contin\u00faa Alberto D\u00e1vila con unos planes de futuro: \u00abYa hemos acogido varios Campeonatos de Espa\u00f1a y con las mejoras pensamos en el futuro en albergar un Campeonato de Espa\u00f1a Profesional o alg\u00fan circuito europeo femenino. Ser\u00eda darle al campo un salto cualitativo y de prestigio, adem\u00e1s dise\u00f1ado por Severiano Ballesteros.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>\u00bfCu\u00e1les han sido las \u00faltimas mejoras?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">Hemos hecho nuevos caminos hormigonados de salida y entrada a los hoyos m\u00e1s cercanos a la casa club. Hemos hecho una zona nueva con una caseta tipo chiringuito para el avituallamiento. Para que sea m\u00e1s acogedor ahora en la temporada de buenas temperaturas en la transici\u00f3n del 9 al 10.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>\u00bfQu\u00e9 supone albergar cada vez m\u00e1s torneos de federaciones?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014La diferencia la notamos en que el primer a\u00f1o solicit\u00e1bamos que vinieran y a partir del segundo te llaman para decirte: queremos ir a tu campo. Eso te llena de orgullo porque significa que est\u00e1s haciendo las cosas bien. Y es fundamental en el tema econ\u00f3mico: de cada 8 euros que genera el golf, 1 se lo queda el golf y el resto es para restauraci\u00f3n, transporte, hoteles&#8230;<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>En el calendario anual uno de los torneos m\u00e1s importantes es el de LA GACETA, con el que se reestren\u00f3 el campo y que se disputa en dos semanas.<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Para nosotros es un campeonato de referencia y ponemos en \u00e9l toda la carne en el asador. En apenas dos d\u00edas hay 250-260 jugadores apuntados por los atractivos que tiene. Aqu\u00ed vuelve a intervenir Eustaquio Andr\u00e9s: \u00abMiramos mucho por nuestros abonados. No podemos caer en los errores de los primeros a\u00f1os de coger todos los campeonatos, ahora somos mucho m\u00e1s selectivos y los que hacemos son muy importantes. Hemos tenido que decir que no a muchos para no entorpecer a nuestros abonados, que son los que nos apoyan durante todo el a\u00f1o. Queremos que nuestros abonados disfruten y puedan jugar todos los d\u00edas, no podemos morir de \u00e9xito. Estamos cerca de la capacidad m\u00e1xima para tener contenta a la gente.<\/p>\n<p class=\"v-d-p\" style=\"\"><strong>Volvamos al principio: \u00bfhan conseguido en estos cinco a\u00f1os que La Valmuza sea mucho m\u00e1s que un campo de golf?<\/strong><\/p>\n<p class=\"v-d-p\" style=\"\">\u2014Claro. Queremos que la gente disfrute con el golf pero que su experiencia no acabe ah\u00ed. Que coma con su familia o tome unas ca\u00f1as con los amigos. Y les damos todas las facilidades para que hagan aqu\u00ed sus propios eventos. Nuestros abonados no son solo como socios de un club, sino que participan en todo. Nuestra gente va en masa. Est\u00e1n a gusto y me aprecian, eso se nota. Eso es hacer club. No queremos que la gente solo vaya a jugar al golf, sino que se integren en el club, y as\u00ed ocurre. Nuestros abonados se han convertido en amigos y eso lo hemos conseguido desde el club.<\/p>\n","protected":false},"excerpt":{"rendered":"10\/05\/2026 a las 10:47h. La Valmuza Golf comienza en estas semanas su primera \u00e9poca fuerte de torneos en&hellip;\n","protected":false},"author":2,"featured_media":543375,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275],"tags":[1798,168,25,24,260,329,18599,7532,661,1138,23,167,22636],"class_list":{"0":"post-543374","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-golf","8":"tag-club","9":"tag-deportes","10":"tag-es","11":"tag-espana","12":"tag-gente","13":"tag-golf","14":"tag-gusto","15":"tag-jugar","16":"tag-objetivo","17":"tag-solo","18":"tag-spain","19":"tag-sports","20":"tag-valmuza"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116550116107659787","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/543374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=543374"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/543374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/543375"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=543374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=543374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=543374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}