{"id":543454,"date":"2026-05-10T12:46:22","date_gmt":"2026-05-10T12:46:22","guid":{"rendered":"https:\/\/www.europesays.com\/es\/543454\/"},"modified":"2026-05-10T12:46:22","modified_gmt":"2026-05-10T12:46:22","slug":"encuentran-un-pequeno-mundo-en-el-sistema-solar-con-una-atmosfera-que-no-deberia-tener","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/543454\/","title":{"rendered":"Encuentran un peque\u00f1o mundo en el sistema solar con una atm\u00f3sfera que no deber\u00eda tener"},"content":{"rendered":"<p>A pesar de que la humanidad cuente con la mejor tecnolog\u00eda, y que seamos capaces de descubrir estrellas que se encuentran a millones de a\u00f1os luz, lo cierto es que <strong>nuestro propio sistema solar sigue siendo un gran desconocido<\/strong> que esconde muchos misterios. Si hace solo unos d\u00edas <a data-external=\"0\" data-intl-links-ca=\"https:\/\/www.elnacional.cat\/ca\/tecnologia\/astronoms-detecten-alguna-cosa-gran-mes-enlla-neptu-nove-planeta-torna-escena_1634425_102.html\" data-intl-links-es=\"https:\/\/www.elnacional.cat\/es\/tecnologia\/astronomos-detectan-algo-grande-mas-alla-neptuno-noveno-planeta-vuelve-escena_1634425_102.html\" href=\"https:\/\/www.elnacional.cat\/es\/tecnologia\/astronomos-detectan-algo-grande-mas-alla-neptuno-noveno-planeta-vuelve-escena_1634425_102.html\" rel=\"follow nofollow noopener\" target=\"_self\" title=\"Astr\u00f3nomos detectan algo grande m\u00e1s all\u00e1 de Neptuno: el noveno planeta vuelve a escena\">cient\u00edficos aseguraban haber encontrado se\u00f1ales del \u201cplaneta 9\u201d m\u00e1s all\u00e1 de Neptuno<\/a>, ahora han encontrado <strong>una peque\u00f1a\u00a0atm\u00f3sfera que envuelve un diminuto mundo helado<\/strong> que, en teor\u00eda, no deber\u00eda tener ninguna.<\/p>\n<p>Este peque\u00f1o mundo tiene una peque\u00f1a atm\u00f3sfera que no deber\u00eda existir<\/p>\n<p>Un grupo de astr\u00f3nomos japoneses ha descubierto que <strong>el objeto helado 2002 XV93, situado en el sistema solar exterior, podr\u00eda estar rodeado por una tenue atm\u00f3sfera<\/strong>. El hallazgo sorprendi\u00f3 a los cient\u00edficos, ya que este peque\u00f1o cuerpo es demasiado diminuto para conservar gas durante mucho tiempo.<\/p>\n<p>El objeto est\u00e1 situado <strong>mucho m\u00e1s all\u00e1 de la \u00f3rbita de Neptuno<\/strong>, donde se encuentran\u00a0miles de cuerpos helados conocidos como objetos transneptunianos.\u00a0Plut\u00f3n es el ejemplo m\u00e1s conocido y uno de los pocos con una atm\u00f3sfera delgada confirmada, por eso hasta hace unos a\u00f1os era considerado tambi\u00e9n un planeta.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\nRecreaci\u00f3n del objeto 2002 XV93 | Imagen: NAOJ&#13;<\/p>\n<p>La atm\u00f3sfera fue detectada gracias a <strong>una ligera disminuci\u00f3n en la luz de una estrella durante una alineaci\u00f3n poco com\u00fan<\/strong>. Adem\u00e1s, los c\u00e1lculos indican que deber\u00eda desaparecer en apenas mil a\u00f1os, a menos que exista alg\u00fan proceso que la reponga constantemente. Esto significa que la atm\u00f3sfera debe haberse formado o renovado relativamente hace poco tiempo.<\/p>\n<p>Los datos del <strong>Telescopio Espacial James Webb aportan otra pieza al rompecabezas<\/strong>. Las observaciones no muestran evidencia de gases congelados en la superficie que pudieran convertirse lentamente en vapor y mantener una atm\u00f3sfera.<\/p>\n<p>Lo que lleva a los cient\u00edficos a considerar otras explicaciones. Una posibilidad es que <strong>material del interior de ese peque\u00f1o mundo\u00a0haya llegado a la superficie<\/strong>, liberando gas. Otra es que el <strong>impacto de un cometa<\/strong> haya depositado o liberado suficiente material para crear una atm\u00f3sfera temporal. Aunque ser\u00e1n necesarias m\u00e1s investigaciones para conocer qu\u00e9 es lo que est\u00e1 ocurriendo exactamente en\u00a02002 XV93.<\/p>\n","protected":false},"excerpt":{"rendered":"A pesar de que la humanidad cuente con la mejor tecnolog\u00eda, y que seamos capaces de descubrir estrellas&hellip;\n","protected":false},"author":2,"featured_media":543455,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[119,123,124,25,24,117,121,122,23,118,120],"class_list":{"0":"post-543454","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciencia-y-tecnologia","8":"tag-ciencia","9":"tag-ciencia-y-tecnologia","10":"tag-cienciaytecnologia","11":"tag-es","12":"tag-espana","13":"tag-science","14":"tag-science-and-technology","15":"tag-scienceandtechnology","16":"tag-spain","17":"tag-technology","18":"tag-tecnologia"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116550355151743413","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/543454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=543454"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/543454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/543455"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=543454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=543454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=543454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}