{"id":543536,"date":"2026-05-10T13:53:12","date_gmt":"2026-05-10T13:53:12","guid":{"rendered":"https:\/\/www.europesays.com\/es\/543536\/"},"modified":"2026-05-10T13:53:12","modified_gmt":"2026-05-10T13:53:12","slug":"barcelona-real-madrid-en-directo-previa-y-ultima-hora-de-la-laliga-ea-sports-hoy-en-vivo","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/543536\/","title":{"rendered":"Barcelona &#8211; Real Madrid, en directo: previa y \u00faltima hora de la LaLiga EA Sports hoy, en vivo"},"content":{"rendered":"<p class=\"ev-title\">Real Madrid TV y el \u00e1rbitro<\/p>\n<p>El colegiado del encuentro ser\u00e1 Hern\u00e1ndez Hern\u00e1ndez y en Real Madrid tv hacenun v\u00eddeo: \u00abEl \u00e1rbitro, Hern\u00e1ndez Hern\u00e1ndez, admiti\u00f3 hace a\u00f1os, en una entrevista con el peri\u00f3dico, que era hincha del Barcelona.\u00a0Arbitr\u00f3 algunos Cl\u00e1sicos, y en uno de ellos no pit\u00f3 dos penaltis a favor de Raphael Varane, el primero por una falta y el segundo por una dura entrada de Lenglet, que dej\u00f3 la pierna del jugador franc\u00e9s cubierta de sangre\u00bb.<\/p>\n<p>Tambi\u00e9n hablan de Iglesias Villanueva, colegiado de VAR del partido: \u00abIgnor\u00f3 una mano de Paulo Tour\u00e9 que habr\u00eda dado un penalti al Real Madrid contra el Real Mallorca, estar\u00e1 en la sala del VAR.\u00a0Tambi\u00e9n pas\u00f3 por alto, en otro partido contra el Mallorca, el pitar un penalti y no expulsar a Maffeo tras una dura entrada sobre Vinicius Junior, y estas decisiones y errores contribuyeron a impedir que el Real Madrid compitiera por el t\u00edtulo de la Liga espa\u00f1ola\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"Real Madrid TV y el \u00e1rbitro El colegiado del encuentro ser\u00e1 Hern\u00e1ndez Hern\u00e1ndez y en Real Madrid tv&hellip;\n","protected":false},"author":2,"featured_media":543537,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[168,25,24,23,167],"class_list":{"0":"post-543536","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-deportes","9":"tag-es","10":"tag-espana","11":"tag-spain","12":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116550618892426162","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/543536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=543536"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/543536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/543537"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=543536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=543536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=543536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}