{"id":544742,"date":"2026-05-11T06:23:17","date_gmt":"2026-05-11T06:23:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/544742\/"},"modified":"2026-05-11T06:23:17","modified_gmt":"2026-05-11T06:23:17","slug":"mas-de-30-participantes-recorren-siero-en-una-vuelta-ciclista-no-competitiva","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/544742\/","title":{"rendered":"M\u00e1s de 30 participantes recorren Siero en una vuelta ciclista no competitiva"},"content":{"rendered":"<p class=\"ft-text\">Una vuelta para <strong>conocer el concejo sobre dos ruedas <\/strong>y sin preocuparse por el podium. La <strong>quinta edici\u00f3n de la Vuelta a Siero<\/strong> ha contado este domingo con la participaci\u00f3n de <strong>30 ciclistas<\/strong>, que tomaron la salida desde el nuevo polideportivo de La Pola Siero para completar una<strong> marcha no competitiva de 51 kil\u00f3metros por la zona oriental y central del municipio.<\/strong><\/p>\n<p class=\"ft-text\">La cita, de car\u00e1cter l\u00fadico, recorri\u00f3 parte del trazado utilizado recientemente por la <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.lne.es\/deportes\/deporte-astur\/2026\/04\/25\/nairo-vuelve-reinar-cronica-jose-129504336.html\" rel=\"nofollow noopener\" target=\"_blank\">Vuelta a Asturias<\/a> y permiti\u00f3 a los participantes afrontar algunos de los puertos m\u00e1s conocidos del ciclismo sierense. El itinerario incluy\u00f3 las ascensiones a los<strong> altos de Munc\u00f3 y Mu\u00f1\u00f3, el paso por Valdesoto y la subida final al Piqueru antes del regreso al punto de salida.<\/strong><\/p>\n<p>Desnivel<\/p>\n<p class=\"ft-text\">La prueba se desarroll\u00f3 sobre un perfil ondulado, con unos <strong>750 metros de desnivel acumulado<\/strong>, y no hubo clasificaci\u00f3n ni dorsales, manteniendo el esp\u00edritu participativo de una actividad abierta a aficionados de todas las edades.<\/p>\n<p class=\"ft-text\">La Vuelta a Siero forma parte de la segunda edici\u00f3n del <strong>programa del Patronato Deportivo Municipal \u201c\u00bfEn Siero? S\u00ed, en bici\u201d<\/strong>, una iniciativa orientada a fomentar el uso de la bicicleta como medio de transporte y promover la pr\u00e1ctica deportiva al aire libre.<\/p>\n","protected":false},"excerpt":{"rendered":"Una vuelta para conocer el concejo sobre dos ruedas y sin preocuparse por el podium. La quinta edici\u00f3n&hellip;\n","protected":false},"author":2,"featured_media":544743,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[273],"tags":[1881,313,2838,312,168,1053,25,24,7789,2599,15667,37901,19973,23,167,1357],"class_list":{"0":"post-544742","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciclismo","8":"tag-1881","9":"tag-ciclismo","10":"tag-ciclistas","11":"tag-cycling","12":"tag-deportes","13":"tag-domingo","14":"tag-es","15":"tag-espana","16":"tag-la-vuelta","17":"tag-participacion","18":"tag-participantes","19":"tag-recorren","20":"tag-siero","21":"tag-spain","22":"tag-sports","23":"tag-vuelta"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116554511668962262","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/544742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=544742"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/544742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/544743"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=544742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=544742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=544742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}