{"id":544784,"date":"2026-05-11T06:57:17","date_gmt":"2026-05-11T06:57:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/544784\/"},"modified":"2026-05-11T06:57:17","modified_gmt":"2026-05-11T06:57:17","slug":"cronica-del-valencia-cf-granada-cf-de-copa-de-campeones-juvenil-granada-cf","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/544784\/","title":{"rendered":"Cr\u00f3nica del Valencia CF &#8211; Granada CF de Copa de Campeones Juvenil | Granada CF"},"content":{"rendered":"<p style=\"text-align: justify;\">El<strong> Juvenil A<\/strong> del <strong>Granada Club de F\u00fatbol <\/strong>arranc\u00f3 su aventura en la <strong>Copa de Campeones <\/strong>con remontada y victoria en casa del <strong>Valencia CF<\/strong>, campe\u00f3n del grupo 7. En el Antonio Puchades de la ciudad deportiva del club che, el equipo de <strong>Sergio Ortiz<\/strong> sufri\u00f3 un gol en contra a la hora de encuentro, pero acto seguido logr\u00f3 remontar gracias a un doblete de <strong>Owen<\/strong>, lo que da ventaja moment\u00e1nea a los rojiblancos de cara a la resoluci\u00f3n del jueves antes de una hipot\u00e9tica final four.<\/p>\n<p style=\"text-align: justify;\">Por parte visitante, salieron de inicio: Carlos Guirao en porter\u00eda; Diego Cosma, Morilla, Bourama y Pablo Jim\u00e9nez atr\u00e1s; Dylan Rodr\u00edguez y Manu Maza en el centro del campo, con Mario Jim\u00e9nez m\u00e1s adelantado; Aitor y Owen por las bandas; y Enrique Bass en punta de ataque.<\/p>\n<p style=\"text-align: justify;\">Tras un primer tiempo en el que el dominio fue alterno y los visitantes generaron serio peligro a bal\u00f3n parado, se lleg\u00f3 a un segundo donde el primer golpe lo dio el conjunto valencianista. A la hora de partido, Ochoa defini\u00f3 cruzado ante Carlos Guirao, poniendo el 1-0 en el marcador.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, lejos de achicarse, el Granada, por mediaci\u00f3n de Owen en hasta dos ocasiones, consigui\u00f3 remontar. El primero, con un latigazo ajustado desde el v\u00e9rtice del \u00e1rea y, el segundo, con un remate al palo largo.<\/p>\n<p style=\"text-align: justify;\">Con ese 1-2 en el luminoso, a los pupilos de Sergio Ortiz les toc\u00f3 aguantar durante los \u00faltimos minutos, haciendo bueno el doblete del extremo malague\u00f1o para afrontar con un resultado positivo la vuelta de la eliminatoria en el Estadio Antonio Bail\u00f3n de Peligros, el pr\u00f3ximo jueves 14 de mayo, a las 19.00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"El Juvenil A del Granada Club de F\u00fatbol arranc\u00f3 su aventura en la Copa de Campeones con remontada&hellip;\n","protected":false},"author":2,"featured_media":544785,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[168,25,24,23,167],"class_list":{"0":"post-544784","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-deportes","9":"tag-es","10":"tag-espana","11":"tag-spain","12":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116554645334030251","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/544784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=544784"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/544784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/544785"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=544784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=544784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=544784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}