{"id":545529,"date":"2026-05-11T16:02:14","date_gmt":"2026-05-11T16:02:14","guid":{"rendered":"https:\/\/www.europesays.com\/es\/545529\/"},"modified":"2026-05-11T16:02:14","modified_gmt":"2026-05-11T16:02:14","slug":"canarias-estudia-ir-a-los-tribunales-ante-una-posible-invasion-competencial-de-transportes-para-imponer-el-fondeo-del-hondius","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/545529\/","title":{"rendered":"Canarias estudia ir a los tribunales ante una posible invasi\u00f3n competencial de Transportes para imponer el fondeo del Hondius"},"content":{"rendered":"<p><img decoding=\"async\" class=\"v-ath__i\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/autor-7304-foto-15.jpeg\" alt=\"Joan Guirado\"\/><\/p>\n<p>11\/05\/2026<\/p>\n<p>Actualizado a las 16:32h.<\/p>\n<p class=\"v-d-p\" style=\"\">El presidente del Gobierno de Canarias, Fernando Clavijo, estudia acudir a los tribunales ante una posible invasi\u00f3n competencial por parte del Ministerio de Transportes a la hora de imponer el fondeo del crucero MV <a href=\"https:\/\/www.abc.es\/sociedad\/tecnico-ministerio-sanidad-baja-autobus-transportaba-viajeros-20260510193523-nt.html\" target=\"_self\" data-voc-vtm-id=\"in-text-traffic\" title=\"Hondius\" data-mrf-link=\"www.abc.es\" rel=\"nofollow noopener\">Hondius<\/a> en Granadilla de Abona. Fuentes cercanas a Clavijo explican  &#8230; en ABC que tomar\u00e1n la decisi\u00f3n en los pr\u00f3ximos d\u00edas, cuando el dispositivo de evacuaci\u00f3n y repatriaci\u00f3n ya haya culminado, a la espera de la salida de una parte del pasaje que desembarcar\u00e1n esta tarde, para no afectar al mismo.<\/p>\n<p class=\"v-d-p\" style=\"\">La decisi\u00f3n del Gobierno auton\u00f3mico tiene que ver con lo que ocurri\u00f3 la madrugada del pasado s\u00e1bado a domingo. Al borde de la medianoche, tras una reuni\u00f3n con los tres ministros desplazados a la isla de Tenerife, y al confirmarse que el buque estar\u00eda en el puerto de Granadilla alrededor de 36 horas, Clavijo anunci\u00f3 que hab\u00eda dado orden al presidente de la Autoridad Portuaria de Santa Cruz de denegar la autorizaci\u00f3n del fondeo. Minutos despu\u00e9s la directora general de la Marina Mercante firm\u00f3 una resoluci\u00f3n dejando sin efecto la decisi\u00f3n del presidente de Canarias, que podr\u00eda haber bloqueado el operativo. Todo ocurri\u00f3 a altas horas de la madrugada.<\/p>\n<ul class=\"v-cmp-rld__u\">\n<li class=\"v-cmp-rld__l\">\n<p><a class=\"v-a-lnk\" href=\"http:\/\/www.abc.es\/sociedad\/rosa-davila-presidenta-cabildo-tenerife-cataluna-pais-20260511160020-nt.html#vtm_modulosEngag=noticiasrelacionadas-cmp-uno:sociedad:noticia:1\" title=\"Rosa D\u00e1vila, presidenta del Cabildo de Tenerife: \u00abCon Catalu\u00f1a o Pa\u00eds Vasco no habr\u00edan actuado igual. Ven\u00edan a hacerse la foto\u00bb\" data-voc-vtm-id=\"in-text-traffic\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/imagen-entrevista-kvzB-U20816600550sre-366x256@diario_abc.JPG\" class=\"v-a-img\" width=\"258\" height=\"180\" alt=\"Rosa D\u00e1vila, presidenta del Cabildo de Tenerife: \u00abCon Catalu\u00f1a o Pa\u00eds Vasco no habr\u00edan actuado igual. Ven\u00edan a hacerse la foto\u00bb\"\/><br \/>\n<\/a><\/p>\n<\/li>\n<\/ul>\n<p class=\"v-d-p\" style=\"\">En el Gobierno de Canarias existen serias dudas si la aplicaci\u00f3n del art\u00edculo 299 de la Ley de Puertos sirve para lo que el Ministerio de Transportes lo utiliz\u00f3. Dicho art\u00edculo regula que la Direcci\u00f3n General de la Marina Mercante puede autorizar la entrada a puerto y desembarco de un buque que est\u00e9 en riesgo de naufragio. Esa casu\u00edstica no corresponde con lo que pasaba con el buque MV Hondius, cuya llegada a Granadilla de Abona y evacuaci\u00f3n en esas instalaciones portuarias respond\u00eda a una cuesti\u00f3n de Salud P\u00fablica en virtud de la legalidad internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"11\/05\/2026 Actualizado a las 16:32h. El presidente del Gobierno de Canarias, Fernando Clavijo, estudia acudir a los tribunales&hellip;\n","protected":false},"author":2,"featured_media":545530,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[1575,17,18,1896,106185,25,24,12188,13,14,105939,89846,11,105395,40509,5955,19,20,9,10,15,16,2397,23,12,24674,493,21,22],"class_list":{"0":"post-545529","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espana","8":"tag-ante","9":"tag-breaking-news","10":"tag-breakingnews","11":"tag-canarias","12":"tag-competencial","13":"tag-es","14":"tag-espana","15":"tag-estudia","16":"tag-featured-news","17":"tag-featurednews","18":"tag-fondeo","19":"tag-granadilla","20":"tag-headlines","21":"tag-hondius","22":"tag-imponer","23":"tag-invasion","24":"tag-latest-news","25":"tag-latestnews","26":"tag-news","27":"tag-noticias","28":"tag-noticias-destacadas","29":"tag-noticiasdestacadas","30":"tag-posible","31":"tag-spain","32":"tag-titulares","33":"tag-transportes","34":"tag-tribunales","35":"tag-ultimas-noticias","36":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116556789033732270","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/545529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=545529"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/545529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/545530"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=545529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=545529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=545529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}