{"id":545614,"date":"2026-05-11T17:05:15","date_gmt":"2026-05-11T17:05:15","guid":{"rendered":"https:\/\/www.europesays.com\/es\/545614\/"},"modified":"2026-05-11T17:05:15","modified_gmt":"2026-05-11T17:05:15","slug":"sinner-avanza-sin-sobresaltos-a-octavos-tras-dominar-a-popyrin","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/545614\/","title":{"rendered":"Sinner avanza sin sobresaltos a octavos tras dominar a Popyrin"},"content":{"rendered":"<p class=\"mb-4 text-lg md:leading-8 break-words\">Roma, 11 may (EFE).- Jannik Sinner venci\u00f3 este lunes al australiano Alexei Popyrin en la tercera ronda del Masters 1.000 de Roma (6-2, 6-0) para clasificarse a los octavos de final, en un partido que domin\u00f3 de principio a fin y que confirm\u00f3 su ambici\u00f3n de hacerse con el \u00fanico trofeo del circuito que falta en su palmar\u00e9s.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">El n\u00famero uno del mundo confirm\u00f3 su condici\u00f3n de favorito en la capital italiana, arropado por la afici\u00f3n, despu\u00e9s de imponerse con autoridad, mantener el control en todo momento y brillar ante un rival sin respuestas.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Solo concedi\u00f3 un punto y acab\u00f3 el partido en una hora y seis minutos. El tenista de San C\u00e1ndido avanz\u00f3 as\u00ed a la siguiente fase de un torneo marcado por la ausencia de Carlos Alcaraz y por la ambici\u00f3n de completar la colecci\u00f3n de t\u00edtulos Masters 1.000, una haza\u00f1a de la que hasta el momento solo puede presumir el serbio Nokvak Djokovic.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Son treinta las victorias consecutivas del tenista de San C\u00e1ndido en un torneo de este nivel, y atraviesa el que probablemente sea el momento m\u00e1s dulce de su carrera hasta ahora tras ganar de forma seguida, algo que era in\u00e9dito, Par\u00eds, Indian Wells, Miami, Montecarlo y Madrid.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Poyrin, de 26 a\u00f1os, fue incapaz de prestarle batalla. El tenista que creci\u00f3 teniendo como \u00eddolo al argentino Juan Mart\u00edn del Potro no super\u00f3 su techo en la arcilla romana, la tercera ronda. Tampoco un hito en su carrera, el de ganar por primera vez a un n\u00famero uno.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Sinner comenz\u00f3 el encuentro rompi\u00e9ndole el saque al australiano. Cometi\u00f3 varios errores con la derecha, pero se sobrepuso con solidez y solo concedi\u00f3 un punto de quiebre en el primer set, que domin\u00f3 por completo. Popyrin no se encontr\u00f3, m\u00e1s all\u00e1 de varios servicios con un potente saque que s\u00ed logr\u00f3 atravesar moment\u00e1neamente el muro del rival.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Pero Sinner le pas\u00f3 por encima. El n\u00famero uno cerr\u00f3 el primer set en 39 minutos sin arriesgar mucho. El australiano no pudo hacer nada en los intercambios desde el fondo de la pista y no consigui\u00f3 seguirle el ritmo.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">La segunda manga fue incluso m\u00e1s dura para el australiano, que no logr\u00f3 conectar. Sinner le rob\u00f3 el servicio hasta dos veces e hizo valer los suyos para ponerse r\u00e1pidamente 4-0. Popyrin se qued\u00f3 sin respuesta alguna. Sinner brill\u00f3 tambi\u00e9n con su servicio. Y cerr\u00f3 la victoria muy r\u00e1pido, en poco m\u00e1s de una hora.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">El m\u00e1ximo favorito lo hizo, seg\u00fan dijo tras ganar sobre la pista, en un partido con unas \u00abcondiciones dif\u00edciles\u00bb: \u00abHab\u00eda bastante viento\u00bb, confes\u00f3, antes de dar las gracias a todos por el apoyo.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Popyrin y Sinner ya se enfrentaron tres veces en su carrera, con dos victorias para el italiano, la \u00faltima en Doha precisamente esta temporada.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">El Foro It\u00e1lico sue\u00f1a con que un italiano vuelva a levantar el trofeo en la arcilla romana, algo que no sucede desde 1976, y el de San C\u00e1ndido mantiene viva esa ilusi\u00f3n tras superar una nueva ronda en su camino.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Sinner suma y sigue, y avanza paso a paso en su objetivo de lograr la haza\u00f1a de conquistar el \u00fanico Masters 1.000 que falta en su vitrina, el &#8216;Career Golden Master&#8217; que solo posee Djokovic, quien lo logr\u00f3 hasta en dos ocasiones.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">El transalpino protagonizar\u00e1 as\u00ed un derbi italiano en la siguiente ronda ante Andrea Pellegrino, una de las revelaciones este torneo que se clasific\u00f3 tras acabar con el estadounidense Frances Tiafoe en su primera participaci\u00f3n en un cuadro principal del Masters 1.000.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">(c) Agencia EFE<\/p>\n","protected":false},"excerpt":{"rendered":"Roma, 11 may (EFE).- Jannik Sinner venci\u00f3 este lunes al australiano Alexei Popyrin en la tercera ronda del&hellip;\n","protected":false},"author":2,"featured_media":545615,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[106200,168,995,25,24,17402,4466,23,167],"class_list":{"0":"post-545614","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-alexei-popyrin","9":"tag-deportes","10":"tag-efe","11":"tag-es","12":"tag-espana","13":"tag-octavos-de-final","14":"tag-sinner","15":"tag-spain","16":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116557036232475734","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/545614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=545614"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/545614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/545615"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=545614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=545614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=545614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}