{"id":547039,"date":"2026-05-12T12:16:13","date_gmt":"2026-05-12T12:16:13","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547039\/"},"modified":"2026-05-12T12:16:13","modified_gmt":"2026-05-12T12:16:13","slug":"la-famiglia-se-sienta-a-la-mesa-se-une-a-lafamilia-de-la-federacion-espanola-de-baloncesto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547039\/","title":{"rendered":"La Famiglia se sienta a la mesa se une a #LaFamilia de la Federaci\u00f3n Espa\u00f1ola de Baloncesto"},"content":{"rendered":"<p>La Famiglia se sienta a la mesa se une a #LaFamilia de la Federaci\u00f3n Espa\u00f1ola de Baloncesto<\/p>\n<p>La Famiglia se sienta a la mesa (anteriormente La Mafia) ha firmado un acuerdo de colaboraci\u00f3n con la Federaci\u00f3n Espa\u00f1ola de Baloncesto (FEB), organismo rector del baloncesto en Espa\u00f1a y una de las instituciones deportivas de mayor proyecci\u00f3n nacional e internacional.<\/p>\n<p>El acuerdo vincula a la marca con el universo de #LaFamilia, el concepto con el que la FEB construye comunidad alrededor de los aficionados al baloncesto espa\u00f1ol y de sus selecciones nacionales. Una identidad basada en valores como la uni\u00f3n, el trabajo en equipo, la cercan\u00eda y el sentimiento de pertenencia.<\/p>\n<p>Para La Famiglia se sienta a la mesa, esta colaboraci\u00f3n supone un paso natural dentro de su evoluci\u00f3n de nombre, tal y como afirma su CEO, Javier Florist\u00e1n: \u201cCompartimos con la FEB una visi\u00f3n com\u00fan: reunir a las personas alrededor de experiencias compartidas, ya sea en la cancha, en la grada o en torno a una mesa\u201d.<\/p>\n<p>La Federaci\u00f3n Espa\u00f1ola de Baloncesto cuenta actualmente con m\u00e1s de 451.000 licencias en Espa\u00f1a, m\u00e1s de 157.000 mujeres practicando baloncesto, audiencias superiores a 11 millones de espectadores en televisi\u00f3n y una comunidad digital de m\u00e1s de 1,3 millones de seguidores en redes sociales.<\/p>\n<p>Adem\u00e1s, su actividad abarca tanto las selecciones nacionales masculinas y femeninas como las principales competiciones nacionales, incluyendo modalidades como el 5&#215;5 y el 3&#215;3, con presencia habitual en grandes torneos internacionales como Eurobasket, Mundiales y Juegos Ol\u00edmpicos.<\/p>\n<p>En el marco del acuerdo, La Famiglia se sienta a la mesa podr\u00e1 desarrollar diferentes l\u00edneas de activaci\u00f3n vinculadas al ecosistema FEB, lo que incluye la asociaci\u00f3n y vinculaci\u00f3n de los valores que ambas entidades comparten y que, tras este acuerdo, se potenciar\u00e1n mutuamente. Con esta alianza, La Famiglia se sienta a la mesa refuerza su posicionamiento como una marca cercana, experiencial y vinculada a los momentos compartidos, al mismo tiempo que se suma a uno de los territorios emocionales m\u00e1s reconocibles del deporte espa\u00f1ol: #LaFamilia.<\/p>\n<p>Este patrocinio supone un hito hist\u00f3rico para La Famiglia se sienta a la mesa, al formar parte de una nueva etapa estrat\u00e9gica en la que la marca refuerza su presencia y notoriedad a nivel nacional. La acci\u00f3n se enmarca dentro del plan de medios nacional que la compa\u00f1\u00eda est\u00e1 impulsando por primera vez en su historia, acompa\u00f1ando su evoluci\u00f3n de marca y consolidando su posicionamiento dentro del sector de la restauraci\u00f3n organizada.<\/p>\n<p>M\u00e1s sobre LMssLM<br \/>&#13;<br \/>\nEl Grupo LMssLM se funda en el a\u00f1o 2000 en Zaragoza y en los \u00faltimos a\u00f1os ha experimentado un crecimiento exponencial con tus tres marcas de gastronom\u00eda italiana: La Famiglia se sienta a la mesa, Ditaly y La Boutique Trattoria Viajera. El Grupo se caracteriza por unos valores muy marcados como la originalidad, la calidad de sus productos y la innovaci\u00f3n. El Grupo cuenta con un obrador propio donde se elaboran sus productos para distribuir a cualquier unidad de negocio de Espa\u00f1a, Portugal y Andorra. Tras m\u00e1s de 25 a\u00f1os de \u00e9xito, el Grupo LMssLM se ha consolidado como un referente de la gastronom\u00eda italiana en Espa\u00f1a. Su compromiso con la calidad de la materia prima, la autenticidad de los sabores y una apuesta constante por las \u00faltimas tendencias en decoraci\u00f3n lo han convertido en un modelo dentro del sector. Actualmente, el Grupo cuenta con m\u00e1s de 110 unidades operativas en Espa\u00f1a, Portugal y Andorra.<\/p>\n","protected":false},"excerpt":{"rendered":"La Famiglia se sienta a la mesa se une a #LaFamilia de la Federaci\u00f3n Espa\u00f1ola de Baloncesto La&hellip;\n","protected":false},"author":2,"featured_media":547040,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[4605,299,1918,298,4597,4613,4616,4609,4608,4610,168,4603,4606,25,24,4120,4598,4614,2713,4601,830,4599,4600,4602,4615,4617,4607,4604,23,167,4611,4612],"class_list":{"0":"post-547039","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-baloncesto","8":"tag-arbitros-baloncesto","9":"tag-baloncesto","10":"tag-basket","11":"tag-basketball","12":"tag-basquet","13":"tag-canalfeb","14":"tag-clasificacion","15":"tag-copa-princesa","16":"tag-copa-principe","17":"tag-copa-reina","18":"tag-deportes","19":"tag-eba","20":"tag-entrenadores-baloncesto","21":"tag-es","22":"tag-espana","23":"tag-estadisticas","24":"tag-federacion-baloncesto","25":"tag-jornada-virtual","26":"tag-jugadores","27":"tag-laeb-plata","28":"tag-leb-oro","29":"tag-liga-espana","30":"tag-liga-espanola-baloncesto","31":"tag-liga-femenina","32":"tag-marcadores-baloncesto","33":"tag-rankings","34":"tag-reglas-baloncesto","35":"tag-seleccion-baloncesto","36":"tag-spain","37":"tag-sports","38":"tag-supercopa","39":"tag-television-baloncesto"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547039"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547040"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}