{"id":547164,"date":"2026-05-12T13:58:17","date_gmt":"2026-05-12T13:58:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547164\/"},"modified":"2026-05-12T13:58:17","modified_gmt":"2026-05-12T13:58:17","slug":"flick-confirma-su-renovacion-estoy-contento-por-la-confianza-que-me-ha-dado-el-club","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547164\/","title":{"rendered":"Flick confirma su renovaci\u00f3n: \u00abEstoy contento por la confianza que me ha dado el club\u00bb"},"content":{"rendered":"<p class=\"mb-4 text-lg md:leading-8 break-words\">Sant Joan Desp\u00ed (Barcelona), 12 may (EFE).- El entrenador del Barcelona, Hansi Flick, confirm\u00f3 este martes que renovar\u00e1 con el club azulgrana hasta 2028, con un a\u00f1o m\u00e1s opcional, y se mostr\u00f3 agradecido a la entidad por la confianza que le est\u00e1 dando.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u00abEstoy muy agradecido al club por poder entrenar hasta 2028. El club tendr\u00e1 el derecho de pararlo, yo tambi\u00e9n. Ya se hablar\u00e1 de ese a\u00f1o opcional. En los \u00faltimos d\u00edas, me ha quedado claro que estoy en el lugar adecuado. Ahora hay que trabajar m\u00e1s duro, alcanzar el mejor nivel y conseguir t\u00edtulos. Todos tienen ese sue\u00f1o de ganar la &#8216;Champions&#8217; y lo volveremos a intentar\u00bb, asegur\u00f3.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">El t\u00e9cnico alem\u00e1n hizo estas declaraciones en la previa del partido de LaLiga frente al Alav\u00e9s, despu\u00e9s de que el lunes varias informaciones avanzaran que hab\u00eda llegado a un acuerdo verbal para renovar con la entidad catalana, que todav\u00eda no lo ha hecho oficial.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">La comparecencia ha tenido lugar un d\u00eda despu\u00e9s de la r\u00faa por las calles de Barcelona para celebrar el t\u00edtulo que el primer equipo azulgrana gan\u00f3 el pasado domingo ante el Real Madrid en el Spotify Camp Nou.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Flick agradeci\u00f3 el apoyo de la afici\u00f3n durante las celebraciones -\u00abfue muy emotivo ver l\u00e1grimas en los ojos de la gente\u00bb, ha destacado- y, al ser preguntado qu\u00e9 le pareci\u00f3 que durante la r\u00faa Lamine Yamal ondeara una bandera de Palestina, ha respondido: \u00abSon cosas que no me gustan. He hablado con \u00e9l y si \u00e9l quiere hacerlo\u2026 es su decisi\u00f3n. Tiene 18 a\u00f1os\u00bb.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Tras la conquista del t\u00edtulo, Flick ha recordado que tienen el objetivo de \u00absumar los 100 puntos\u00bb, algo que solo se ha conseguido una vez en la historia del club, en la temporada 2012-13, con Tito Vilanova de entrenador.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u00abPara ello, hay que ganar los tres partidos que quedan y jugar bien\u00bb, ha afirmado Flick, quien ha afirmado que no ha hablado con sus jugadores sobre los premios Zamora, por el que pugna el portero Joan Garcia, y Zarra, que puede ganar Ferran Torres como mejor goleador espa\u00f1ol de la temporada. En este sentido, ha puntualizado que \u00ablo importante\u00bb es el equipo.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Asimismo, se ha referido a algunos nombres propios de la plantilla como los delanteros Marcus Rashford y Robert Lewandowski, cuya continuidad no est\u00e1 asegurada para la pr\u00f3xima temporada.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u00abLos valoro mucho, pero tenemos que analizarlo todo y ya se ver\u00e1 al final de temporada. Las cifras de Marcus son buenas. Y de Robert, qu\u00e9 puedo decir. He ganado t\u00edtulos con \u00e9l\u00bb, ha dicho.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Tambi\u00e9n ha hablado sobre la situaci\u00f3n de Balde, suplente en los \u00faltimos encuentros tras superar una lesi\u00f3n muscular, de quien ha comentado que le est\u00e1n ayudando para que d\u00e9 \u00abotro paso adelante\u00bb en su trayectoria.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u00abLe pido mejorar d\u00eda a d\u00eda. Es un gran jugador. He hablado con \u00e9l. Cancelo est\u00e1 jugando a un gran nivel y nos ha dado m\u00e1s opciones en ataque\u00bb, ha relatado.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Al ser preguntado por si el equipo cuenta con l\u00edderes para seguir creciendo, Flick ha mencionado varios jugadores que pueden ayudar en esta faceta: \u00abTenemos distintos tipos de l\u00edderes. Gavi desde que volvi\u00f3 a entrenar ha hecho aumentar el nivel de los entrenamientos, es el coraz\u00f3n del equipo. Pedri es un l\u00edder con el bal\u00f3n. Eric tambi\u00e9n lo es. Y tenemos a los capitanes, como Frenkie de Jong, Ronald Araujo y Raphinha\u00bb.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Sobre la confecci\u00f3n de la plantilla de cara al pr\u00f3ximo curso, ha admitido que tanto \u00e9l como el director deportivo, Anderson de Souza &#8216;Deco&#8217;, tienen \u00abclaras\u00bb desde hace meses cu\u00e1les son las prioridades, pero ha subrayado que \u00abel trabajo no ha acabado\u00bb. EFE<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">(c) Agencia EFE<\/p>\n","protected":false},"excerpt":{"rendered":"Sant Joan Desp\u00ed (Barcelona), 12 may (EFE).- El entrenador del Barcelona, Hansi Flick, confirm\u00f3 este martes que renovar\u00e1&hellip;\n","protected":false},"author":2,"featured_media":547165,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[106385,210,168,995,8305,25,24,13342,24534,8138,19309,23,167],"class_list":{"0":"post-547164","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-bandera-de-palestina","9":"tag-barcelona","10":"tag-deportes","11":"tag-efe","12":"tag-el-equipo","13":"tag-es","14":"tag-espana","15":"tag-hansi-flick","16":"tag-la-temporada","17":"tag-lamine-yamal","18":"tag-sant-joan-despi","19":"tag-spain","20":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116561963082299838","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547164"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547165"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}