{"id":547205,"date":"2026-05-12T14:32:15","date_gmt":"2026-05-12T14:32:15","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547205\/"},"modified":"2026-05-12T14:32:15","modified_gmt":"2026-05-12T14:32:15","slug":"alicante-reivindica-los-temas-pendientes-de-la-profesion","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547205\/","title":{"rendered":"Alicante reivindica los temas pendientes de la profesi\u00f3n"},"content":{"rendered":"<p>El <a href=\"https:\/\/www.enferalicante.org\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Colegio de Enfermer\u00eda de Alicante<\/a> ha celebrado en una c\u00e9ntrica plaza de la ciudad de Alicante diferentes actividades con motivo del D\u00eda Internacional de la Enfermera, este a\u00f1o bajo el lema de <a href=\"https:\/\/www.icn.ch\/sites\/default\/files\/inline-files\/ICN_IND2026_report_SP_A4_3.3.pdf\" type=\"link\" id=\"https:\/\/www.icn.ch\/sites\/default\/files\/inline-files\/ICN_IND2026_report_SP_A4_3.3.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u201cNuestras enfermeras. Nuestro futuro. Las enfermeras empoderadas salvan vidas\u201d.<\/a> Una fecha para celebrar corporativamente el trabajo que realizan los profesionales de Enfermer\u00eda, pero tambi\u00e9n para poner el foco de atenci\u00f3n en todos aquellos aspectos y cuestiones que afectan de forma negativa tanto al desarrollo profesional de las enfermeras y enfermeros como a su trabajo diario y a la atenci\u00f3n que se presta a los pacientes y a los usuarios de los sistemas de salud.<\/p>\n<p>Cientos de personas han visitado la carpa ubicada en dicha plaza desde la que se han realizado cribados b\u00e1sicos de salud y se ha instruido sobre c\u00f3mo actuar ante un atragantamiento.\u00a0 Asimismo, han colaborado en adornar con sus mensajes de apoyo a las enfermeras y enfermeros y han planteado numerosas preguntas que han sido expuestas en un panel dando continuidad a la campa\u00f1a \u201cPregunta a tu enfermera\u201d, puesta en marcha por el <a href=\"https:\/\/diarioenfermero.es\/tag\/Consejo-General-de-Enfermeria\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Consejo General de Enfermer\u00eda<\/a> con la colaboraci\u00f3n, entre otros, del Colegio de Enfermer\u00eda de Alicante. Para ello se ha contado con la colaboraci\u00f3n de alumnos de la Universidad CEU Cardenal Herrera, de la Academia COTS y del Colegio Santa Faz de San Vicente del Raspeig.<\/p>\n<p>Junto a ello, en el plano reivindicativo, desde el Colegio de Enfermer\u00eda de Alicante, su presidenta, <a href=\"https:\/\/diarioenfermero.es\/tag\/Montse-Angulo\" type=\"link\" id=\"https:\/\/diarioenfermero.es\/tag\/Montse-Angulo\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Montserrat Angulo<\/a>, se ha hecho eco del documento \u201cLa Enfermer\u00eda como eje estructural del SNS\u201d, confeccionado por el <a href=\"https:\/\/diarioenfermero.es\/tag\/Consejo-General-de-Enfermeria\" type=\"link\" id=\"https:\/\/diarioenfermero.es\/tag\/Consejo-General-de-Enfermeria\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Consejo General de Enfermer\u00eda<\/a>, del que formamos parte, y en el que queda de manifiesto el d\u00e9ficit estructural cr\u00edtico de enfermeras que afecta al Sistema Nacional de Salud frente a lo cual la respuesta no puede limitarse a medidas puntuales, sino que exige una inversi\u00f3n decidida y reformas de fondo en la profesi\u00f3n enfermera. Su mensaje central es que \u201csin enfermeras no hay salud y sin salud no hay futuro\u201d.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/alicante-2-1024x768.jpg\" alt=\"\" class=\"wp-image-102695\" style=\"width:367px;height:auto\"  \/><\/p>\n<p><strong>Una profesi\u00f3n en situaci\u00f3n de riesgo<\/strong><\/p>\n<p>El diagn\u00f3stico inicial describe una situaci\u00f3n de riesgo marcada por tres grandes factores: un d\u00e9ficit estimado de 100.000 enfermeras respecto a la media europea, la previsi\u00f3n de m\u00e1s de 50.000 jubilaciones en la pr\u00f3xima d\u00e9cada y la salida anual de profesionales al extranjero. A ello se suma que Espa\u00f1a presenta una ratio de 6,36 enfermeras por cada 1.000 habitantes, frente a las 8,19 de Europa.<\/p>\n<p><strong>Ratios<\/strong><\/p>\n<p>Datos que en nuestra provincia hacen referencia a que contamos con 4,78 enfermeros\/as en activo por cada 1.000 habitantes y en la Comunidad Valenciana con 5,5.<\/p>\n<p>Ante ello, faltan:<\/p>\n<ul class=\"wp-block-list\">\n<li>1.435 enfermeros\/as para alcanzar la media de la Comunidad Valenciana.<\/li>\n<li>2.811 profesionales para igualar la media nacional.<\/li>\n<li>8.012 enfermeros\/as para situarse al nivel de la Uni\u00f3n Europea.<\/li>\n<\/ul>\n<p>Al ritmo actual de crecimiento, tardar\u00edamos en alcanzar la media europea entre 22 y 29 a\u00f1os.<\/p>\n<p>\u201cEstas ratios insuficientes tienen un efecto directo en peores resultados en salud, mayor riesgo de mortalidad, reingresos y sobrecarga asistencial\u201d, ha indicado la presidenta del Colegio de Enfermer\u00eda de Alicante, Montserrat Angulo.<\/p>\n<p><strong>Sobrecarga laboral y agresiones<\/strong><\/p>\n<p>La profesi\u00f3n de Enfermer\u00eda se ve afectada tambi\u00e9n por un \u201cbucle del abandono\u201d provocado por la sobrecarga, la precariedad contractual, los techos de cristal, el deterioro de la salud mental, las agresiones y la fuga de talento. \u201cEl 39,4% de las enfermeras se plantea abandonar la profesi\u00f3n en los pr\u00f3ximos diez a\u00f1os y el 67% sufre ansiedad, mientras que el 33 padece depresi\u00f3n. La conclusi\u00f3n es clara: solo una intervenci\u00f3n estructural puede romper este ciclo\u201d, a\u00f1ade Montserrat Angulo.<\/p>\n<p><strong>Soluciones claras y concretas<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/alicante-3-1024x768.jpg\" alt=\"\" class=\"wp-image-102696\" style=\"width:443px;height:auto\"  \/><\/p>\n<p>Para solucionar estos problemas, la presidenta del Colegio de Enfermer\u00eda de Alicante coincide con lo planteado en el documento citado anteriormente y destaca que es necesaria una estrategia que se articule en estos cuatro pilares:<\/p>\n<ul class=\"wp-block-list\">\n<li>La clasificaci\u00f3n A1 sin subgrupos. Enfermer\u00eda, pese a contar con grado universitario de 240 cr\u00e9ditos ECTS y nivel acad\u00e9mico equivalente al de otras profesiones, sigue encuadrada en el grupo A2, lo que limita su desarrollo profesional y acceso a puestos de alta gesti\u00f3n. Se reclama que el nuevo Estatuto Marco reconozca el grado en el Grupo A1, las especialidades y m\u00e1steres en el Grupo 7, y el doctorado en el Grupo 8.<\/li>\n<li>El desarrollo real de las especialidades enfermeras. El modelo \u201clow-cost\u201d generalista, basado en utilizar una enfermera \u201cpara todo\u201d, no es v\u00e1lido. Hace falta avanzar hacia un sistema que combine enfermeras generalistas y especialistas.<\/li>\n<li>La prescripci\u00f3n aut\u00f3noma enfermera. El modelo actual genera barreras, retrasos y saturaci\u00f3n, ya que obliga en determinados casos a derivar al m\u00e9dico para obtener una receta. La reforma de la Ley del Medicamento permitir\u00eda que la enfermera atienda, diagnostique y prescriba dentro de su \u00e1mbito competencial, aportando seguridad jur\u00eddica, agilidad y eficiencia al sistema.<\/li>\n<li>La retenci\u00f3n del talento y los entornos seguros. Existen contratos indignos, acumulaci\u00f3n de contratos de d\u00edas u horas, agresiones a enfermeras y una respuesta penal insuficiente ante ellas. Es necesario cuidar a quienes cuidan y eso implica garantizar estabilidad laboral, ratios seguras y tolerancia cero frente a la violencia.<\/li>\n<\/ul>\n<p>A modo de resumen y conclusi\u00f3n, la presidenta del Colegio de Enfermer\u00eda de Alicante ha propuesto en la rueda de prensa celebrada esta ma\u00f1ana traducir estas evidencias en ley: \u201cEs necesario aprobar un Estatuto Marco que reconozca el A1, reformar la Ley del Medicamento y desarrollar un Marco Estrat\u00e9gico de Cuidados centrado en la persona, la calidad, la seguridad, el liderazgo enfermero y la innovaci\u00f3n\u201d.<\/p>\n<p>La presidenta colegial ha estado acompa\u00f1ada en la rueda de prensa por Francisco Ponce, director territorial de la Conselleria de Sanidad en Alicante. Ponce ha indicado que \u201cla Administraci\u00f3n p\u00fablica tiene que estar al lado de los pilares de nuestra sanidad y las enfermeras son las que dan vida tambi\u00e9n al trabajo diario de los sanitarios. Nuestra labor es dar las mayores facilidades de trabajo a nuestros profesionales\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/alicante-4-1024x768.jpg\" alt=\"\" class=\"wp-image-102698\" style=\"width:361px;height:auto\"  \/><\/p>\n<p>El director territorial de Sanidad destac\u00f3 el apoyo a la profesi\u00f3n con la creaci\u00f3n de una jefatura de Cuidados de Enfermer\u00eda que \u201cest\u00e1 trabajando muy bien y estudia de qu\u00e9 forma se pueden mejorar esas ratios\u201d.<\/p>\n<p><strong>Asistencia de autoridades<\/strong><\/p>\n<p>El acto organizado por el Colegio de Enfermer\u00eda ha contado con la asistencia de numerosas autoridades y personalidades como el concejal de Planes Estrat\u00e9gicos y Proyectos Europeos, Sanidad y Protecci\u00f3n Animal del Ayuntamiento de Alicante, Luis Morata, la Bellea del Foc, Mar\u00eda Pastor (que se da la circunstancia de que es estudiante de Enfermer\u00eda), la directora de Enfermer\u00eda del HGU de San Juan, Ver\u00f3nica Amat, la subdirectora de Enfermer\u00eda del mismo centro, Rosa Mar\u00eda Bustos, las subdirectoras de Enfermer\u00eda del HGU Dr Balmis, In\u00e9s Gonz\u00e1lez y Cristina Peydr\u00f3, la directora de Primaria del Departamento de Salud Alicante, Carmen Llabata, el director de Enfermer\u00eda del HACLE de San Vicente, Ismael Esteban, la vicedecana de Enfermer\u00eda de la Facultad de Ciencias de la Salud de la Universidad CEU Cardenal Herrera, y la vicedecana de Enfermer\u00eda de la Universidad Europa de Valencia y directora del Campus de Alicante, Noelia Rodr\u00edguez.<\/p>\n<p>Junto a ellos han asistido tambi\u00e9n diferentes miembros de la Junta de Gobierno del Colegio de Enfermer\u00eda de Alicante.<\/p>\n","protected":false},"excerpt":{"rendered":"El Colegio de Enfermer\u00eda de Alicante ha celebrado en una c\u00e9ntrica plaza de la ciudad de Alicante diferentes&hellip;\n","protected":false},"author":2,"featured_media":547206,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[17,18,106396,106397,106398,25,106399,24,13,14,11,19,20,106400,9,10,15,16,30558,23,12,21,22],"class_list":{"0":"post-547205","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espana","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-colegio-enfermeria-de-alicante","11":"tag-consejo-general-de-enfermeria","12":"tag-dia-internacional-de-las-enfermeras","13":"tag-es","14":"tag-escasez-de-enfermeras","15":"tag-espana","16":"tag-featured-news","17":"tag-featurednews","18":"tag-headlines","19":"tag-latest-news","20":"tag-latestnews","21":"tag-montse-angulo","22":"tag-news","23":"tag-noticias","24":"tag-noticias-destacadas","25":"tag-noticiasdestacadas","26":"tag-ratios","27":"tag-spain","28":"tag-titulares","29":"tag-ultimas-noticias","30":"tag-ultimasnoticias"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116562096909266074","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547205"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547206"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}