{"id":547508,"date":"2026-05-12T18:40:14","date_gmt":"2026-05-12T18:40:14","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547508\/"},"modified":"2026-05-12T18:40:14","modified_gmt":"2026-05-12T18:40:14","slug":"el-sorprendente-plan-b-de-dechambeau-tras-la-crisis-de-liv-vivir-de-youtube","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547508\/","title":{"rendered":"El sorprendente plan B de DeChambeau tras la crisis de LIV: \u00a1vivir de Youtube!"},"content":{"rendered":"<p class=\"ft-text\">El golfista estadounidense Bryson DeChambeau ha abierto la puerta a un futuro lejos de LIV Golf en medio de la incertidumbre que atraviesa el circuito saud\u00ed tras el anuncio de que el fondo soberano PIF dejar\u00e1 de financiar la competici\u00f3n a partir de finales de 2026. <strong>El actual campe\u00f3n del US Open reconoci\u00f3 que el escenario le tom\u00f3 completamente por sorpresa y admiti\u00f3 que ya contempla alternativas tanto dentro como fuera del golf profesional.<\/strong><\/p>\n<p class=\"ft-text\">\u201cMe sorprendi\u00f3 much\u00edsimo, no me lo esperaba\u201d, asegur\u00f3 DeChambeau, una de las principales estrellas de LIV Golf desde su salida del PGA Tour en 2022. <strong>El estadounidense explic\u00f3 que, meses antes, desde la organizaci\u00f3n le hab\u00edan transmitido que el proyecto ten\u00eda financiaci\u00f3n garantizada hasta 2032.<\/strong> Sin embargo, el cambio de rumbo del PIF ha generado dudas sobre la continuidad del circuito y sobre el futuro de muchos de sus jugadores.<\/p>\n<p class=\"ft-text\">Ante esa situaci\u00f3n, DeChambeau afirm\u00f3 que una de sus prioridades ser\u00eda potenciar todav\u00eda m\u00e1s su faceta como creador de contenido. El estadounidense, que supera los 2,5 millones de suscriptores en YouTube, considera que su presencia digital puede convertirse en una plataforma global para seguir impulsando el golf. <strong>\u201cMe encantar\u00eda triplicar el crecimiento de mi canal de YouTube, o incluso m\u00e1s\u201d, explic\u00f3. Entre sus planes, tambi\u00e9n contempla doblar sus v\u00eddeos a diferentes idiomas para ampliar su alcance internacional.<\/strong><\/p>\n<p class=\"ft-text\">Aun as\u00ed, el dos veces ganador de un major no descarta regresar a circuitos tradicionales. DeChambeau reconoci\u00f3 que ha mantenido conversaciones con el PGA Tour sobre una posible vuelta, aunque record\u00f3 que todav\u00eda pesa sobre \u00e9l la suspensi\u00f3n impuesta a los jugadores que abandonaron el circuito para unirse a LIV Golf. <strong>\u201cLas posibles sanciones ser\u00edan bastante desafortunadas, considerando lo que podr\u00eda hacer por ellos\u201d, se\u00f1al\u00f3.<\/strong><\/p>\n<p class=\"ft-text\">El estadounidense tambi\u00e9n aprovech\u00f3 para cuestionar la situaci\u00f3n actual del PGA Tour, a<strong>segurando que el circuito tampoco atraviesa un momento sencillo. \u201cSeamos honestos sobre la situaci\u00f3n. Tienen a los medios de comunicaci\u00f3n de su lado, pero tambi\u00e9n est\u00e1n reduciendo el n\u00famero de participantes, despidiendo empleados y reestructurando su negocio\u201d, <\/strong>afirm\u00f3.<\/p>\n<p class=\"ft-text\"><strong>Las declaraciones de DeChambeau llegan en un momento especialmente delicado para el golf mundial, con el futuro de LIV Golf en entredicho y con las negociaciones para una reunificaci\u00f3n del deporte todav\u00eda sin una soluci\u00f3n definitiva.<\/strong><\/p>\n<p>\u00bfC\u00f3mo podr\u00e1 monetizar?<\/p>\n<p class=\"ft-text\"><strong>El plan de Bryson DeChambeau con YouTube no solo apunta a ganar audiencia, sino tambi\u00e9n a construir una gran fuente de ingresos fuera del golf profesional<\/strong>. El estadounidense ya obtiene beneficios por publicidad gracias a los millones de visualizaciones de su canal, pero el gran negocio est\u00e1 en los patrocinios integrados en los v\u00eddeos y en la expansi\u00f3n internacional de su contenido. <strong>Con doblajes a otros idiomas, m\u00e1s marcas globales y formatos virales de entretenimiento, <\/strong>DeChambeau busca convertir su canal en una plataforma comercial capaz de generar ingresos millonarios m\u00e1s all\u00e1 de los torneos.<\/p>\n","protected":false},"excerpt":{"rendered":"El golfista estadounidense Bryson DeChambeau ha abierto la puerta a un futuro lejos de LIV Golf en medio&hellip;\n","protected":false},"author":2,"featured_media":547509,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275],"tags":[168,25,24,329,23,167],"class_list":{"0":"post-547508","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-golf","8":"tag-deportes","9":"tag-es","10":"tag-espana","11":"tag-golf","12":"tag-spain","13":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116563072284242366","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547508"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547509"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}