{"id":547517,"date":"2026-05-12T18:46:16","date_gmt":"2026-05-12T18:46:16","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547517\/"},"modified":"2026-05-12T18:46:16","modified_gmt":"2026-05-12T18:46:16","slug":"falda-de-cuero-y-blusa-semitransparente-que-no-llevaba-desde-2018","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547517\/","title":{"rendered":"falda de cuero y blusa semitransparente que no llevaba desde 2018"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/reina-sofia_22bf5d7f_260512115557_800x800.webp.webp\" alt=\"reina sof\u00eda\" class=\"image lazyload\" width=\"800\" height=\"800\" data-aspectratio=\"800\/800\"\/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/reina-sofia_22bf5d7f_260512115603_1280x720.webp.webp\" alt=\"Pilar Eyre, periodista especializada en realeza: \u201cDo\u00f1a Sof\u00eda tiene fama de ser muy austera, que la monarqu\u00eda espa\u00f1ola es una monarqu\u00eda pobre, pero la verdad es que tiene joyas fabulosas que no conocemos\u201d\" class=\"image lazyload\" width=\"1280\" height=\"720\" data-aspectratio=\"1280\/720\"\/><\/p>\n<p>La <strong>reina Letizia<\/strong>\u00a0(53 a\u00f1os) es una gran lectora, por eso su presencia en el Premio\u00a0SM &#8216;El Barco de Vapor&#8217; genera m\u00e1s expectaci\u00f3n si cabe. En medio de la revoluci\u00f3n por <a href=\"https:\/\/www.lecturas.com\/realeza\/experta-sobre-video-viral-reina-letizia-tiene-gran-habilidad-para-reconducir-situaciones-inesperadas-sin-generar-incomodidad-ni-humillacion-otra-persona_192656\" target=\"_self\" rel=\"nofollow noopener\">su actitud en uno de sus \u00faltimos actos p\u00fablicos<\/a>, la consorte ha retomado su agenda oficial este martes en Madrid.\u00a0<\/p>\n<p>A lo largo de toda la ma\u00f1ana, do\u00f1a Letizia ha tenido tiempo de ultimar los detalles del acto, ya que no ha sido hasta las 18:00 horas cuando ha reaparecido en\u00a0la <strong>Real Casa de Correos<\/strong>.\u00a0Una velada cultural en la que ha premiado a\u00a0Josan Hatero\u00a0por la obra \u201cLa memoria de las bicicletas\u201d, como mejor obra de literatura infantil y ha entregado el Premio SM &#8216;Gran Angular&#8217; a Alba Quintas Garciandia por &#8216;La cuarta vida de Blanca Cuervo&#8217;, como mejor obra de literatura juvenil por \u201chacer un retrato certero y doloroso de la realidad que vive una parte de la juventud\u201d.<\/p>\n<p>La Reina ha tenido la oportunidad de leerse los dos libros y, tras el acto, ha tenido la oportunidad de charlar con ellos. Un encuentro m\u00e1s distendido en el que se ha interesado por su trabajo.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/reina-letizia_46e51878_260512182203_1200x1800.webp.webp\" alt=\"Reina Letizia\" class=\"lazyload\" width=\"1200\" height=\"1800\" data-aspectratio=\"1200\/1800\"\/>&#13;&#13;Gtres<br \/>\nEl look de trabajo de la reina Letizia para hoy<\/p>\n<p>El tiempo no termina de estabilizarse este mes de mayo y tras las lluvias torrenciales del fin de semana, do\u00f1a Letizia ha ido a lo seguro con un look casual que reafirma que la comodidad no est\u00e1 re\u00f1ida con el estilo.<\/p>\n<p>Para la ocasi\u00f3n, la reina ha rescatado de su armario una misteriosa blusa que luci\u00f3 por \u00faltima vez en 2018. En concreto, se trata de una <strong>blusa fluida de manga larga con transparencias<\/strong>\u00a0y estampado en plata. Letizia luci\u00f3 esta pieza hace ocho a\u00f1os para ir a ver el musical &#8216;Billy Elliot&#8217; junto a sus hijas, Leonor y Sof\u00eda, su madre, Paloma Rocasolano, y la reina Sof\u00eda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/reina-letizia_8f771fb7_260512183218_1200x1800.webp.webp\" alt=\"Reina Letizia \" class=\"lazyload\" width=\"1200\" height=\"1800\" data-aspectratio=\"1200\/1800\"\/>&#13;<\/p>\n<p>La reina ha rescatado de su armario una blusa que llevaba ocho a\u00f1os sin lucir.<\/p>\n<p>&#13;&#13;Gtres<\/p>\n<p>La reina ha combinado la blusa con una de las prendas m\u00e1s socorridas e ic\u00f3nicas de su armario: la falda midi de piel en color negro de Hugo Boss. La estren\u00f3 en 2022 y, desde entonces, se ha convertido en uno de sus &#8216;must&#8217; de oto\u00f1o\/invierno, por lo que ha vuelto a lucirla ante la bajada de las temperaturas en la capital este martes.<\/p>\n<p>La falda de Letizia, de corte evas\u00e9 y tiro alto, con abertura delantera y cintur\u00f3n de piel con hebilla tonal, aporta <strong>el toque m\u00e1s rockero y sofisticado a su estilismo<\/strong>. La combinaci\u00f3n resulta en un look cl\u00e1sico y pulido, perfecto para este tipo de actos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/reina-letizia_0608fa6d_260512190046_1200x1800.webp.webp\" alt=\"Reina Letizia\" class=\"lazyload\" width=\"1200\" height=\"1800\" data-aspectratio=\"1200\/1800\"\/>&#13;&#13;Gtres<br \/>\nUna agenda reducida<\/p>\n<p>La semana de trabajo se ha reducido sustancialmente para la Reina. En v\u00edsperas del D\u00eda de San Isidro, solo volveremos a ver a la madre de Leonor y Sof\u00eda un d\u00eda m\u00e1s. Ser\u00e1 este mi\u00e9rcoles 13 de mayo en el Teatro Real con motivo de la\u00a0inauguraci\u00f3n de la XVII Conferencia Iberoamericana de Ministras y Ministros de Salud. Previamente, la consorte participar\u00e1 en un encuentro iberoamericano sobre Enfermedades Raras en Iberoam\u00e9rica con el que pondr\u00e1 fin a sus compromisos institucionales.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\"   src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/reina-letizia_e672c8df_260512182246_1200x1800.webp.webp\" alt=\"Reina Letizia\" class=\"lazyload\" width=\"1200\" height=\"1800\" data-aspectratio=\"1200\/1800\"\/>&#13;&#13;Gtres<br \/>\nFeria del libro de Madrid 2026\u00a0<\/p>\n<p>Muy pronto volveremos a ver a la reina Letizia rodeada de libros. Ya es tradici\u00f3n que sea ella la encargada de <strong>inaugurar la Feria del libro de Madrid<\/strong>. Una edici\u00f3n que volver\u00e1 al Parque del Retiro\u00a0del 29 de mayo al 14 de junio y cuyo objetivo es promover la lectura en grandes y peque\u00f1os.\u00a0<\/p>\n<p>Consciente de su poder medi\u00e1tico, su intenci\u00f3n con su mera presencia no es otra que la de promover algo tan importante como leer. Da igual si te gustan las novelas, las biograf\u00edas, las historias de fantas\u00eda, rom\u00e1nticas&#8230; todas te ayudar\u00e1n a \u00abaprender\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"La reina Letizia\u00a0(53 a\u00f1os) es una gran lectora, por eso su presencia en el Premio\u00a0SM &#8216;El Barco de&hellip;\n","protected":false},"author":2,"featured_media":547518,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[255,146,147,25,24,256,23],"class_list":{"0":"post-547517","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-famosos","8":"tag-celebrities","9":"tag-entertainment","10":"tag-entretenimiento","11":"tag-es","12":"tag-espana","13":"tag-famosos","14":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116563096477254193","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547517"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547518"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}