{"id":547591,"date":"2026-05-12T19:41:21","date_gmt":"2026-05-12T19:41:21","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547591\/"},"modified":"2026-05-12T19:41:21","modified_gmt":"2026-05-12T19:41:21","slug":"peter-jackson-frodo-y-una-espectacular-joan-collinsen-la-primera-alfombra-roja-de-cannes","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547591\/","title":{"rendered":"Peter Jackson, Frodo y una espectacular Joan Collins,en la primera alfombra roja de Cannes"},"content":{"rendered":"<p class=\"mb-4 text-lg md:leading-8 break-words\">Cannes (Francia), 12 may (EFE).- Peter Jackson, acompa\u00f1ado por Elijah Wood, inolvidable Frodo en la saga &#8216;El se\u00f1or de los anillos&#8217; (&#8216;The Lord of the Rings&#8217;), protagonizaron este martes la primera alfombra roja del 79 Festival de Cannes, donde hoy el realizador neozeland\u00e9s recibe, de manos del actor, una Palma de Oro de honor.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Era lo esperado, pero la sorpresa lleg\u00f3 con la aparici\u00f3n estelar de Joan Collins, espectacular a sus 92 a\u00f1os, que se pase\u00f3 por la alfombra como una gran estrella, tanto que, a solo dos metros de distancia, pasaba desapercibida Jane Fonda.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Collins, con un llamativo vestido blanco con enormes volantes en la parte superior y un conjunto espectacular de collar y pendientes de brillantes, fue recibida con gritos de sorpresa por los fans.<\/p>\n<p><img alt=\"\" loading=\"lazy\" width=\"960\" height=\"689\" decoding=\"async\" data-nimg=\"1\" class=\"rounded-lg\" style=\"color:transparent\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/ea89a9e684e8fa8fcad3a77320609933.jpeg\"\/><\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Casi tantos como los que acogieron a Wood y Jackson cuando desfilaron por la alfombra con la m\u00fasica de fondo de la saga de pel\u00edculas que adaptaron para el cine las historias de J.R.R. Tolkien.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">A continuaci\u00f3n pasaron los miembros del jurado, presidido por el realizador surcoreano Park Chan-Wook y en el que tambi\u00e9n est\u00e1n las actrices Demi Moore -con un vestido blanco puro Hollywood- y Ruth Negga, la directora Chloe Zao, el actor Stellan Skarsgard o el director chileno Diego C\u00e9spedes, que puso el toque original en la moda masculina con un desestructurado traje blanco.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Antes de ellos, hab\u00edan llegado James Franco, Alfonso Cuar\u00f3n o Diego Luna, acompa\u00f1ado por la actriz Adriana Paz, que participa en su pel\u00edcula &#8216;Ceniza en la boca&#8217;, que presenta esta semana, fuera de competici\u00f3n, en el festival.<\/p>\n<p><img alt=\"\" loading=\"lazy\" width=\"960\" height=\"640\" decoding=\"async\" data-nimg=\"1\" class=\"rounded-lg\" style=\"color:transparent\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/19a11953a9150acd7cc079977b2ab9e8.jpeg\"\/><\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Directores como Costa Gavras, Bong Joon Ho, Hirokazu Kore-eda o Claude Lelouch y actrices como Gong Li, Zhao Tao o Philippine Leroy-Beaulieu, la jefa de Lilly Collins en la popular serie &#8216;Emily in Paris&#8217;.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">(c) Agencia EFE<\/p>\n","protected":false},"excerpt":{"rendered":"Cannes (Francia), 12 may (EFE).- Peter Jackson, acompa\u00f1ado por Elijah Wood, inolvidable Frodo en la saga &#8216;El se\u00f1or&hellip;\n","protected":false},"author":2,"featured_media":547592,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[11984,4490,995,27500,56497,146,147,25,24,54055,70344,106454,106472,64342,23],"class_list":{"0":"post-547591","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entretenimiento","8":"tag-cannes","9":"tag-demi-moore","10":"tag-efe","11":"tag-el-senor-de-los-anillos","12":"tag-elijah-wood","13":"tag-entertainment","14":"tag-entretenimiento","15":"tag-es","16":"tag-espana","17":"tag-festival-de-cannes","18":"tag-frodo","19":"tag-joan-collins","20":"tag-lilly-collins","21":"tag-peter-jackson","22":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116563312542462767","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547591"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547592"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}