{"id":547784,"date":"2026-05-12T21:51:18","date_gmt":"2026-05-12T21:51:18","guid":{"rendered":"https:\/\/www.europesays.com\/es\/547784\/"},"modified":"2026-05-12T21:51:18","modified_gmt":"2026-05-12T21:51:18","slug":"el-betis-vuelve-a-la-champions-mas-de-20-anos-despues","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/547784\/","title":{"rendered":"\u00a1El Betis vuelve a la Champions m\u00e1s de 20 a\u00f1os despu\u00e9s!"},"content":{"rendered":"<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph ue-c-article--first-letter-highlighted\">Le ha costado sangre, sudor, l\u00e1grimas, varios presidentes, dieciocho entrenadores y cientos de futbolistas, pero el <strong>Betis<\/strong>, m\u00e1s de dos d\u00e9cadas despu\u00e9s, volver\u00e1 a jugar la <strong>Champions League<\/strong>. Los verdiblancos fueron pioneros entre los equipos andaluces a la hora de disputar la m\u00e1xima competici\u00f3n de la <strong>UEFA<\/strong>. Pero desde su primera presencia, en la temporada 2005-06, no la han vuelto a pisar.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">Eso cambiar\u00e1 el pr\u00f3ximo curso despu\u00e9s de que, con <strong>Manuel Pellegrini<\/strong> al frente y tras haber asegurado previamente su sexta clasificaci\u00f3n europea consecutiva, se hayan impuesto esta noche en el <strong>Estadio de La Cartuja<\/strong> al <strong>Elche<\/strong> por 2-1 aprovechando la derrota del <strong>Celta<\/strong> en <strong>Bala\u00eddos<\/strong> para asegurar matem\u00e1ticamente la quinta plaza liguera, que esta temporada reparte un pasaporte para la <strong>Liga de Campeones<\/strong>. Un \u00e9xito rotundo que borra de un plumazo las decepciones en la <strong>Copa<\/strong> y la <strong>Europa League<\/strong> que cambia la realidad deportiva y econ\u00f3mica del club.<\/p>\n<p>Un primer tiempo al ritmo de Bala\u00eddos<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">En una tarde de transistores como las de toda la vida, con dos equipos jug\u00e1ndose un puesto <strong>Champions<\/strong> y otros dos tratando de escapar de la amenaza del descenso en partidos cuyos horarios se solapaban, dio la sensaci\u00f3n de que sobre el c\u00e9sped de <strong>La Cartuja<\/strong> se jugaba al ritmo que marcaban en <strong>Bala\u00eddos<\/strong>. Si el <strong>Celta<\/strong> aceleraba, el <strong>Betis<\/strong> tambi\u00e9n; si lo hac\u00eda el <strong>Levante<\/strong>, quien respond\u00eda era el <strong>Elche<\/strong>. Un toma y daca que provoc\u00f3 vuelcos imprevisibles en los marcadores.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">Los de <strong>Pellegrini<\/strong> arrancaron el partido intentando evitar que el conjunto franjiverde se hiciera con el bal\u00f3n y obligando a los de <strong>Sarabia<\/strong> a tomar riesgos en la salida desde atr\u00e1s. <strong>Antony<\/strong> fue el primero en intentarlo, sin \u00e9xito. Pero antes de los 10 minutos, con el <strong>Celta<\/strong> por delante en su partido, lleg\u00f3 el primer tanto de la tarde en la capital hispalense. Su autor, el <strong>Cucho Hern\u00e1ndez<\/strong>, que est\u00e1 cerrando el curso a un nivel alt\u00edsimo..<\/p>\n<p>Gol del Cucho Hern\u00e1ndez (1-0) en el Betis 2-1 ElcheSportian<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">Una buena jugada construida desde la base sirvi\u00f3 para que <strong>Fornals<\/strong> recibiera en tres cuartos de campo y buscara a <strong>Juan Camilo<\/strong>. Y el colombiano, antes de llegar a la frontal, sorprendi\u00f3 con un golpeo raso, muy ajustado al poste, que se col\u00f3 entre las piernas de un defensa y sorprendi\u00f3 a <strong>Dituro<\/strong>. Antes incluso de merecerlo, los verdiblancos ya mandaban en el electr\u00f3nico, respondiendo al tanto vigu\u00e9s en <strong>Bala\u00eddos<\/strong>.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">El partido entr\u00f3 entonces en una fase de indefinici\u00f3n. El <strong>Elche<\/strong> no encontraba el camino y el <strong>Betis<\/strong> parec\u00eda conformarse. S\u00f3lo <strong>Antony<\/strong> volvi\u00f3 a intentarlo con un remate cruzado que se march\u00f3 fuera por poco. Pero el cloroformo que le puso el conjunto ilicitano al juego termin\u00f3 desactivando a los verdiblancos. En especial por su costado izquierdo, donde <strong>Junior<\/strong> volvi\u00f3 a demostrar que esta no es su temporada.<\/p>\n<p>Gol de H\u00e9ctor Fort (1-1) en el Betis 2-1 ElcheSportian<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">En una arrancada de <strong>Valera<\/strong>, dejando atr\u00e1s a tres rivales, <strong>H\u00e9ctor Fort<\/strong> recibi\u00f3 por la derecha y busc\u00f3 un golpeo cruzado. El bal\u00f3n rebot\u00f3 en <strong>Firpo<\/strong> y tom\u00f3 una par\u00e1bola tremenda que hizo imposible cualquier intento de <strong>Valles<\/strong>. La respuesta visitante lleg\u00f3 casi al tiempo que en la grada de <strong>La Cartuja<\/strong> se celebraban los goles del <strong>Levante<\/strong> en <strong>Bala\u00eddos<\/strong> y que serv\u00edan para cumplir la primera de las dos premisas que necesitaba el <strong>Betis<\/strong> para certificar matem\u00e1ticamente su clasificaci\u00f3n para la <strong>Champions<\/strong>.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">El 1-1 y la posibilidad de alcanzar su ambicioso objetivo, en lugar de reactivar a los de <strong>Pellegrini<\/strong>, provoc\u00f3 que entraran en un estado de nervios incomprensible. <strong>Junior<\/strong> volvi\u00f3 a mostrarse inoperante ante\u00a0<strong>Diangana<\/strong> en dos llegadas de peligro. Y en el alargue, la pol\u00e9mica: error tremendo de <strong>Diego Llorente<\/strong> en un despeje y bal\u00f3n suelto para <strong>Andr\u00e9 Silva<\/strong>; el central madrile\u00f1o reacciona, despeja y la pelota va al brazo del portugu\u00e9s, que aprovecha para asistir; y <strong>Diangana<\/strong> llega solo y marca. Pero el \u00e1rbitro lo anula por mano y el <strong>VAR<\/strong> valida su decisi\u00f3n.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/6a03909330c18.jpeg\" class=\"ue-c-article__image\" alt=\"\"\/><\/p>\n<p>Ficha del Betis 2-1 ElcheEFE | MARCA<\/p>\n<p>Golazo de Fornals&#8230; y a la Champions<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\"><strong>Eder Sarabia<\/strong>, t\u00e9cnico del conjunto franjiverde, emprendi\u00f3 el camino de los vestuarios en cuanto se se\u00f1al\u00f3 el descanso muy enfadado, protestando de manera vehemente la acci\u00f3n pol\u00e9mica y pidiendo explicaciones a <strong>Beller\u00edn<\/strong> y <strong>Llorente<\/strong>. Y nada m\u00e1s regresar al banquillo para la segunda parte se llev\u00f3 otro varapalo disciplinario que dej\u00f3 a su equipo con un futbolista menos y m\u00e1s de 40 minutos por delante por una imprudencia de <strong>P\u00e9trot<\/strong>.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\"><strong>Antony<\/strong> lleg\u00f3 antes a un bal\u00f3n junto a la banda, a la altura de los banquillos, y el lateral franc\u00e9s se pas\u00f3 de frenada, entrando con los tacos por delante y la pierna a la altura del gemelo del brasile\u00f1o. <strong>D\u00edaz de Mera<\/strong> no se lo pens\u00f3 y le mostr\u00f3 la roja directa, confirmada tambi\u00e9n desde la sala de videoarbitraje. Y ah\u00ed, pese al orden mostrado siempre por el <strong>Elche<\/strong>, cambi\u00f3 por completo el rumbo del partido. Demasiado minutos en inferioridad num\u00e9rica ante un rival como el <strong>Betis<\/strong>&#8230;<\/p>\n<p>Gol de Pablo Fornals (2-1) en el Betis 2-1 ElcheSportian<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">Los verdiblancos comenzaron a asediar el \u00e1rea de <strong>Dituro<\/strong>. <strong>Sarabia<\/strong> renunci\u00f3 a un delantero para dar entrada a <strong>V\u00edctor Chust<\/strong> y el central fue decisivo en su primera aparici\u00f3n interviniendo lo suficiente para que un testarazo del <strong>Cucho<\/strong> fuera al larguero en vez de a la red. <strong>Lo Celso<\/strong> tambi\u00e9n lo intent\u00f3 con un golpeo al palo corto. Y el <strong>Ingeniero<\/strong> quem\u00f3 r\u00e1pido las naves dando entrada a Isco para que el embotellamiento de los franjiverdes en su \u00e1rea fuera a\u00fan mayor.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">Parec\u00eda cuesti\u00f3n de tiempo que llegara el 2-1 y el destino lo ten\u00eda reservado para el que, posiblemente, haya sido el futbolista m\u00e1s importante del <strong>Betis<\/strong> esta temporada. Un c\u00f3rner lanzado por Isco lo despej\u00f3 la defensa, el bal\u00f3n lleg\u00f3 a <strong>Fornals<\/strong> a varios metros de la frontal, y el castellonense control\u00f3, se acerc\u00f3 y sac\u00f3 un latigazo que se col\u00f3 por la escuadra. Golazo y \u00e9xtasis en <strong>La Cartuja<\/strong>, que se ve\u00eda ya con pie y medio en la pr\u00f3xima <strong>Liga de Campeones<\/strong>.<\/p>\n<p data-mrf-recirculation=\"Links P\u00e1rrafos\" class=\"ue-c-article__paragraph paragraph\">Al <strong>Elche<\/strong> no le qued\u00f3 otra que adelantar l\u00edneas, presionar arriba y buscar alguna acci\u00f3n aislada que le permitiera ara\u00f1ar al menos un punto. Pero cada contra de los verdiblancos era clar\u00edsima. <strong>Dituro<\/strong> se tuvo que emplear a fondo para impedir que <strong>Abde<\/strong> hiciera el tercero. <strong>\u00c1lvaro<\/strong> reaccion\u00f3 con un zurdazo que se fue alto. El <strong>Cucho<\/strong> pudo sentenciar en una contra tremenda. Y Altimira tuvo la \u00faltima en el 98&#8217;&#8230; No marc\u00f3, pero el <strong>Betis<\/strong> pudo celebrar su regreso a la <strong>Champions<\/strong>\u00a0haciendo sonar la m\u00fasica y dejando a los de <strong>Sarabia<\/strong> en una situaci\u00f3n delicada, con el descenso asediando.<\/p>\n","protected":false},"excerpt":{"rendered":"Le ha costado sangre, sudor, l\u00e1grimas, varios presidentes, dieciocho entrenadores y cientos de futbolistas, pero el Betis, m\u00e1s&hellip;\n","protected":false},"author":2,"featured_media":547785,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[268],"tags":[168,25,24,280,282,281,23,167],"class_list":{"0":"post-547784","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-futbol","8":"tag-deportes","9":"tag-es","10":"tag-espana","11":"tag-football","12":"tag-futbol","13":"tag-soccer","14":"tag-spain","15":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116563823687426338","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=547784"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/547784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/547785"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=547784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=547784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=547784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}