{"id":548108,"date":"2026-05-13T02:11:34","date_gmt":"2026-05-13T02:11:34","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548108\/"},"modified":"2026-05-13T02:11:34","modified_gmt":"2026-05-13T02:11:34","slug":"miquel-salom-se-rinde-ante-los-pioneros-de-la-fotografia-con-una-muestra-en-palma","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548108\/","title":{"rendered":"Miquel Salom se rinde ante los pioneros de la fotograf\u00eda con una muestra en Palma"},"content":{"rendered":"<p>El Arxiu Municipal de Palma, con sede en Can Bordils, acoge hasta el 27 de agosto la <a href=\"https:\/\/www.ultimahora.es\/etiqueta\/exposici%C3%B3n.html?utm_source=Inline-tag&amp;utm_medium=internal\" rel=\"nofollow noopener\" target=\"_blank\">exposici\u00f3n<\/a> <strong><a href=\"https:\/\/www.ultimahora.es\/etiqueta\/Miquel+Salom.html?utm_source=Inline-tag&amp;utm_medium=internal\" rel=\"nofollow noopener\" target=\"_blank\">Miquel Salom<\/a> i els pioners de la fotografia<\/strong>, que recoge algunas de las obras que el fot\u00f3grafo mallorqu\u00edn ha tomado a lo largo de su trayectoria utilizando una t\u00e9cnica casi bicentenaria, la del <strong>colodi\u00f3n h\u00famedo<\/strong>, en la que se hacen servir placas de vidrio o metal para exponerlas a la luz a trav\u00e9s de emulsiones y lograr as\u00ed captar el mundo. Salom rinde homenaje de esta manera a los pioneros de la <a href=\"https:\/\/www.ultimahora.es\/etiqueta\/fotograf%C3%ADa.html?utm_source=Inline-tag&amp;utm_medium=internal\" rel=\"nofollow noopener\" target=\"_blank\">fotograf\u00eda<\/a>, utilizando su arte para seguir retratando el mundo poni\u00e9ndole lo que m\u00e1s necesita a veces: pausa.<\/p>\n<p>El regidor de Cultura del Ajuntament de Palma, <strong>Javier Bonet<\/strong>, junto a la directora general de Patrimoni de Cort, <strong>Pilar Ribal<\/strong>, quien ha asumido buena parte de la organizaci\u00f3n del proyecto, y el propio artista, <strong>Miquel Salom<\/strong>, adem\u00e1s de <strong>Montserrat Torras<\/strong>, coordinadora y comisaria del Mallorca PhotoFest, iniciativa que tiene lugar estos meses en la Isla y dentro de la cual se enmarca esta muestra.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/4622103.jpg\" border=\"0\" alt=\"\" width=\"726\" height=\"877\" loading=\"lazy\"\/>&#13;<br \/>\nUna de las im\u00e1genes que se pueden ver en la exposici\u00f3n.&#13;<\/p>\n<p>As\u00ed pues, la exposici\u00f3n se nutre de las fotograf\u00edas que el propio Salom ha ido tomando a lo largo de los a\u00f1os utilizando la mencionada <strong>t\u00e9cnica<\/strong>, una que ha alabado, pero de la que tambi\u00e9n ha comentado su enorme <strong>\u00abdificultad\u00bb<\/strong>, lo que provoca que muchos que se adentran en ella, desistan. \u00c9l, sin embargo, ha mantenido durante los a\u00f1os su buen hacer con el colodi\u00f3n h\u00famedo como una manera de mantener vivo el legado de aquellos que fueron los primeros para que muchos pudieran luego continuar sus sendas. En especial el escultor brit\u00e1nico <strong>Frederick Scott Archer<\/strong>, quien cambi\u00f3 radicalmente la historia de la fotograf\u00eda.<\/p>\n<p>Regalo<\/p>\n<p>A Salom le agradeci\u00f3 Bonet el \u00abregalo\u00bb que hace a la ciudadan\u00eda con esta muestra que no solo se conforma de fotograf\u00edas, sino que tambi\u00e9n incluye algunas<strong> c\u00e1maras antiguas <\/strong>a modo de exposici\u00f3n y una <strong>pieza audiovisual <\/strong>que permite ver el proceso laborioso que hay detr\u00e1s de cada una de las instant\u00e1neas tomadas. A su vez, <strong>documentaci\u00f3n hist\u00f3rica y fotogr\u00e1fica <\/strong>completan la propuesta que se puede ver estos d\u00edas en el Arxiu.<\/p>\n<p>De esta manera, la muestra no solo recoge el trabajo de Salom, sino que hace extensible su <strong>reconocimiento<\/strong> a estos pioneros, entre los que destacan nombres como <strong>Louis Daguerre<\/strong>, en cuyo nombre se denomin\u00f3 al daguerrotipo, <strong>Bayard<\/strong>, <strong>Fox Talbot<\/strong> o <strong>Nic\u00e9phore Niepce<\/strong>.<\/p>\n<p>Por su parte, Salom, que avanz\u00f3 que podr\u00eda estar <strong>\u00abhablando durante semanas\u00bb<\/strong> sobre lo que se encuentra entre las paredes de la sala que alberga la exposici\u00f3n, confes\u00f3 tambi\u00e9n que \u00abresumir lo que signific\u00f3 para la fotograf\u00eda esta t\u00e9cnica es imposible y, de hecho, olvidado\u00bb. Es por ello que coment\u00f3 que b\u00e1sicamente decidi\u00f3 coger el toro por los cuernos y rendir un <strong>homenaje<\/strong> a unos pioneros porque \u00absi no lo hac\u00eda yo, no lo har\u00eda nadie m\u00e1s\u00bb.<\/p>\n<p>Por otro lado, Salom habl\u00f3 de una sensaci\u00f3n doble con este proyecto, ya que por un lado se trata del <strong>\u00abfinal de una etapa y del comienzo de otra\u00bb<\/strong>, y del componente de \u00abreto\u00bb que tienen estas obras, no solo para el espectador, ya que no son las t\u00edpicas im\u00e1genes a las que uno est\u00e1 acostumbrado, sino tambi\u00e9n para \u00e9l como artista por el incre\u00edblemente laborioso proceso de ejecuci\u00f3n que se compone de <strong>\u00ab23 pasos <\/strong>y que es supercomplicado de hacer\u00bb, explic\u00f3 el artista.<\/p>\n<p>Tambi\u00e9n ech\u00f3 la vista atr\u00e1s moment\u00e1neamanete Salom para recordar que fue <strong>a los \u00ab14 a\u00f1os\u00bb<\/strong> cuando su padre le puso una c\u00e1mara en las manos para que tomara una foto de toda la familia y, al escuchar el click de la c\u00e1mara, sinti\u00f3 que \u00abalgo en el <strong>coraz\u00f3n<\/strong> que me hablaba y me dec\u00eda que esto era lo que deb\u00eda hacer. Como si fuera algo superior quien me lo dijera\u00bb, y concluy\u00f3 diciendo que \u00abcomo soy un hombre a quien le gusta hacer lo que le dicen, pues eso he hecho, <strong>fotograf\u00eda desde entonces<\/strong>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"El Arxiu Municipal de Palma, con sede en Can Bordils, acoge hasta el 27 de agosto la exposici\u00f3n&hellip;\n","protected":false},"author":2,"featured_media":548109,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[229,233,231,230,209,232,234,146,147,25,24,2003,2086,244,4586,106572,23],"class_list":{"0":"post-548108","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-diseno","8":"tag-arte","9":"tag-arte-y-diseno","10":"tag-arts","11":"tag-arts-and-design","12":"tag-cultura","13":"tag-design","14":"tag-diseno","15":"tag-entertainment","16":"tag-entretenimiento","17":"tag-es","18":"tag-espana","19":"tag-exposicion","20":"tag-exposiciones-en-mallorca","21":"tag-fotografia","22":"tag-fotografia-en-mallorca","23":"tag-miquel-salom","24":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116564845716247518","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548108"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548109"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}