{"id":548130,"date":"2026-05-13T02:31:17","date_gmt":"2026-05-13T02:31:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548130\/"},"modified":"2026-05-13T02:31:17","modified_gmt":"2026-05-13T02:31:17","slug":"dimitris-giannakopulos-en-valencia-antes-de-la-llegada-del-panathinaikos-a-manises-para-medirse-al-valencia-basket-en-la-euroliga","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548130\/","title":{"rendered":"Dimitris Giannakopulos, en Val\u00e8ncia antes de la llegada del Panathinaikos a Manises para medirse al Valencia Basket en la Euroliga"},"content":{"rendered":"<p class=\"ft-text\">La cuenta atr\u00e1s ha empezado. <strong>El Valencia Basket <\/strong><a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.euroleaguebasketball.net\/es\/euroleague\/game-center\/2025-26\/valencia-basket-panathinaikos-aktor-athens\/E2025\/403\/\" rel=\"nofollow noopener\" target=\"_blank\"><strong>buscar\u00e1 este mi\u00e9rcoles el billete para la Final Four<\/strong><\/a><strong> en un partido que le medir\u00e1 a un Panathinaikos<\/strong> que ha aterrizado en el aeropuerto de Manises este martes unos minutos despu\u00e9s de las 19:00. Y lo hizo sin su presidente Dimitris Giannakopoulos en la expedici\u00f3n, <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.superdeporte.es\/valencia-basket\/2026\/05\/01\/euroliga-sanciona-presidente-panathinaikos-valenciabasket-129755024.html\" rel=\"nofollow noopener\" target=\"_blank\">debiendo cumplir a\u00fan el tercer partido de sanci\u00f3n que le impuso la Euroliga<\/a> por su comportamiento en la pista durante el segundo partido del playoff en el Roig Arena.<\/p>\n<p class=\"ft-text\">Una ausencia que, sin embargo, no implica que no est\u00e9 en Val\u00e8ncia, ya que as\u00ed lo ha asegurado el propietario del club griego en sus Instagram Stories, con un v\u00eddeo en el que muestra unos edificios de la ciudad desde una terraza, antes de cenar. <\/p>\n<p class=\"ft-text\">El pol\u00e9mico <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.superdeporte.es\/valencia-basket\/2026\/05\/09\/asombrosa-peticion-dimitris-giannakopoulos-valencia-130032208.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>presidente del Panathinaikos hab\u00eda solicitado d\u00edas atr\u00e1s que fuera el propio Valencia Basket quien tomara la iniciativa de solicitar que dejaran si efecto su sanci\u00f3n<\/strong><\/a> para este partido, algo que obviamente no ocurri\u00f3. De hecho, fue el propio club taronja, tras las cr\u00edticas hacia \u00e9l por parte de Pedro Mart\u00ednez por acercarse a presionar a la mesa arbitral, quien hizo un comunicado solicitando una sanci\u00f3n para \u00e9l.<\/p>\n<p class=\"ft-text\"><strong>En ning\u00fan caso podr\u00eda entrar al Roig Arena para este quinto y definitivo partido<\/strong>, pero falta ver y qu\u00e9 planes tiene para la noche del mi\u00e9rcoles si es cierta su presencia en la ciudad, ya que no podr\u00eda acceder ni con la expedici\u00f3n ni con los aficionados griegos al pabell\u00f3n.<\/p>\n<p class=\"ft-text\"><strong>Quien no estar\u00e1 seguro en la pista es Kostas Sloukas<\/strong> por una lesi\u00f3n en la rodilla izquierda que ya le impidi\u00f3 estar en los anteriores partidos de cuartos de final.<\/p>\n<p class=\"ft-text\">El Panathinaikos no pudo aprovechar sus dos partidos como local para certificar el pase a la Final Four que se disputar\u00e1 en su pista y tendr\u00e1 una \u00faltima oportunidad en una cancha en la que se llev\u00f3 los dos primeros puntos de la eliminatoria en dos partidos decididos en la \u00faltima jugada. <strong>El conjunto griego no tuvo competici\u00f3n el fin de semana y prepara este partido desde el pasado s\u00e1bado<\/strong> en busca convertirse en el primer equipo que se clasifica para la Final Four despu\u00e9s de tener que pasar una eliminatoria de play-in. Ser\u00e1 la sexta vez que se enfrente a un quinto partido de eliminatorias, habiendo ganado tres y perdido dos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/4871e837-7010-4ba3-8bd3-7649fe7ea8b3_alta-libre-aspect-ratio_default_0_x1024y455.jpg\" width=\"1200\" height=\"800\" alt=\"Los jugadores del Panathinaikos, a su llegada al aeropuerto de Manises.\" class=\"ft-helper-img-rd\" loading=\"lazy\" fetchpriority=\"auto\"\/><\/p>\n<p class=\"ft-helper-fontColor-quaternary ft-helper-fontSize-body-S ft-helper-spacer-t-xxs\">Los jugadores del Panathinaikos, a su llegada al aeropuerto de Manises.  \/ F. Calabuig<\/p>\n<p>Diez precedentes en Val\u00e8ncia<\/p>\n<p class=\"ft-text\"><strong>El partido de la noche del mi\u00e9rcoles ser\u00e1 la d\u00e9cima ocasi\u00f3n en la que el Panathinaikos visite Val\u00e8ncia para un partido de Euroliga<\/strong>, lo que le convierte en el equipo que m\u00e1s veces hemos recibido en casa para un partido de competici\u00f3n europea. Ser\u00e1 la cuarta ocasi\u00f3n del curso en la que se vean las caras en el Roig Arena, con triunfo taronja en Liga Regular por 102-84 y victoria griega en los dos primeros partidos de este Playoff.<\/p>\n<p class=\"ft-text\">Euroliga 2010-11. Fase de grupos. Valencia Basket 56- Panathinaikos 72<\/p>\n<p class=\"ft-text\">Euroliga 2017-18. Liga Regular. Valencia Basket 67- Panathinaikos 63<\/p>\n<p class=\"ft-text\">Euroliga 2019-20. Liga Regular. Valencia Basket 94- Panathinaikos 87<\/p>\n<p class=\"ft-text\">Euroliga 2020-21. Liga Regular. Valencia Basket 95- Panathinaikos 83<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/71ca5aed-9818-439e-af27-d013e2013342_alta-libre-aspect-ratio_default_0_x1024y455.jpg\" width=\"1200\" height=\"800\" alt=\"Los jugadores del Panathinaikos, subiendo al autob\u00fas del Valencia Basket en Manises.\" class=\"ft-helper-img-rd\" loading=\"lazy\" fetchpriority=\"auto\"\/><\/p>\n<p class=\"ft-helper-fontColor-quaternary ft-helper-fontSize-body-S ft-helper-spacer-t-xxs\">Los jugadores del Panathinaikos, subiendo al autob\u00fas del Valencia Basket en Manises.  \/ F. Calabuig<\/p>\n<p class=\"ft-text\">Euroliga 2022-23. Liga Regular. Valencia Basket 94- Panathinaikos 91<\/p>\n<p class=\"ft-text\">Euroliga 2023-24. Liga Regular. Valencia Basket 81- Panathinaikos 82<\/p>\n<p class=\"ft-text\">Euroliga 2025-26. Liga Regular. Valencia Basket 102- Panathinaikos 84<\/p>\n<p class=\"ft-text\"><a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.superdeporte.es\/valencia-basket\/2026\/04\/28\/valencia-basket-pierde-forma-cruel-panathinaikos-cronica-129636068.html\" rel=\"nofollow noopener\" target=\"_blank\">Euroliga 2025-26. Playoff partido 1. Valencia Basket 67- Panathinaikos 68<\/a><\/p>\n<p class=\"ft-text\"><a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.superdeporte.es\/valencia-basket\/2026\/04\/30\/derrota-cruel-prorroga-valencia-basket-129726847.html\" rel=\"nofollow noopener\" target=\"_blank\">Euroliga 2025-26. Playoff partido 2. Valencia Basket 105- Panathinaikos 107<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La cuenta atr\u00e1s ha empezado. El Valencia Basket buscar\u00e1 este mi\u00e9rcoles el billete para la Final Four en&hellip;\n","protected":false},"author":2,"featured_media":548131,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[13944,299,1918,298,168,105850,25,24,833,12000,105851,5631,6661,23,167,235,2916],"class_list":{"0":"post-548130","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-baloncesto","8":"tag-aterriza","9":"tag-baloncesto","10":"tag-basket","11":"tag-basketball","12":"tag-deportes","13":"tag-dimitris","14":"tag-es","15":"tag-espana","16":"tag-euroliga","17":"tag-final-four","18":"tag-giannakopoulos","19":"tag-panathinaikos","20":"tag-playoff","21":"tag-spain","22":"tag-sports","23":"tag-valencia","24":"tag-valencia-basket"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116564924511408210","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548130"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548131"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}