{"id":548280,"date":"2026-05-13T04:54:17","date_gmt":"2026-05-13T04:54:17","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548280\/"},"modified":"2026-05-13T04:54:17","modified_gmt":"2026-05-13T04:54:17","slug":"alas-de-sangre-serie-alas-de-sangre-de-rebecca-yarros-prepara-su-salto-a-la-pantalla-con-amazon-prime-video","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548280\/","title":{"rendered":"ALAS DE SANGRE SERIE | &#8216;Alas de sangre&#8217; de Rebecca Yarros prepara su salto a la pantalla con Amazon Prime Video"},"content":{"rendered":"<p class=\"ft-text ft-helper-closenews\"><strong>Amazon Prime Video presum\u00eda <\/strong>hace unos d\u00edas <strong>de las pr\u00f3ximas adaptaciones literarias<\/strong> que llegar\u00e1n a la plataforma como &#8216;La hip\u00f3tesis del amor&#8217; de Ali Hazelwood, la serie <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20260511\/off-campus-serie-hockey-romance-introduccion-130089825\" target=\"_blank\" rel=\"nofollow noopener\">&#8216;Off Campus&#8217; de Elle Kennedy que saldr\u00e1 este mi\u00e9rcoles<\/a>, la tercera temporada de &#8216;Maxton Hall&#8217; de Mona Kasten, &#8216;Perfectos Mentirosos&#8217; de Alex M\u00edrez y much\u00edsimas m\u00e1s. Pero el <strong>as que ten\u00eda guardado bajo la manga<\/strong> era el anuncio de la saga superventas de fantas\u00eda de <strong>Rebecca Yarros<\/strong>, &#8216;Emp\u00edreo&#8217;, publicada en Espa\u00f1a por la editorial Planeta, que saltar\u00e1 a la pantalla en formato serie pr\u00f3ximamente.<\/p>\n<p class=\"ft-text\">La noticia <strong>la ha anunciado durante la presentaci\u00f3n de Amazon<\/strong> a anunciantes en el Beacon Theatre de Nueva York el propio <strong>Michael B. Jordan<\/strong>, productor ejecutivo del proyecto y una de las figuras que m\u00e1s ha apostado por la adaptaci\u00f3n desde antes incluso de la publicaci\u00f3n del primer volumen, &#8216;Alas de sangre&#8217;. La serie estar\u00e1 producida por Amazon MGM Studios junto a Outlier Society, la productora del <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20260316\/michael-b-jordan-delincuente-the-wire-sinners-pecadores-oscar-128009802\" target=\"_blank\" rel=\"nofollow noopener\">reciente ganador del Oscar a mejor actor<\/a>, y nace con la ambici\u00f3n de convertirse en el pr\u00f3ximo &#8216;Juego de Tronos&#8217;.<\/p>\n<p>Un largo camino hacia la adaptaci\u00f3n<\/p>\n<p class=\"ft-text\">Hasta ahora, sin embargo,<strong> el sue\u00f1o de ver a Violet y Xaden en pantalla parec\u00eda haberse difuminado<\/strong>. Despu\u00e9s de que la autora anunciara en 2023 que Amazon MGM se hab\u00eda hecho con los derechos, el proyecto entr\u00f3 en un largo periodo de silencio y un par\u00f3n que se prolong\u00f3 hasta septiembre del a\u00f1o pasado. Entonces se produjo un relevo clave, sali\u00f3 Moira Walley-Beckett (creadora de &#8216;Anne With an E&#8217; y guionista de &#8216;Breaking Bad&#8217;) y se incorpor\u00f3 Meredith Averill, conocida por su trabajo en &#8216;Locke &amp; Key&#8217;, como nueva &#8216;showrunner&#8217;. Y cuando todo apuntaba a<strong> que la serie se iba a quedar en un limbo<\/strong> durante a\u00f1os antes de su estreno, todo des\u00e1nimo ha desaparecido cuando Prime Video ha descartado todos los rumores de paralizaci\u00f3n con un \u00abla <strong>serie &#8216;Alas de sangre&#8217; est\u00e1 en camino<\/strong>\u00bb y una foto de los productores ejecutivos Rebecca Yarros, Michael B. Jordan, Lisa Joy (quien dirigir\u00e1 el primer episodio) y Meredith Averill.<\/p>\n<p class=\"ft-text\">\u00abEl viaje de Violet en &#8216;Alas de sangre&#8217;\u00a0ha <strong>desatado un fen\u00f3meno global<\/strong>, cautivando a millones de lectores y creando una base de fans apasionada en torno a su mundo, sus personajes y sus implicaciones emocionales\u00bb, ha declarado Peter Friedlander, director de Televisi\u00f3n Global de Amazon MGM Studios en la presentaci\u00f3n. \u00abLa <strong>brillante serie de Rebecca Yarros es una de las adaptaciones m\u00e1s esperadas del mundo<\/strong>, y junto con Meredith y nuestros valiosos socios de Kilter, Outlier y Premeditated, la estamos llevando a la pantalla de una manera que honra lo que los fans adoran de la historia\u00bb. <\/p>\n<p class=\"ft-text\">Y no miente, porque &#8216;<strong>Alas de sangre<\/strong>&#8216;, publicada en 2023, seguida de &#8216;Alas de hierro&#8217; en 2024 y &#8216;Alas de \u00f3nix&#8217; en 2025 <strong>han sido todo un fen\u00f3meno editorial<\/strong>. \u00c9xito tras \u00e9xito. Sin ir m\u00e1s lejos, el \u00faltimo de la saga &#8216;Emp\u00edreo&#8217; <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20250205\/alas-onix-rebecca-yarros-supera-ejemplares-vendidos-114007154\" target=\"_blank\" rel=\"nofollow noopener\">vendi\u00f3 m\u00e1s de 120.000 ejemplares en apenas una semana en Espa\u00f1a<\/a>, un hito que no se alcanzaba desde el fen\u00f3meno de &#8216;Harry Potter&#8217; de J.K. Rowling. Y, a parte, fue un punto de inflexi\u00f3n para que muchas editoriales abrieran los ojos de lo que gustaba a los lectores: un nuevo g\u00e9nero llamado &#8216;<strong>romantasy<\/strong>&#8216; que mezclaba fantas\u00eda y romance. Nada nuevo en el mundo anglosaj\u00f3n, pero s\u00ed un poco desconocido como etiqueta en Espa\u00f1a. Y tambi\u00e9n fue todo una revoluci\u00f3n en cuanto a las <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20240702\/furor-ediciones-especiales-limitadas-formula-exito-libros-novelas-104014269\" target=\"_blank\" rel=\"nofollow noopener\">ediciones especiales con cantos tintados<\/a>, una f\u00f3rmula que a d\u00eda de hoy ya se repite como modus operandi entre las novedades del g\u00e9nero &#8216;young adult&#8217;. Las \u00faltimas dos novelas que cerrar\u00e1n la saga a\u00fan no est\u00e1n anunciadas.<\/p>\n<p>\u00bfDe qu\u00e9 va &#8216;Alas de sangre&#8217;?<\/p>\n<p class=\"ft-text\">En las novelas tan famosas de Rebecca Yarros se relata la\u00a0<strong>vida de Violet Sorrengail<\/strong>, una joven que cre\u00eda que se unir\u00eda al Cuadrante de los Escribas (al que pertenec\u00eda su difunto padre) para vivir una vida tranquila, pero que al final acaba luchando para formar parte de la \u00e9lite de Navarre en el Cuadrante de los Jinetes de Dragones obligada por su madre. En el entreno, Violet pasa a ser un blanco f\u00e1cil porque muchos creen que <strong>es d\u00e9bil y que no superar\u00e1 las pruebas<\/strong>. Adem\u00e1s, muchos la matar\u00edan para poder tener m\u00e1s probabilidades de conseguir un drag\u00f3n, pero tambi\u00e9n otros como Xaden Riorson la matar\u00edan por el simple hecho de ser la hija de la comandante general. Una rivalidad que evoluciona a algo m\u00e1s.<\/p>\n<p data-close=\"closedContent\" class=\"subscribeHideForDisplay\">Suscr\u00edbete para seguir leyendo<\/p>\n","protected":false},"excerpt":{"rendered":"Amazon Prime Video presum\u00eda hace unos d\u00edas de las pr\u00f3ximas adaptaciones literarias que llegar\u00e1n a la plataforma como&hellip;\n","protected":false},"author":2,"featured_media":548281,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[171],"tags":[106604,106598,6826,4550,146,147,25,24,106602,106599,26585,106600,106601,23,214,106603],"class_list":{"0":"post-548280","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-adaptacion-literaria","9":"tag-alas-de-sangre","10":"tag-amazon-prime-video","11":"tag-dragones","12":"tag-entertainment","13":"tag-entretenimiento","14":"tag-es","15":"tag-espana","16":"tag-novela-fantastica","17":"tag-rebecca-yarros","18":"tag-romantasy","19":"tag-serie-alas-de-sangre","20":"tag-series-de-prime","21":"tag-spain","22":"tag-tv","23":"tag-violet-y-xaden"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116565486156885790","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548280"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548281"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}