{"id":548290,"date":"2026-05-13T05:03:19","date_gmt":"2026-05-13T05:03:19","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548290\/"},"modified":"2026-05-13T05:03:19","modified_gmt":"2026-05-13T05:03:19","slug":"el-grupo-acs-incrementa-su-beneficio-neto-un-215","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548290\/","title":{"rendered":"El Grupo ACS incrementa su beneficio neto un 21,5%"},"content":{"rendered":"<p>El <a href=\"https:\/\/pressroom.grupoacs.com\/\" type=\"link\" id=\"https:\/\/pressroom.grupoacs.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Grupo ACS<\/a> obtuvo en el primer trimestre 2026 un <a href=\"https:\/\/intereconomia.com\/tag\/beneficios\/\" type=\"post_tag\" id=\"2909\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">beneficio <\/a>neto atribuible de 232 millones de euros, lo que supone un incremento del 21,5% respecto al mismo periodo del a\u00f1o anterior, un 30,0% al ajustarse por el efecto del tipo de cambio. El beneficio por acci\u00f3n (BPA) creci\u00f3 un 19,3%, hasta los 0,89 euros. Tras estos resultados, ACS mantiene su\u00a0previsi\u00f3n de superar los 1.000 millones de beneficio en 2026, un 20-25 % m\u00e1s que en 2025.<\/p>\n<p>El beneficio neto ordinario del Grupo, que excluyen los resultados extraordinarios en ambos ejercicios, aument\u00f3 un 25% hasta superar los 239 millones de euros, en l\u00ednea con el l\u00edmite superior del objetivo de crecimiento establecido para 2026 y apoyado en la buena evoluci\u00f3n de Turner.<\/p>\n<p>La contribuci\u00f3n de cada segmento de actividad al beneficio se muestra en la siguiente tabla:<\/p>\n<p><img data-perfmatters-preload=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"613\" height=\"205\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/1778648597_542_image-5.png\" alt=\"\" class=\"wp-image-1055811\" style=\"width:800px;height:auto\"  \/><\/p>\n<p>El beneficio bruto de explotaci\u00f3n (EBITDA) del Grupo alcanz\u00f3 los 772 millones de euros, un 10% superior que en 2025 (16% ajustado por tipo de cambio). Destaca el fuerte crecimiento de Turner, con una mejora de sus m\u00e1rgenes operativos.<\/p>\n<p>Por su parte, el beneficio ordinario de explotaci\u00f3n (EBIT) se situ\u00f3 en 549 millones de euros, un 16,8% m\u00e1s que el a\u00f1o anterior (23,7% ajustado por tipo de cambio).<\/p>\n<p>Diversificaci\u00f3n Internacional<\/p>\n<p>Las ventas del Grupo ACS en el periodo alcanzaron los 12.344 millones de euros, un 4,7% m\u00e1s, gracias al s\u00f3lido comportamiento de todas las actividades. <\/p>\n<p><img data-perfmatters-preload=\"\" decoding=\"async\" width=\"605\" height=\"316\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/1778648598_414_image-6.png\" alt=\"\" class=\"wp-image-1055812\" style=\"width:800px;height:auto\"   fetchpriority=\"high\"\/><\/p>\n<p> En el primer trimestre 2026, la cartera se situ\u00f3 en los 99.825 millones de euros, lo que supone un crecimiento del 9,9% respecto al a\u00f1o anterior (un +13,5% ajustado por tipo de cambio). Este avance responde al aumento del volumen de adjudicaciones registradas en el ejercicio, que super\u00f3 los 17.460 millones de euros, un 26,9% m\u00e1s ajustado por tipo de cambio, especialmente impulsado por los mercados de infraestructuras de nueva generaci\u00f3n, y con especial \u00e9nfasis en la construcci\u00f3n de centros de datos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"651\" height=\"359\" alt=\"\" class=\"wp-image-1055814 perfmatters-lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/image-7.png\"  data-\/><\/p>\n<p>Resultados por \u00e1reas de actividad<\/p>\n<p>1. Turner<\/p>\n<p>Turner mostr\u00f3 un fuerte crecimiento de ventas (+25% ajustado por tipo de cambio) impulsado por el buen comportamiento en el sector de centros de datos, y respaldado por el crecimiento en farmacia, semiconductores, aviaci\u00f3n y edificios p\u00fablicos. Nuevo aumento del margen EBITDA de 72 bps hasta 3,9%, impulsado por la estrategia de crecimiento de Turner centrada en proyectos de mayor valor a\u00f1adido en sectores de tecnolog\u00eda. El beneficio antes de impuestos aument\u00f3 un 40% respecto al mismo periodo del a\u00f1o pasado, alcanzando los 246 millones de euros, con una mejora continua del margen hasta el 3,8%. Adem\u00e1s, las adjudicaciones crecieron un 32,9%, disparando la cartera de proyectos hasta los 42.333 millones de euros.<\/p>\n<p>2. CIMIC<\/p>\n<p>Las ventas de CIMIC alcanzaron los 2.445 millones de euros, apoyados en el buen comportamiento de sectores estrat\u00e9gicos de crecimiento, en particular los centros de datos. El beneficio ordinario antes de impuestos de CIMIC aument\u00f3 un 4,8% respecto a marzo de 2025, alcanzando los 116 millones de euros.<\/p>\n<p>La cartera de proyectos super\u00f3 los 23.000 millones de euros, un 7,9% m\u00e1s que el a\u00f1o anterior, impulsada por las adjudicaciones de 2.980, gracias al crecimiento en todos los segmentos, especialmente en centros de datos, defensa y movilidad sostenible.<\/p>\n<p>3. Ingenier\u00eda y construcci\u00f3n<\/p>\n<p>Las ventas del \u00e1rea del Ingenier\u00eda y Construcci\u00f3n del Grupo ACS aumentaron un 2,9%, impulsadas por la actividad en los segmentos de alto crecimiento. El EBITDA creci\u00f3 un 16,1% alcanzando los 173 millones de euros, y el beneficio antes de impuestos aument\u00f3 un 18,2%, hasta los 81 millones de euros. Por su parte, la cartera se increment\u00f3 un 5,3% ajustada por tipo de cambio, gracias a un elevado volumen de adjudicaciones de 3.535 millones de euros. En este sentido, los sectores que m\u00e1s crecieron fueron movilidad sostenible y transporte, adem\u00e1s de infraestructuras y defensa, donde el Grupo se encuentra en una s\u00f3lida posici\u00f3n tanto en Estados Unidos como en Espa\u00f1a y Alemania.<\/p>\n<p>4. Infraestructuras<\/p>\n<p>El \u00e1rea de Infraestructuras, donde operan Abertis, Iridium y ACS Digital &amp; Energy, contribuy\u00f3 con 37 millones de euros al beneficio ordinario del Grupo. Abertis mostr\u00f3 un s\u00f3lido rendimiento operativo, con un crecimiento del tr\u00e1fico del 1,4% apoyado en el buen comportamiento en Espa\u00f1a, Estados Unidos y Chile. Las ventas y el EBITDA de Abertis en t\u00e9rminos comparables crecieron un 6% y un 9% respectivamente, respaldadas por la diversificaci\u00f3n geogr\u00e1fica de la cartera y el crecimiento de las tarifas vinculadas a la inflaci\u00f3n. Iridium obtuvo un beneficio antes de impuestos de 9 millones de euros, y ACS Digital &amp; Energy, el \u00e1rea que engloba el desarrollo de la plataforma de centros de datos, gan\u00f3 4 millones de euros.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"658\" height=\"373\" alt=\"\" class=\"wp-image-1055815 perfmatters-lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/image-8.png\"  data-\/><\/p>\n<p>Esta buena evoluci\u00f3n se debe al fuerte flujo de caja operativo neto de 2.349 millones de euros, lo que ha permitido mantener una atractiva remuneraci\u00f3n al accionista (441 millones de euros en efectivo) y realizar inversiones estrat\u00e9gicas por un valor de 1.283 millones de euros en los \u00faltimos doce meses.<\/p>\n<p>Entre ellas destacan:<\/p>\n<ul class=\"wp-block-list\">\n<li>Las inversiones en centros de datos, por m\u00e1s de 500 millones.<\/li>\n<li>La ampliaci\u00f3n de capital en Abertis por 200 millones de euros para apoyar su plan de inversiones.<\/li>\n<li>Las inversiones en infraestructuras greenfield de m\u00e1s 370 millones de euros.<\/li>\n<li>Otras inversiones financieras netas y adquisiciones.<\/li>\n<\/ul>\n<p>Por su parte, las desinversiones en el mismo periodo alcanzaron los 956 millones de euros, destacando principalmente la operaci\u00f3n de la plataforma de Centros de Datos con GIP-BlackRock, y la venta del 50% del negocio de transporte de UGL en Australia.<\/p>\n<p><strong>ACS mantiene previsi\u00f3n de superar los 1.000 millones de beneficio en 2026<\/strong><\/p>\n<p>El grupo ACS ha reiterado este martes su previsi\u00f3n de lograr un beneficio neto operativo para 2026 de entre 1.030 y 1.070 millones de euros, lo que arrojar\u00eda un incremento de un 20-25 %, seg\u00fan ha indicado a la Comisi\u00f3n Nacional del Mercado de Valores (CNMV).<\/p>\n<p>La compa\u00f1\u00eda, que no ha actualizado sus previsiones por la incertidumbre geopol\u00edtica actual, especialmente por la guerra de Ir\u00e1n y los efectos de su evoluci\u00f3n, trabaja ya en un nuevo plan estrat\u00e9gico para noviembre.<\/p>\n<p>Los centros de datos son un foco estrat\u00e9gico para el grupo, que cuenta con una cartera de 19.400 millones en este segmento y nuevos pedidos por valor de 6.900 millones.<\/p>\n<p>En una conferencia con analistas para explicar las cuentas del trimestre, el consejero delegado de ACS, Juan Santamar\u00eda, ha subrayado que el grupo tiene una generaci\u00f3n de caja muy fuerte gracias al crecimiento que ha experimentado en los \u00faltimos cuatro a\u00f1os y que espera que siga creciendo. La compa\u00f1\u00eda baraja unos 900 millones de flujo de caja operativo neto por a\u00f1o despu\u00e9s del pago de dividendos.<\/p>\n<p><strong>Tambi\u00e9n espera crecimiento en su filial norteamericana Turner<\/strong><\/p>\n<p>Tambi\u00e9n espera crecimiento en su filial norteamericana Turner, que va a continuar haci\u00e9ndolo a un ritmo \u00abmuy, muy r\u00e1pido\u00bb y se espera que sus ingresos alcancen los 18-19.000 millones.<\/p>\n<p>Respecto a su alianza con GIP para desarrollar y operar una plataforma global de centros de datos, Santamar\u00eda sostiene que est\u00e1 evolucionando muy positivamente gracias a las conexiones aseguradas a la red de energ\u00eda y los permisos obtenidos.<\/p>\n<p>Tambi\u00e9n observa un crecimiento en la carga de pedidos en el sector comercial y en el segmento de semiconductores, que es una actividad que contin\u00faa despegando y aumenta significativamente.<\/p>\n<p>Respecto a su participada Abertis, insiste en que hay algunas oportunidades que est\u00e1n analizando y que si tienen sentido acometer\u00e1n una inyecci\u00f3n de capital.<\/p>\n<p>Sobre su exposici\u00f3n a EEUU, Santamar\u00eda ha apuntado que cuanto m\u00e1s generan ah\u00ed m\u00e1s invierten en este mercado, del que ha destacado el inter\u00e9s de los inversores estadounidenses en la compa\u00f1\u00eda, que no contempla en estos momentos salir a bolsa ah\u00ed, a medida que crece en todas las \u00e1reas, no solo en centros de datos.<\/p>\n<p>En relaci\u00f3n con su filial alemana Hochtief, no prev\u00e9 elevar su participaci\u00f3n actual en la compa\u00f1\u00eda aunque ser\u00e1n \u00aboportunistas\u00bb si se presenta esta posibilidad.<\/p>\n","protected":false},"excerpt":{"rendered":"El Grupo ACS obtuvo en el primer trimestre 2026 un beneficio neto atribuible de 232 millones de euros,&hellip;\n","protected":false},"author":2,"featured_media":548291,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[24720,5078,103103,82,95,94,25,24,23],"class_list":{"0":"post-548290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"tag-acs","9":"tag-beneficios","10":"tag-beneficios-empresariales","11":"tag-business","12":"tag-economia","13":"tag-economy","14":"tag-es","15":"tag-espana","16":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116565521859353195","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548290"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548291"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}