{"id":548599,"date":"2026-05-13T09:30:21","date_gmt":"2026-05-13T09:30:21","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548599\/"},"modified":"2026-05-13T09:30:21","modified_gmt":"2026-05-13T09:30:21","slug":"el-barca-centrado-en-remontar-puestos-en-la-liga-endesa","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548599\/","title":{"rendered":"El Bar\u00e7a, centrado en remontar puestos en la Liga Endesa"},"content":{"rendered":"<p class=\"ft-text ft-helper-align-justify\"><strong>La Liga Endesa alcanza el momento culminante de la temporada regular d\u00f3nde se est\u00e1n decidiendo los puestos de cara al play-off<\/strong> y el Bar\u00e7a de Xavi Pascual est\u00e1 inmerso en esa lucha por quedar lo m\u00e1s arriba posible en la tabla.<\/p>\n<p class=\"ft-text ft-helper-align-justify\">Los blaugrana, <strong>que actualmente ocupan la cuarta plaza, con 21 victorias y nueve derrotas, no puede permitirse ning\u00fan traspi\u00e9 en estos encuentros que cierran la temporada regular,<\/strong> y menos hacerlo este mi\u00e9rcoles, en su visita a un equipo que se est\u00e1 jugando sus \u00faltimas opciones de seguir en la Liga, el Covir\u00e1n Granada.<\/p>\n<p class=\"ft-text ft-helper-align-justify\"><strong>Pascual tiene claro que les espera un partido muy complicado ante el conjunto granadino que sigue todav\u00eda con vida<\/strong> despu\u00e9s de sus \u00faltimas tres victorias aunque su situaci\u00f3n es pr\u00e1cticamente l\u00edmite, ya que un triunfo blaugrana este mi\u00e9rcoles en la pista de Covir\u00e1n (19.30) les llevar\u00e1 directamente al descenso.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/fe0a305f-f2c0-455a-b0b8-5994523490c7_alta-libre-aspect-ratio_default_0_x640y284.jpg\" width=\"1200\" height=\"800\" alt=\"El Bar\u00e7a tiene que aprovechar un Juan N\u00fa\u00f1ez que ha mostrado una clara mejora en los \u00faltimos encuentros\" class=\"ft-helper-img-rd\" loading=\"lazy\" fetchpriority=\"auto\"\/><\/p>\n<p class=\"ft-helper-fontColor-quaternary ft-helper-fontSize-body-S ft-helper-spacer-t-xxs\">El Bar\u00e7a tiene que aprovechar un Juan N\u00fa\u00f1ez que ha mostrado una clara mejora en los \u00faltimos encuentros  \/ FCB<\/p>\n<p>Prohibido perder<\/p>\n<p class=\"ft-text ft-helper-align-justify\"><strong>El Bar\u00e7a tiene que centrarse en su objetivo que es sumar un nuevo triunfo y meter m\u00e1s presi\u00f3n a los equipos que tiene por delante<\/strong>. El Bar\u00e7a se encuentra empatado con Valencia Basket (21-9), aunque a los blaugrana les espera un duelo clave ante el conjunto de <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.sport.es\/es\/noticias\/baloncesto\/saltan-alarmas-valencia-basket-designacion-130132786\" rel=\"nofollow noopener\" target=\"_blank\">Pedro Mart\u00ednez, que se est\u00e1 jugando sus opciones de estar en la Final Four ante el Panathinaikos.<\/a><\/p>\n<p class=\"ft-text ft-helper-align-justify\">En caso de imponerse al cuadro \u2018taronja\u2019, <strong>los de Pascual les superar\u00eda en la clasificaci\u00f3n, aunque deber\u00edan esperar que el UCAM Murcia, segundo clasificado(22-8) &#8216;pinchase\u2019<\/strong> en alguno de los partidos que le restan para cerrar esta temporda regular.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/561ca168-6857-4b30-a79f-ba4c5c4b7f9e_alta-libre-aspect-ratio_default_0_x703y312.jpg\" width=\"1200\" height=\"800\" alt=\"Willy y Fall deben seguir jugando a un gran nivel para cubrir la ausencia de Vesely\" class=\"ft-helper-img-rd\" loading=\"lazy\" fetchpriority=\"auto\"\/><\/p>\n<p class=\"ft-helper-fontColor-quaternary ft-helper-fontSize-body-S ft-helper-spacer-t-xxs\">Willy y Fall deben seguir jugando a un gran nivel para cubrir la ausencia de Vesely  \/ FCB<\/p>\n<p class=\"ft-text ft-helper-align-justify\"><strong>En esta situaci\u00f3n de igualdad, una derrota en Granada dejar\u00eda a los blaugrana con muy pocas opciones de remontar puestos<\/strong>, por lo que la mirada est\u00e1 centrada en no dar opciones al cuadro nazar\u00ed y salir con un nuevo triunfo que tendr\u00edan que rematar este domingo en su visita a otro equipo complicado como La Laguna Tenerife.<\/p>\n<p>Sin bajar la guardia<\/p>\n<p class=\"ft-text ft-helper-align-justify\"><strong>Una tensi\u00f3n en la clasificaci\u00f3n que obliga al Bar\u00e7a a no tomarse ni un respiro y por ello el equipo volver\u00e1 a salir concentrado como lo ha hecho en los \u00faltimos encuentros<\/strong>, y buscando la aportaci\u00f3n colectiva, que le ha estado funcionando al t\u00e9cnico y que espera tenga continuidad en su visita de hoy a Granada.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/e9b0c634-d7e9-4694-b7b6-cab87f3a0614_alta-libre-aspect-ratio_default_0_x878y390.jpg\" width=\"1200\" height=\"800\" alt=\"Dani Gonz\u00e1lez podr\u00eda tener otra oportunidad ante el Covir\u00e1n Granada\" class=\"ft-helper-img-rd\" loading=\"lazy\" fetchpriority=\"auto\"\/><\/p>\n<p class=\"ft-helper-fontColor-quaternary ft-helper-fontSize-body-S ft-helper-spacer-t-xxs\">Dani Gonz\u00e1lez podr\u00eda tener otra oportunidad ante el Covir\u00e1n Granada  \/ FCB<\/p>\n<p class=\"ft-text ft-helper-align-justify\">El Bar\u00e7a sigue contando con muchos problemas de lesiones. A la baja de Will Clyburn, <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.sport.es\/es\/noticias\/barca\/baloncesto\/azulgrana-jan-vesely-anuncia-retira-130135698\" rel=\"nofollow noopener\" target=\"_blank\">siguen estando en el \u2018dique seco\u2019 Jan Vesely, que anunciaba precisamente este martes su intenci\u00f3n de retirarse a final de temporada<\/a>, adem\u00e1s de Tomas Satoransky, y <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.sport.es\/es\/noticias\/barca\/baloncesto\/kusturica-boumtje-boumtje-destrozan-movistar-129754160\" rel=\"nofollow noopener\" target=\"_blank\">el joven Nikola Kusturica, recuperando de un esguince que se hizo en la final del Campeonato de Espa\u00f1a Sub18.<\/a><\/p>\n<p class=\"ft-text ft-helper-align-justify\"><a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.sport.es\/es\/videos\/barca\/baloncesto\/20260213\/juani-marcos-hay-poner-excusas\/126780066.shtml\" rel=\"nofollow noopener\" target=\"_blank\">La \u00faltima p\u00e9rdida lleg\u00f3 en el duelo ante el San Pablo Burgos con la lesi\u00f3n del base Juani Marcos<\/a>, aunque apunta a que estar\u00e1 disponible, con un Nico Laprovittola, que ya est\u00e1 m\u00e1s cerca de volver con el equipo pero todav\u00eda no est\u00e1 a punto.<\/p>\n<p class=\"ft-text ft-helper-align-justify\">Pascual cuenta con la efectividad de Shengelia y Punter, y <a class=\"ft-link ft-link--decoration\" href=\"https:\/\/www.sport.es\/es\/noticias\/barca\/baloncesto\/juan-nunez-fichaje-final-temporada-129022231\" rel=\"nofollow noopener\" target=\"_blank\">con un Juan N\u00fa\u00f1ez que ya demostr\u00f3 estar recuperando su juego a gran velocidad.<\/a>Ante la ausencia de Vesely, tambi\u00e9n ha ganado protagonismo Youssoupha Fall y un Willy que tambi\u00e9n ha subido el nivel de juego. <strong>Para cubrir las bajas, Pascual ha vuelto a convocar a Dani Gonz\u00e1lez y Sayon Keita.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"La Liga Endesa alcanza el momento culminante de la temporada regular d\u00f3nde se est\u00e1n decidiendo los puestos de&hellip;\n","protected":false},"author":2,"featured_media":548600,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[299,298,13197,168,11276,92382,106640,25,24,6816,23,167],"class_list":{"0":"post-548599","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-baloncesto","8":"tag-baloncesto","9":"tag-basketball","10":"tag-centrado","11":"tag-deportes","12":"tag-el-barca","13":"tag-en-la-liga-endesa","14":"tag-en-remontar","15":"tag-es","16":"tag-espana","17":"tag-puestos","18":"tag-spain","19":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116566572290743435","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548599"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548600"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}